{"id":74005,"date":"2017-01-18T13:45:32","date_gmt":"2017-01-18T12:45:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/traffico-reperti-archeologici-perquisizioni-anche-cosenza\/"},"modified":"2023-01-16T19:26:04","modified_gmt":"2023-01-16T18:26:04","slug":"132368-traffico-reperti-archeologici-perquisizioni-anche-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/132368-traffico-reperti-archeologici-perquisizioni-anche-cosenza\/","title":{"rendered":"Traffico di reperti archeologici, perquisizioni anche a Cosenza. Coinvolti giudici, avvocati, medici e farmacisti (NOMI)"},"content":{"rendered":"<p><strong>I carabinieri del comando tutela patrimonio culturale hanno scoperto un&#8217;organizzazione dedita al traffico illecito di reperti archeologici.<\/strong><!--more--><\/p>\n<p>CROTONE &#8211; Dodici misure cautelari sono state disposte dal gip presso il tribunale di Crotone. Inoltre sono state avviate 35 perquisizioni nelle province di Crotone, Catanzaro, Reggio Calabria, <strong>Cosenza<\/strong>, Catania e Reggio Emilia, nei confronti di ricettatori e soggetti facenti parte di un&#8217;organizzazione criminale in grado di gestire tutte le fasi del traffico di reperti archeologici per un giro d&#8217;affari di alcuni milioni di euro.<\/p>\n<p>Bersaglio prediletto dai &#8216;tombaroli&#8217; era il sito archeologico di &#8216;<strong>Capo colonna<\/strong>&#8216; a Crotone. Tra le persone arrestate un noto docente e, tra gli indagati, diversi professionisti. Sequestrate preziose collezioni con numerosi reperti archeologici di notevole interesse storico-artistico ed elevato valore economico.\u00a0Tra le 35 persone indagate ci sarebbero <strong>giudici di pace, avvocati, medici e farmacisti<\/strong>. <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-132421 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/01\/attianese.jpg\" alt=\"attianese\" width=\"253\" height=\"173\" title=\"\">Una vera e propria organizzazione di trafficanti di reperti archeologici. <strong>L&#8217;accademico coinvolto<\/strong>, docente crotonese di materie letterarie con la passione dell&#8217;archeologia, \u00e8<strong> Pasquale Attianese, di 70 anni <\/strong><em>(in foto a destra)<\/em><strong>.<br \/>\n<\/strong><\/p>\n<p>Nei confronti degli indagati sono state eseguite perquisizioni nei loro domicili e negli studi professionali, con la contestuale notifica delle informazioni di garanzia emesse dalla Procura della Repubblica di Crotone, che ha coordinato l&#8217;operazione. L&#8217;operazione \u00e9 stata denominata <strong>&#8220;Tempio di Hera&#8221;,<\/strong> dal nome di Hera Lacinia, la dea moglie di Zeus cui \u00e9 intitolato il parco archeologico di Capo Colonna dove l&#8217;organizzazione di tombaroli avrebbe reperito i reperti oggetto del traffico illegale.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>I NOMI:<\/strong><\/span><\/p>\n<p>Tre arresti: due in carcere e uno ai domiciliari. Si tratta di\u00a0<strong>Pasquale\u00a0Giuseppe Attianese, <\/strong>(come sopra citato)\u00a0docente in pensione e autore di diverse pubblicazioni di numismatica; <strong>Vincenzo Godano,<\/strong> 30 anni, di Isola Capo Rizzuto, soprannominato &#8220;l&#8217;archeologo&#8221;, che addestrava i suoi uomini all&#8217;uso di sofisticati metal detector. Per una terza persona, <strong>R. M.,<\/strong> attualmente irreperibile, sono stati disposti i domiciliari.<\/p>\n<p><strong>OBBLIGO DI DIMORA<\/strong>, disposto dal gip nei confronti di\u00a0<strong>Francesco Carmine Verterame, <\/strong>61 anni, di Isola Capo Rizzuto;\u00a0<strong>Francesco Salvatore Filoramo, <\/strong>68 anni; <strong>Luca Filoramo, <\/strong>39 anni; <strong>Francesco Arena, <\/strong>38 anni, di Crotone.<\/p>\n<p><strong>OBBLIGO DI PRESENTAZIONE ALLA P.G.\u00a0<\/strong>per\u00a0<strong>Antonio Pasquale Fabiano, <\/strong>46 anni, di Crotone;\u00a0<strong>Giovanni Luigi Lettieri, <\/strong>63 anni, di Crotone; <strong>Raffaele Malena, <\/strong>70 anni, di Cir\u00f2 Marina; <strong>Ernesto Palopoli, <\/strong>82 anni, nativo di Rossano ma residente a Torretta di Crucoli (Il principale ricettatore &#8211; sempre a detta degli inquirenti &#8211; che ha accumulato negli anni quasi duemila reperti archeologici esposti nel suo museo privato);\u00a0<strong>Salvatore Rocca, <\/strong>34 anni, di Cariati.<\/p>\n<p>Sono accusati, a vario titolo, di <strong>associazione per delinquere dedita all&#8217;esecuzione di scavi clandestini, impossessamento di reperti archeologici dello Stato, danneggiamento di aree vincolate, ricettazione.<\/strong> Le indagini, condotte dai Carabinieri del comando tutela patrimonio culturale in collaborazione con i militari del comando provinciale di Crotone, sono state coordinate dalla Procura della Repubblica del capoluogo ionico, in particolare dal procuratore capo Giuseppe Capoccia e dal sostituto Luisiana Di Vittorio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I carabinieri del comando tutela patrimonio culturale hanno scoperto un&#8217;organizzazione dedita al traffico illecito di reperti archeologici.<\/p>\n","protected":false},"author":22,"featured_media":74006,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-74005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=74005"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74005\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/74006"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=74005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=74005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=74005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}