{"id":74212,"date":"2017-01-23T16:35:53","date_gmt":"2017-01-23T15:35:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/stupra-la-figlia-e-viene-posto-ai-domiciliari-cinquantenne-tradotto-in-carcere\/"},"modified":"2023-01-16T19:26:19","modified_gmt":"2023-01-16T18:26:19","slug":"133455-stupra-la-figlia-e-viene-posto-ai-domiciliari-cinquantenne-tradotto-in-carcere","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/133455-stupra-la-figlia-e-viene-posto-ai-domiciliari-cinquantenne-tradotto-in-carcere\/","title":{"rendered":"Stupra la figlia e viene posto ai domiciliari, cinquantenne tradotto in carcere"},"content":{"rendered":"<h4>L&#8217;uomo per circa due anni ha preteso dalla figlia tre rapporti sessuali completi a settimana.<\/h4>\n<p><!--more--><br \/>\nCROTONE\u00a0&#8211; &#8220;Sono solo un padre severo&#8221;. Cos\u00ec si \u00e8 giustificato l&#8217;uomo accusato di aver ripetutamente stuprato sua figlia. I carabinieri della Stazione di Cotronei hanno tradotto in carcere un 50enne di Petilia Policastro che attualmente si trovava ristretto agli arresti domiciliari dove stava scontando una condanna per violenza sessuale nei confronti della figlia. L&#8217;uomo, arrestato nel settembre 2014 in esecuzione di un&#8217;ordinanza di custodia cautelare in carcere emessa dal Gip del Tribunale di Crotone, nel frattempo \u00e8 stato condannato a 5 anni e 6 mesi di reclusione. Ora che quella condanna \u00e8 stata confermata i militari lo hanno trasferito presso la casa circondariale di Crotone per scontare la pena residua<strong>. A far emergere la vicenda e&#8217; stata la stessa figlia, oggi 26enne, raccontando ai carabinieri gli abusi che avvenivano gia&#8217; da due lunghi anni,<\/strong> durante i quali il padre pretendeva da lei anche due o tre rapporti sessuali completi ogni settimana, approfittando dei momenti nei quali i due restavano in casa da soli, costringendola, peraltro, a tacere, esercitando sulla stessa minacce e ricatti dettati dalla supremazia parentale fra padre e figlia. Al processo l&#8217;uomo si e&#8217; sempre difeso asserendo che le accuse della figlia sarebbero state una ritorsione nei suoi confronti perche&#8217; lui era un padre severo, ma i giudici lo hanno comunque condannato non credendo alla sua versione dei fatti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;uomo per circa due anni ha preteso dalla figlia tre rapporti sessuali completi a settimana.<\/p>\n","protected":false},"author":22,"featured_media":74213,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-74212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=74212"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/74213"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=74212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=74212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=74212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}