{"id":7424,"date":"2012-11-09T07:35:20","date_gmt":"2012-11-09T06:35:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=7424"},"modified":"2023-01-17T13:40:39","modified_gmt":"2023-01-17T12:40:39","slug":"3080-operazione-di-bonifica-nella-zona-di-vaglio-lise","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/3080-operazione-di-bonifica-nella-zona-di-vaglio-lise\/","title":{"rendered":"Operazione di bonifica nella zona di Vaglio Lise"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA<\/strong> &#8211; Nella giornata di ieri la Polizia Municipale ha proceduto alla demolizione di un manufatto abusivo nella zona di Vaglio Lise, dove regnava una situzione di degrado<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">abbastanza evidente.&nbsp;<span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">L\u2019intervento, effettuato con l\u2019ausilio dei mezzi di Ecologia Oggi e delle cooperative sociali, ha riguardato l\u2019area su cui insistevano delle pensiline e la vecchia biglietteria. Quest\u2019ultima, in particolare, con la costruzione di un corpo aggiunto era stata abusivamente trasformata in una dimora abitativa.<\/span><br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">Gli operatori della Polizia Municipale hanno proceduto allo sgombero ed alla demolizione del manufatto, attivando la conseguente operazione di bonifica dei luoghi che sar\u00e0 ultimata nelle prossime ore.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Nella giornata di ieri la Polizia Municipale ha proceduto alla demolizione di un manufatto abusivo nella zona di Vaglio Lise, dove regnava una situzione di degrado<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42,5],"tags":[],"class_list":["post-7424","post","type-post","status-publish","format-standard","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=7424"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7424\/revisions"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=7424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=7424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=7424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}