{"id":74254,"date":"2017-01-24T17:03:43","date_gmt":"2017-01-24T16:03:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/truffe-on-line-nel-cosentino-rintracciati-i-responsabili-dei-raggiri-sul-web\/"},"modified":"2023-01-16T19:26:22","modified_gmt":"2023-01-16T18:26:22","slug":"133628-truffe-on-line-nel-cosentino-rintracciati-i-responsabili-dei-raggiri-sul-web","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/133628-truffe-on-line-nel-cosentino-rintracciati-i-responsabili-dei-raggiri-sul-web\/","title":{"rendered":"Truffe on line nel cosentino, rintracciati i responsabili dei raggiri sul web"},"content":{"rendered":"<h4>Due uomini\u00a0sono stati identificati e denunciati in stato di libert\u00e0 dopo aver incassato il denaro dalle vittime.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROSE (CS) &#8211; I carabinieri della stazione di Rose hanno denunciato in stato di libert\u00e0 due persone accusate di truffa on line. Si tratta di due uomini residenti fuori regione:\u00a0un trentottenne di Atripalda in provincia di Avellino e un quarantaquattrenne nato in Germania che da tempo vive a Corsano in provincia di Lecce. A seguito di accertamenti \u00e8 emerso che il presunto truffatore campano aveva pubblicato su un sito internet l&#8217;annuncio di vendita di una moto agricola. Successivamente dopo essere stato contattato e aver <strong>ricevuto l&#8217;importo di 1.800 euro da un cinquantenne di Rose era scomparso nel nulla.<\/strong> Il pugliese invece avrebbe con le stesse modalit\u00e0 finto di vendere su internet uno smartphone ad un sessantatreenne anche egli di Rose. Dopo aver incassato 90 euro dalla vittima l&#8217;uomo aveva fatto perder le proprie tracce. Entrambi sono stati rintracciati e denunciati.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Due uomini\u00a0sono stati identificati e denunciati in stato di libert\u00e0 dopo aver incassato il denaro dalle vittime.<\/p>\n","protected":false},"author":22,"featured_media":74255,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-74254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=74254"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74254\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/74255"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=74254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=74254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=74254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}