{"id":7430,"date":"2012-11-09T09:07:20","date_gmt":"2012-11-09T08:07:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=7430"},"modified":"2023-01-17T13:40:40","modified_gmt":"2023-01-17T12:40:40","slug":"3084-la-riforma-del-mercato-del-lavoro-istruzioni-per-luso","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/3084-la-riforma-del-mercato-del-lavoro-istruzioni-per-luso\/","title":{"rendered":"\u201cLa Riforma del Mercato del Lavoro: istruzioni per l\u2019uso\u201d"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA<\/strong> &#8211; La &#8220;Confindustria Cosenza&#8221; ha organizzato per marted\u00ec 13 novembre, con inizio alle ore 9.30, nella propria sede, un seminario nel quale verranno illustrati sia&nbsp;gli<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">aspetti prettamente normativi che quelli pi\u00f9 operativi e gestionali introdotti&nbsp;dalla cosiddetta &#8220;Riforma Fornero\u201d.Sar\u00e0 presentato, alle aziende ed agli operatori del settore, il quadro complessivo delle novit\u00e0 attraverso una panoramica generale della norma ed un\u2019analisi particolare riferita ai temi della flessibilit\u00e0 in entrata (apprendistato, contratto a termine, lavoro intermittente e autonomo, contratti a progetto, etc.) ed in uscita (dimissioni, licenziamento, nuovi ammortizzatori sociali, etc.).<\/p>\n<p style=\"text-align: justify;\">Il seminario \u201cLa Riforma del Mercato del Lavoro: istruzioni per l\u2019uso\u201d intende porsi come utile strumento di confronto e sar\u00e0 aperto al dibattito ed ai quesiti dei partecipanti.<span style=\"font-size: 12px; line-height: 18.649999618530273px; background-color: #ffffff;\"><span style=\"font-size: 12px; line-height: 18.649999618530273px; background-color: #ffffff;\"><span style=\"font-size: 12px; line-height: 18.649999618530273px; background-color: #ffffff;\"><span style=\"font-size: 12px; line-height: 18.649999618530273px; background-color: #ffffff;\"><br \/><\/span><\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; La &#8220;Confindustria Cosenza&#8221; ha organizzato per marted\u00ec 13 novembre, con inizio alle ore 9.30, nella propria sede, un seminario nel quale verranno illustrati sia&nbsp;gli<\/p>\n","protected":false},"author":22,"featured_media":7431,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42,5],"tags":[],"class_list":["post-7430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=7430"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/7431"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=7430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=7430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=7430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}