{"id":74302,"date":"2017-01-25T18:39:37","date_gmt":"2017-01-25T17:39:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/fotonotizia-slalom-tra-le-buche-a-commenda\/"},"modified":"2023-01-16T19:26:24","modified_gmt":"2023-01-16T18:26:24","slug":"133823-fotonotizia-slalom-tra-le-buche-a-commenda","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/133823-fotonotizia-slalom-tra-le-buche-a-commenda\/","title":{"rendered":"FOTONOTIZIA &#8211; Slalom tra le buche a Commenda aspettando la ditta appaltatrice"},"content":{"rendered":"<h4>Lavori gi\u00e0 appaltati e ritardi causati, ufficialmente, dal maltempo.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; Gli automobilisti che attraversano alcune strade rendesi, hanno imparato a cimentarsi in creativi slalom tra le buche. In diversi punti della citt\u00e0 il manto stradale \u00e8 puntellato da voragini che, con la pioggia, rischiano di danneggiare le auto che vi finiscono dentro. Il perch\u00e9 il Comune non abbia dato mandato di intervenire non \u00e8 un mistero. L&#8217;obiettivo, come sempre, \u00e8 quello di risparmiare. E il municipio temporeggia. Il maltempo infatti pare non abbia permesso alla ditta che si \u00e8 aggiudicata l&#8217;appalto, per canalizzare le acque bianche di via Morelli, via Ciro Menotti e via Nino Bixio, di iniziare i lavori. P<strong>er evitare di riempire buche, per poi rifare nuovamente a distanza di poco tempo la bitumazione delle strade, si \u00e8 preferito attendere.<\/strong> Circa centomila euro saranno spesi per evitare i continui allagamenti nelle aree pi\u00f9 critiche del centro di Rende. Nel frattempo dall&#8217;Ufficio Tecnico del Comune informano che se la ditta non inizier\u00e0 i lavori, a breve si provveder\u00e0 a coprire temporaneamente le buche pi\u00f9 profonde con del bitume a freddo.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Lavori gi\u00e0 appaltati e ritardi causati, ufficialmente, dal maltempo.<\/p>\n","protected":false},"author":22,"featured_media":74303,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,44],"tags":[],"class_list":["post-74302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=74302"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74302\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/74303"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=74302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=74302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=74302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}