{"id":74390,"date":"2017-01-27T20:22:37","date_gmt":"2017-01-27T19:22:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cambiare-la-scuola-e-possibile-incontro-a-cosenza-domani\/"},"modified":"2023-01-16T19:26:30","modified_gmt":"2023-01-16T18:26:30","slug":"134279-cambiare-la-scuola-e-possibile-incontro-a-cosenza-domani","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/134279-cambiare-la-scuola-e-possibile-incontro-a-cosenza-domani\/","title":{"rendered":"Cambiare la scuola \u00e8 possibile, incontro pubblico domani a Cosenza"},"content":{"rendered":"<h4 dir=\"auto\">Assemblea aperta tra docenti, studenti, cittadini e parlamentari per conoscere il documento che si propone di rivoluzionare l&#8217;istruzione.<\/h4>\n<p><!--more--><\/p>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">COSENZA &#8211; Domani, Sabato 28 Gennaio, alle 15.30, presso la Sala Teatro della Scuola \u201cFratelli Bandiera\u201d dello Spirito Santo di Cosenza, si terr\u00e0 il Convegno sul tema: \u201cCambiare la scuola si pu\u00f2! &#8211; Una scuola pubblica per una cittadinanza attiva e una societ\u00e0 conviviale\u201d. L&#8217;obiettivo dell&#8217;evento organizzato dal meet up \u201cCosenza e Oltre\u201d, \u00e8 quello di sottoporre all\u2019attenzione di presidi, insegnanti, genitori e studenti un Documento programmatico contenente un\u2019idea alternativa e pedagogicamente rivoluzionaria della formazione scolastica. &#8220;Crediamo in una societ\u00e0 migliore di questa. Crediamo &#8211; scrive in una nota il Meet up Cosenza e Oltre &#8211; che<strong> la scuola rappresenti la chiave di volta e l\u2019epicentro critico per\u00a0formare la persona, ossia l\u2019individuo nella pienezza dei propr\u00ee diritti e doveri<\/strong>. La scuola serve a\u00a0cambiare la societ\u00e0 e a garantire il funzionamento delle istituzioni. Per questo motivo\u00a0crediamo sia giunto il momento di cambiare radicalmente la scuola&#8221;. All&#8217;incontro parteciperanno i\u00a0portavoce del Movimento 5 Stelle al Senato e alla Camera: Silvia Chimienti, Nicola Morra, Luigi Gallo, Maria Marzana e Valente Simone. La cittadinanza tutta \u00e8 inviata a partecipare.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Assemblea aperta tra docenti, studenti, cittadini e parlamentari per conoscere il documento che si propone di rivoluzionare l&#8217;istruzione.<\/p>\n","protected":false},"author":21,"featured_media":74391,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,34,53],"tags":[],"class_list":["post-74390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-magazine","category-ck20-scuola"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=74390"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74390\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/74391"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=74390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=74390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=74390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}