{"id":74394,"date":"2017-01-28T06:38:18","date_gmt":"2017-01-28T05:38:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ndrangheta-dossier-della-dia-svela-lespansione-dei-muto-a-roma-e-il-patto-tra-italiani-e-clan-rango\/"},"modified":"2023-01-16T19:26:30","modified_gmt":"2023-01-16T18:26:30","slug":"134297-ndrangheta-dossier-della-dia-svela-lespansione-dei-muto-a-roma-e-il-patto-tra-italiani-e-clan-rango","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/134297-ndrangheta-dossier-della-dia-svela-lespansione-dei-muto-a-roma-e-il-patto-tra-italiani-e-clan-rango\/","title":{"rendered":"&#8216;Ndrangheta: dossier della Dia, l&#8217;espansione dei Muto a Roma e il patto tra &#8220;Italiani e clan Rango&#8221;"},"content":{"rendered":"<p><strong>La \u2018ndrangheta \u00e8 l&#8217;organizzazione criminale pi\u00f9 potente, con un organismo decisionale di vertice e una base territoriale. Due facce di una stessa medaglia: una moderna e in grado di aggiornarsi e cogliere ogni occasione di profitto e l\u2019altra arcaica, fatta di radici e regole, giuramenti e sangue<\/strong><!--more--><\/p>\n<p>COSENZA &#8211; La &#8216;ndrangheta \u00e8 la pi\u00f9 potente organizzazioni mafiosa a livello internazionale. Questo \u00e8 il &#8216;dato&#8217; che emerge chiaramente nell&#8217;analisi contenuta nella Relazione relativa al primo semestre del 2016 della Direzione investigativa antimafia.<\/p>\n<p>Ha radicamenti all\u2019estero, ed \u00e8 capace di crescere, ramificarsi e occupare nuovi spazi. Le inchieste giudiziarie che hanno caratterizzato il semestre, scrive la Direzione Investigativa Antimafia, &#8220;confermano l\u2019andamento gi\u00e0 registrato negli anni precedenti, che vede le cosche in grado di intessere profonde relazioni con soggetti corrotti degli apparati istituzionali e con professionisti piegati alle logiche mafiose. La duttilit\u00e0 operativa fuori Regione dell\u2019organizzazione deriva, infatti, dalla commistione tra le professionalit\u00e0 maturate, soprattutto nel Nord del Paese, da affiliati di nuova generazione, diretta espressione delle famiglie, e professionisti attratti consapevolmente alla \u2018ndrangheta&#8221;.<\/p>\n<p>Questo &#8220;connubio tra cosche e professionisti, specie di quelli operanti in settori ad alta redditivit\u00e0 come la grande distribuzione, l\u2019immobiliare e quello turistico-alberghiero e i forti addentellati con esponenti della pubblica amministrazione si affiancano, cos\u00ec, a quella che rimane la principale fonte di finanziamento, ossia il traffico internazionale di stupefacenti, e a una pressante azione usuraria ed estorsiva&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-134300 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/01\/dia-stemma-legno-web.jpg\" alt=\"dia-stemma-legno-web\" width=\"432\" height=\"212\" title=\"\"><\/p>\n<h2>Provincia di Cosenza: dai Rango-Zingari al clan Lanzino Ru\u00e0, fino ai Muto di Cetraro<\/h2>\n<p>Il panorama criminale della provincia appare sostanzialmente immutato rispetto ai semestri precedenti, restando caratterizzato dall\u2019operativit\u00e0 del gruppo <strong>Rango- Zingari<\/strong>, sorto, nel recente passato, dalla fusione tra i <strong>superstiti della cosca&#8221;Bella Bella&#8221;<\/strong>\u00a0il gruppo degli <strong>Zingari cosentini<\/strong>. L\u2019aggregato criminale avrebbe, inoltre, stretto un <strong>patto federativo<\/strong> con le due compagini mafiose dei <strong>Perna-Cicerto e Lanzino-Ru\u00e0,<\/strong>\u00a0anch\u2019esse operanti nel capoluogo.<\/p>\n<h3>I patti elettorali-mafiosi del &#8216;Sistema Rende&#8217;<\/h3>\n<p>Nel mese di <strong>marzo<\/strong>, proprio la cosca Lanzino-Ru\u00e0,\u00a0\u00e8 stata al centro di un\u2019articolata operazione di servizio denominata &#8220;<strong>Sistema Rende&#8221;,<\/strong>\u00a0conclusa dall\u2019Arma dei Carabinieri con l\u2019<strong>arresto di 10 persone<\/strong>, tra cui alcuni politici locali e esponenti di vertice della cosca. Le indagini hanno delineato un <strong>\u201cintreccio\u201d politico \u2013 mafioso<\/strong> che ha consentito ad alcuni candidati alle varie tornate elettorali per il rinnovo degli Enti locali, di ottenere l\u2019appoggio elettorale da parte di personaggi di rilievo della citata cosca.<\/p>\n<p>Tra le attivit\u00e0 illecite riscontrate \u2013 frutto di \u201c<strong>patti elettorali mafiosi\u201d<\/strong> \u2013 figurano l\u2019affidamento di spazi pubblici in gestione a personaggi appartenenti alla \u2018ndrangheta; l\u2019assunzione, presso la societ\u00e0 municipalizzata preposta alla gestione dei servizi comunali, di soggetti vicini al gruppo criminale e la promessa dell\u2019assegnazione di fondi pubblici, per finanziare una cooperativa creata per la gestione dell\u2019area mercatale di Rende.<\/p>\n<h3>I clan sul Tirreno cosentino<\/h3>\n<p>Proseguendo nell\u2019analisi dei singoli contesti territoriali della provincia, a Scalea si registra la presenza dei <strong>Valente e degli Stummo<\/strong>, in contatto con i <strong>Muto<\/strong>, la cui influenza si estende su tutto il versante tirrenico cosentino, da Guardia Piemontese fino al confine con la Basilicata.<\/p>\n<p><strong>La citt\u00e0 di Paola<\/strong>, oltre a subire l\u2019influenza dei citati Rango-Zingari, risulta segnata dalle cosche <strong>Martello-Scofano-Ditto e Serpa<\/strong>\u00a0da sempre contrapposte. Ad <strong>Amantea<\/strong>, al confine con la provincia di Catanzaro, insistono i <strong>Besaldo, gli Africano e i Gentile<\/strong>, quest\u2019ultimi colpiti da una confisca eseguita nel mese di marzo dalla Sezione Operativa D.I.A. di Catanzaro. Nello specifico \u00e8 stato sottratto ad un<strong> imprenditore<\/strong> \u2013 peraltro nipote del capo cosca e collegato alla \u2018ndrina <strong>Lanzino-Di Puppo<\/strong> \u2013 un patrimonio del valore di oltre <strong>1,2 milioni di euro<\/strong>, costituito, tra l\u2019altro, da un\u2019attivit\u00e0 di commercio al dettaglio di abbigliamento e da quote di societ\u00e0 operanti nel comparto della gestione degli impianti sportivi, della pulizia in genere e del commercio di autoveicoli. Da sottolineare che nel Lazio e in particolare a Roma, \u00e8 stata riscontrata molto attiva la cosca <strong>Muto di Cetraro. <\/strong><\/p>\n<h3>Il clan sullo Jonio cosentino<\/h3>\n<p>Sul versante ionico, riporta la relazione della Dia, sarebbero invece attivi gli <strong>Abbruzzese<\/strong>, con particolare riferimento ai comuni di <strong>Cassano allo Ionio, Rossano, Corigliano Calabro, Cosenza e Scanzano Jonio (Mt)<\/strong>, mentre a <strong>Castrovillari<\/strong> si segnalano i<strong> Recchia- Impieri.<\/strong> Sempre su <strong>Cassano<\/strong> allo Ionio si segnalano, oltre agli Abbruzzese, anche i <strong>Forastefano-Portofaro-Faillace e i Bevilacqua<\/strong>. Nella zona di <strong>Rossano<\/strong> e nella Piana di Sibari sarebbero infine operativi i <strong>Galluzzi-Acri-Morf\u00f2,<\/strong> mentre a sud della provincia, tra <strong>Paterno Calabro, Rogliano e Piano Lago<\/strong> si segnalano i <strong>Chirillo<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La \u2018ndrangheta \u00e8 l&#8217;organizzazione criminale pi\u00f9 potente, con un organismo decisionale di vertice e una base territoriale. Due facce di una stessa medaglia: una moderna e in grado di aggiornarsi e cogliere ogni occasione di profitto e l\u2019altra arcaica, fatta di radici e regole, giuramenti e sangue<\/p>\n","protected":false},"author":22,"featured_media":74395,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-74394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=74394"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74394\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/74395"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=74394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=74394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=74394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}