{"id":74400,"date":"2017-01-28T08:20:15","date_gmt":"2017-01-28T07:20:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sfruttava-i-suoi-dipendenti-interdetto-imprenditore-lametino\/"},"modified":"2023-01-16T19:26:31","modified_gmt":"2023-01-16T18:26:31","slug":"134308-sfruttava-i-suoi-dipendenti-interdetto-imprenditore-lametino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/134308-sfruttava-i-suoi-dipendenti-interdetto-imprenditore-lametino\/","title":{"rendered":"Sfruttava i suoi dipendenti, interdetto imprenditore lametino"},"content":{"rendered":"<p><strong>Operazione &#8220;Spartaco&#8221; questa mattina della Finanza di Lamezia; interdetto un ristoratore che vessava i suoi dipendenti<\/strong><!--more--><\/p>\n<p>LAMEZIA TERME &#8211; Il gruppo della guardia di finanza di Lamezia Terme ha eseguito un\u2019ordinanza applicativa di misure cautelari personali e patrimoniali nei confronti di un imprenditore del settore della ristorazione, indagato per il reato di<strong> estorsione continuata<\/strong> verso<strong> undici lavoratori<\/strong>, suoi dipendenti. All\u2019uomo \u00e8 stato temporaneamente imposto il divieto di esercitare ogni attivit\u00e0 d\u2019impresa. L\u2019operazione, che \u00e8 stata denominata \u201c<strong>Spartaco<\/strong>\u201d, dal nome del famoso schiavo ribelle, \u00e8 scaturita dalla denuncia di un dipendente che era stato licenziato perch\u00e8 si era lamentato per le condizioni di sfruttamento cui era stato a lungo sottoposto.<\/p>\n<p>I finanzieri hanno poi scoperto che, almeno <strong>dall\u2019agosto del 2015 all\u2019ottobre del 2016<\/strong>, l\u2019imprenditore aveva costretto i suoi dipendenti ad accettare gravose condizioni di lavoro, consistenti nel prestare la propria attivit\u00e0 per<strong> otto-dieci ore al giorno, a fronte di un contratto part-time<\/strong> in base al quale venivano retribuiti per sole quattro o cinque ore giornaliere.<\/p>\n<p><strong>Ma non solo: in un caso, l\u2019imprenditore avrebbe anche minacciato in maniera grave uno dei dipendenti, che aveva \u201cosato\u201d reclamare i propri diritti, ventilando delle ritorsioni consistenti in violenze fisiche e materiali.<\/strong> I finanzieri hanno stimato che l\u2019imprenditore abbia guadagnato illecitamente circa 56.600 euro, cifra che \u00e8 stata preventivamente sequestrata come provento della presunta estorsione.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Operazione &#8220;Spartaco&#8221; questa mattina della Finanza di Lamezia; interdetto un ristoratore che vessava i suoi dipendenti<\/p>\n","protected":false},"author":32,"featured_media":74401,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-74400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=74400"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74400\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/74401"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=74400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=74400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=74400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}