{"id":74571,"date":"2017-02-01T16:39:40","date_gmt":"2017-02-01T15:39:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/triplice-omicidio-cassano-pentiti-aula-parlano-eroina-infamate\/"},"modified":"2023-01-16T19:26:42","modified_gmt":"2023-01-16T18:26:42","slug":"135084-triplice-omicidio-cassano-pentiti-aula-parlano-eroina-infamate","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/135084-triplice-omicidio-cassano-pentiti-aula-parlano-eroina-infamate\/","title":{"rendered":"Triplice omicidio di Cassano, pentiti in aula parlano di eroina e &#8216;infamate&#8217;"},"content":{"rendered":"<h4>Tre collaboratori di giustizia oggi a Cosenza hanno tentato di ricostruire le ragioni che avrebbero portato all&#8217;uccisione di Coc\u00f2 Campolongo, Ibtissam Touss e Giuseppe Iannicelli.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Tre corpi carbonizzati in una Fiat Punto in agro di Cassano allo Jonio. Il\u00a0pluripregiudicato cinquantaduenne Giuseppe Iannicelli, il nipotino di tre anni Coco\u2019 Campilongo e la compagna del nonno, la marocchina di ventisettenne Ibtissam Touss furono trucidati senza piet\u00e0, nei pressi di un casolare abbandonato poco distante dalla loro abitazione. Un delitto efferato portato a termine con freddezza, per ragioni ancora da tutte chiarire. Oggi in aula dove si sta celebrando <strong>il processo a carico dei due unici imputati del triplice omicidio, Cosimo Donato e Faustino Campilongo, tre collaboratori di giustizia della sibaritide hanno tentato di chiarire il contesto in cui \u00e8 maturato il delitto<\/strong>. Inanzi al collegio giudicante della Corte d&#8217;Assise del Tribunale di Cosenza presieduto da Giovanni Garofalo con a latere il giudice Francesca De Vuono i &#8216;pentiti&#8217; hanno rivelato alcuni particolari della vita di Iannicelli. Incalzati dalle domande del pm Saverio Vertuccio, i collaboratori hanno dato versioni parzialmente differenti su quello che era il ruolo di Iannicelli all&#8217;interno del panorama criminale della sibaritide.<\/p>\n<p>&nbsp;<\/p>\n<h3>LE DICHIARAZIONI DEL COLLABORATORE DI GIUSTIZIA ANTONIO FORASTEFANO<\/h3>\n<p>In videoconferenza da localit\u00e0 protetta l&#8217;ex boss Antonio Forastefano ha chiarito i rapporti del suo clan con Iannicelli. &#8220;Lo conoscevo da anni. Quando io divenni il capo del clan dopo la guerra di mafia, &#8211; ha spiegato Antonio Forastefano &#8211; ha iniziato a vendere la droga per me. Prima lavorava per gli zingari, che io abbia memoria\u00a0sin dal 1998\u00a0ha sempre spacciato. Dopo che io presi il controllo Giuseppe Iannicelli chiese di incontrarmi. <strong>Eduardo Pepe e Fioravante Abbruzzese erano stati gi\u00e0 uccisi ed io ero latitante, ma fissai con lui un appuntamento in un terreno e gli imposi di acquistare da me eroina e cocaina<\/strong>, altrimenti sarei stato costretto ad ucciderlo. Era una scelta obbligata. Quando lo arrestarono era la moglie che veniva a ritirare la droga da me. Non credo avesse problemi con gli Zingari, per\u00f2 in mia presenza parlava male della famiglia Abbruzzese dicendo che non riusciva a guadagnare abbastanza denaro&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<h3>LE DICHIARAZIONI DEL COLLABORATORE DI GIUSTIZIA\u00a0PASQUALE PERCIACCANTE<\/h3>\n<p>Il collaboratore di giustizia Pasquale Perciaccante, cognato di Iannicelli, si \u00e8 presentato in aula e dinanzi al collegio giudicante ha tentato di far comprendere quale posizione rivestisse il suo congiunto all&#8217;interno della cosca. &#8220;Ero un affiliato al clan degli Abbruzzese di Lauropoli, &#8211; ha chiarito Perciaccante oggi in aula &#8211; una consorteria prima guidata da Franco Abbruzzese &#8216;Dentuzzo&#8217; e poi da Eduardo Pepe. Iannicelli spacciava eroina a Cassano, gliela vendevamo noi la veniva a prendere a Lauropoli. Aspirava ad un ruolo maggiore, di vertice, pi\u00f9 indipendente, ma pi\u00f9 volte gli era stato ribadito che lui doveva vendere la droga. E basta. Infatti non aveva nessuna informazione su agguati e sulle altre attivit\u00e0 del clan. Per tenerlo buoni gli fecero anche una finta affiliazione, la terza, ma era solo un trucco perch\u00e9 in realt\u00e0 non aveva nessun valore in quanto invece di cinque referenti era avvenuta alla presenza di solo Franco Abruzzese e Nicola Bevilacqua. In realt\u00e0 non lo volevano nel clan perch\u00e9 parlava troppo, per\u00f2 era utile per smistare l&#8217;eroina. <strong>Quando abbiamo capito che comprava la droga dai Forastefano gli abbiamo chiarito che se avesse continuato cos\u00ec sarebbe stato ammazzato come Antonio Bevilacqua &#8216;Popin&#8217;.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Il fratello, Battista Iannicelli, pi\u00f9 volte mi aveva confessato di esser guardato con sospetto ogni volta che andava alle case popolari a Timpone Rosso. Diceva che gli zingari lo odiavano, che gli avevano fatto il segno della pistola una volta in piazza. <strong>Si diceva che volesse collaborare con la giustizia per non farsi uccidere. <\/strong>In pi\u00f9 era accusato di aver &#8216;infamato&#8217; Fiore Abbruzzese, figlio di Franco Abbruzzese &#8216;Dentuzzo&#8217;, quando nel corso di una perquisizione gli trovarono a casa dei caricatori e dei kalashnikov. Iannicelli infatti, si diceva, che avesse detto alle forze dell&#8217;ordine che le armi erano di Fiore. Gi\u00e0 nel 2004 quando io ero in carcere a Catanzaro avevamo fatto una riunione in cui c&#8217;erano anche Mario Bevilacqua, Andrea Abbruzzese e Tommaso Iannicelli e l\u00ec si era deciso che &#8216;appena usciti lo facciamo fuori&#8217;. Mi \u00e8 stato raccontato da Battista che Iannicelli il giorno in cui \u00e8 morto aveva un appuntamento a Sibari, ma era una trappola. A Sibari non c&#8217;\u00e8 mai arrivato \u00e8 stato ucciso vicino casa sua. Che io sappia ha sempre comprato la &#8216;nera&#8217; alle case popolari, dalla famiglia Abbruzzese dal &#8217;98 fino alla sua morte&#8221;,<\/p>\n<h3>LE DICHIARAZIONI DEL COLLABORATORE DI GIUSTIZIA DOMENICO FALBO<\/h3>\n<p>&nbsp;<\/p>\n<p>L&#8217;ultimo dei &#8216;pentiti&#8217; a testimoniare oggi in aula \u00e8 stato il trentacinquenne Domenico Falbo. &#8220;Appartenevo al clan dei Forastefano, &#8211; ha raccontato Falbo &#8211; conoscevo Giuseppe Iannicelli perch\u00e9 abitava nel mio quartiere. Era molto vicino agli Abbruzzese e spacciava eroina e cocaina dalla fine degli anni &#8217;90 quando ancora si poteva vendere in maniera &#8216;libera&#8217; senza il condizionamento dei clan. Quando il cognato Pasquale Perciaccante gli ha presentato gli Abbruzzese ha iniziato a collaborare con loro. Poi ad un certo punto ha iniziato a rifornirsi dai Forastefano di nascosto dagli zingari. Viceversa comprava la droga dagli Abbruzzese senza far sapere nulla ai Forastefano. A dicembre in carcere ho conosciuto un collaboratore di giustizia che ha frequentato Faustino Campilongo nel penitenziario di Torino. Mi ha raccontato che gli aveva confessato di essere stato costretto ad uccidere Iannicelli con il bambino e la fidanzata. Era un gesto che dovevano compiere<strong> per dimostrare la fedelt\u00e0 al clan degli zingari e poter entrare nella consorteria a pieno titolo. I mandanti secondo la sua versione sono gli zingari&#8221;.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\">LEGGI ANCHE<\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/2310\"><span class=\"current\"> Triplice omicidio a Cassano, quel \u2018mi piace\u2019 su facebook cliccato dopo la scomparsa<\/span><\/a><\/span><\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/1626\"><span class=\"current\">Le foto os\u00e9 di Iannicelli sul cellulare, i retroscena del delitto di Coc\u00f2 Campolongo (VIDEO)<\/span><\/a><\/span><\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/2046\">Omicidio Coc\u00f2, giallo su chi guidava l\u2019auto del nonno<\/a><\/span><\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/1960\">Triplice omicidio di Cassano,<\/a>\u00a0<a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/1960\">il nonno di Coc\u00f2 segu\u00ec in auto una Fiat Uno<\/a><\/span><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Tre collaboratori di giustizia oggi a Cosenza hanno tentato di ricostruire le ragioni che avrebbero portato all&#8217;uccisione di Coc\u00f2 Campolongo, Ibtissam Touss e Giuseppe Iannicelli.<\/p>\n","protected":false},"author":18,"featured_media":74572,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-74571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=74571"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74571\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/74572"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=74571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=74571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=74571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}