{"id":74642,"date":"2017-02-03T17:04:58","date_gmt":"2017-02-03T16:04:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ragazzino-in-ospedale-dopo-aver-bevuto-una-bottiglietta-dacqua\/"},"modified":"2023-01-16T19:26:47","modified_gmt":"2023-01-16T18:26:47","slug":"135576-ragazzino-in-ospedale-dopo-aver-bevuto-una-bottiglietta-dacqua","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/135576-ragazzino-in-ospedale-dopo-aver-bevuto-una-bottiglietta-dacqua\/","title":{"rendered":"Ragazzino in ospedale dopo aver bevuto una bottiglietta d&#8217;acqua"},"content":{"rendered":"<header class=\"header\">\n<h4>Anche la madre del dodicenne ha avvertito un malore dopo aver bevuto la stessa acqua.<\/h4>\n<\/header>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>LOCRI (RC) &#8211; Un dodicenne \u00e8 stato ricoverato d&#8217;urgenza all&#8217;Ospedale di Locri dopo aver bevuto dell&#8217;acqua. Il ragazzino rientrato a casa dopo essersi allenato in un campo di calcio, avrebbe stappato una bottiglietta d&#8217;acqua minerale acquistata in un supermercato vicino casa. Dopo aver ingerito parte del liquido contenuto avrebbe poi iniziato ad avvertire forti dolori all&#8217;addome. Trasportato d&#8217;urgenza al Pronto Soccorso di Locri \u00e8 stato ricoverato per accertare cosa sia stato a causare i crampi che hanno colpito stomaco ed esofago del ragazzino.<\/p>\n<p>&nbsp;<\/p>\n<p>Anche la madre del giovane sportivo <strong>dopo aver bevuto qualche sorso dalla stessa bottiglietta, da mezzo litro, ha avvertito un malore con dolori simili a quelli lamentati dal figlio pochi minuti prima.<\/strong> Il dodicenne \u00e8 ora ricoverato in osservazione. L&#8217;acqua era imbottigliata in una confezione che reca sovrimpressione un noto marchio nazionale. Sul caso indagano i carabinieri che hanno provveduto al sequestro della bottiglietta e di parte del suo contenuto. L&#8217;acqua al suo interno \u00e8 stata sottoposta ad analisi di laboratorio per verificare se sia stata contaminata da agenti esterni. Madre e figlio sono ora in buone condizioni di salute.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche la madre del dodicenne ha avvertito un malore dopo aver bevuto la stessa acqua.<\/p>\n","protected":false},"author":22,"featured_media":74643,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-74642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=74642"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/74643"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=74642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=74642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=74642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}