{"id":74805,"date":"2017-02-08T18:44:42","date_gmt":"2017-02-08T17:44:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/valle-di-confino-i-sovversivi-dimenticati-della-valle-del-savuto-tornano-alla-luce\/"},"modified":"2023-01-16T19:26:58","modified_gmt":"2023-01-16T18:26:58","slug":"136413-valle-di-confino-i-sovversivi-dimenticati-della-valle-del-savuto-tornano-alla-luce","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/136413-valle-di-confino-i-sovversivi-dimenticati-della-valle-del-savuto-tornano-alla-luce\/","title":{"rendered":"&#8220;Valle di Confino&#8221;: i &#8220;sovversivi&#8221; dimenticati della Valle del Savuto, tornano alla luce"},"content":{"rendered":"<p><strong><span style=\"line-height: 1.5;\">Il\u00a0nuovo libro di Leonardo Falbo \u201cValle di Confino. Sovversivi inviati nel Savuto durante il Fascismo\u201d,\u00a0restituisce finalmente alla storia i volti e le gesta dei \u201csovversivi\u201d che per anni popolarono la nostra Valle del Savuto.<\/span><\/strong><!--more--><\/p>\n<p><span style=\"line-height: 1.5;\">COLOSIMI (CS) &#8211; E&#8217; uscito da poco il\u00a0nuovo libro di <\/span><strong style=\"line-height: 1.5;\">Leonardo Falbo \u201cValle di Confino. Sovversivi inviati nel Savuto durante il Fascismo\u201d<\/strong><span style=\"line-height: 1.5;\">, edito da Comet Editor Press. <\/span><strong style=\"line-height: 1.5;\">Il saggio \u201cValle di Confino\u201d restituisce finalmente alla storia i volti e le gesta dei \u201csovversivi\u201d che per anni popolarono la nostra Valle del Savuto, uomini e donne che con la loro vita testimoniarono il valore della libert\u00e0 e della democrazia.<\/strong><span style=\"line-height: 1.5;\">\u00a0Tra il 1926 e il 1942, 190 confinati \u2013 184 uomini e 6 donne, gran parte dei quali considerati in vario modo \u201csovversivi\u201d \u2013 furono inviati dal regime fascista nella Valle del Savuto.\u00a0Operai, contadini, braccianti, artigiani, inservienti, professionisti e preti furono letteralmente strappati dalle loro esistenze e confinati in dieci comuni della suddetta valle, tutti paesi \u201csegnati da profonda miseria\u201d e pienamente rispondenti alle esigenze del regime, ovvero \u201cessere lontani dalla vita\u201d. <\/span><strong style=\"line-height: 1.5;\">Per troppo tempo, le storie di questi uomini e di queste donne, sono rimaste avvolte nel silenzio e nell\u2019oblio. A riportare la luce, intrisa di rigore metodologico e amore per il proprio territorio, su questo prezioso spaccato di storia locale \u00e8 stato Leonardo Falbo<\/strong><span style=\"line-height: 1.5;\">, docente e storico roglianese, da anni attento e acuto ricercatore e osservatore delle vicende storiche del proprio paese natale, Rogliano, e dell\u2019intera Valle del Savuto.<\/span><\/p>\n<p><strong>L\u2019AUTORE<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-136414 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/02\/leornardo-falbo-321x280.jpg\" alt=\"leornardo falbo\" width=\"233\" height=\"203\" title=\"\">Leonardo Falbo nasce a Rogliano (CS). Docente di Italiano e Storia negli Istituti d\u2019Istruzione Superiore, \u00e8 comandato presso l\u2019Istituto calabrese per la storia dell\u2019antifascismo e dell\u2019Italia contemporanea. \u00c8 socio della Deputazione di Storia Patria per la Calabria e Membro del Comitato di Direzione della \u00abRivista Calabrese di Storia del \u2019900\u00bb. Ha pubblicato numerosi saggi e articoli tra cui: <em>Pietralata! Rogliano\/Marzi:<\/em>\u00a0<em>luogo-simbolo gioachimita?<\/em>, in \u00abAbate Gioacchino\u00bb, a. 0, n. 1, Cosenza, 2003;<em>\u201cL\u2019Operaio\u201d e \u201cCalabria Proletaria\u201d di<\/em>\u00a0<em>Fausto Gullo<\/em>, in<em>Mezzogiorno e Stato nell\u2019opera<\/em>\u00a0<em>di Fausto Gullo<\/em>\u00a0(a cura di Giuseppe Masi), Edizioni Orizzonti Meridionali, Cosenza, 1998;\u00a0<em>Dissenso sociale in Presila<\/em>\u00a0<em>durante il fascismo. Un diario inedito<\/em>, in \u00abRivista Calabrese di Storia del \u2018900\u00bb, 2\/2006-2008;\u00a0<em>Tracce di coniugazione tra<\/em>\u00a0<em>I\u00b0 e II\u00b0 Risorgimento a Cosenza<\/em>, in \u00abRivista Calabrese di Storia del \u2018900\u00bb, 2\/2010. Tra i suoi volumi:\u00a0<em>Vincenzo Gallo &#8211; \u2018U<\/em>\u00a0<em>Chitarraru. Drammaturgo e pedagogo<\/em>, Editoriale Progetto 2000, Cosenza, 1991;\u00a0<em>Fascismo e antifascismo in Calabria. Il<\/em>\u00a0<em>caso di Rogliano<\/em>, Edizioni Orizzonti Meridionali, Cosenza, 1995;\u00a0<em>Un santo per il<\/em>\u00a0<em>popolo. Vita, prodigi e profezie di Fra<\/em>\u00a0<em>\u2018Ntoni da Panettieri<\/em>, Editoriale Progetto 2000, Cosenza, 2003;\u00a0<em>La propriet\u00e0 terriera<\/em>\u00a0<em>nella Calabria di fine Ottocento: GeorgeGoyau e Michele Fera<\/em>\u00a0(a cura di), Pellegrini Editore, Cosenza, 2006;\u00a0<em>Donnu<\/em>\u00a0<em>Carminu. Saga politico-religiosa a Rogliano<\/em>\u00a0<em>nella prima met\u00e0 del Novecento<\/em>, Edizioni Orizzonti Meridionali, Cosenza, 2008.\u00a0Recentemente, colmando un vuoto nella ricerca storica calabrese, ha pubblicato:\u00a0<em>Non solo Ferramonti. Ebrei internati<\/em>\u00a0<em>in provincia di Cosenza (1940-1943)<\/em>, Pellegrini Editore, Cosenza, 2010.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-136415 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/02\/Cover-Valle-di-Confino-193x280.jpg\" alt=\"Cover Valle di Confino\" width=\"265\" height=\"384\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il\u00a0nuovo libro di Leonardo Falbo \u201cValle di Confino. Sovversivi inviati nel Savuto durante il Fascismo\u201d,\u00a0restituisce finalmente alla storia i volti e le gesta dei \u201csovversivi\u201d che per anni popolarono la nostra Valle del Savuto.<\/p>\n","protected":false},"author":22,"featured_media":74806,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[25],"tags":[],"class_list":["post-74805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-libri"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=74805"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74805\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/74806"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=74805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=74805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=74805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}