{"id":74819,"date":"2017-02-10T05:30:33","date_gmt":"2017-02-10T04:30:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sistema-sismi-ca-parentela-scrive-a-musmanno-la-risposta-aumenta-i-dubbi\/"},"modified":"2023-01-16T19:26:59","modified_gmt":"2023-01-16T18:26:59","slug":"136469-sistema-sismi-ca-parentela-scrive-a-musmanno-la-risposta-aumenta-i-dubbi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/136469-sistema-sismi-ca-parentela-scrive-a-musmanno-la-risposta-aumenta-i-dubbi\/","title":{"rendered":"Il rischio terremoti in Calabria, il &#8216;pasticcio&#8217; del sistema &#8221;Sismi.ca&#8221; e i litigi"},"content":{"rendered":"<p><strong>Il deputato Paolo Parentela (M5S), circa un mese fa ha scritto all&#8217;Assessore Musmanno, riguardo\u00a0le criticit\u00e0 della nuova piattaforma Sismi.ca; ma nei fatti, non \u00e8 stato preso alcun provvedimento concreto.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; &#8220;La Regione Calabria continua a confondere le idee ad ingegneri ed architetti sul software messo in opera dal primo gennaio in attuazione del regolamento regionale sulle procedure per la denuncia, il deposito e l\u2019autorizzazione di interventi di carattere strutturale e per la pianificazione territoriale in prospettiva sismica, denominato <strong>Sismi.ca<\/strong>&#8220;. Lo afferma il <strong>deputato M5s Paolo Parentela<\/strong>, che aggiunge: &#8220;<strong>Circa un mese fa ho scritto all\u2019assessore Musmanno, prendendomi carico delle segnalazioni dei professionisti.<\/strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-135176 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/02\/Sismi.ca_-440x195.png\" alt=\"Sismi.ca\" width=\"422\" height=\"187\" title=\"\"> La risposta dell\u2019assessore, per\u00f2, lascia non pochi dubbi interpretativi anche a me, che tecnico non sono. Innanzitutto, <strong>l\u2019assessore sostiene che il nuovo sistema servir\u00e0 a ridurre l\u2019esposizione al rischio di crolli in caso di terremoto. Questo mi induce a pensare che il sistema Sie-rc, adottato in precedenza e con il quale la Regione Calabria ha autorizzato centinaia di progetti, non fosse perfettamente in regola n\u00e8 collaudato allo scopo dettato dalla norma emanata nel 2009, al punto da mettere a rischio la vita dei cittadini calabresi in caso di crolli dovuti ad eventi sismici<\/strong>&#8220;.<\/p>\n<p>Il Cinque Stelle continua: &#8220;Musmanno ha affermato che la Regione Calabria non \u00e8 l\u2019unica in Italia ad avere introdotto un sistema obbligatorio di trasmissione telematica dei progetti. \u00c8 anche vero, per\u00f2, che <strong>nelle altre Regioni viene richiesta la compilazione di un format che tende ad uniformare i dati senza verificare quelli immessi in modo automatico. Questo penalizza i tecnici calabresi e tutti i tecnici operanti nella Regione Calabria che devono sottoporsi ad inutili procedure di verifica senza sgravi di responsabilit\u00e0 che resta in capo a loro.\u00a0<\/strong>La Regione si adoperi quantomeno ad organizzare corsi e seminari per i tecnici costretti ad utilizzare il sistema Sismi.ca ed a correggere le criticit\u00e0 riscontrate. Un giorno, magari, ci diranno anche perch\u00e9 <strong>a soli quattro anni di distanza dall\u2019approvazione della normativa regionale e dalla relativa adozione del vecchio sistema, si sia dovuto procedere alla creazione di un nuovo software<\/strong> ed i motivi per cui non sia stato possibile correggere il vecchio sistema. Forse avremmo anche risparmiato qualche euro dei contribuenti&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><span style=\"text-decoration: underline;\">LEGGI ANCHE:<\/span><\/h3>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/2334\"><span style=\"text-decoration: underline; color: #0000ff;\">Piattaforma \u201cSismi.ca\u201d il solito flop della Regione? Architetti e Ingegneri sul piede di guerra<\/span><\/a><\/h2>\n<p>&nbsp;<\/p>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/2336\"><span style=\"text-decoration: underline; color: #0000ff;\">Piattaforma \u201cSismi.ca\u201d priva di efficacia: \u201cla Regione vuole piangere sul latte versato?\u201d<\/span><\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Il deputato Paolo Parentela (M5S), circa un mese fa ha scritto all&#8217;Assessore Musmanno, riguardo\u00a0le criticit\u00e0 della nuova piattaforma Sismi.ca; ma nei fatti, non \u00e8 stato preso alcun provvedimento concreto.<\/p>\n","protected":false},"author":22,"featured_media":74820,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-74819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=74819"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/74819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/74820"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=74819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=74819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=74819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}