{"id":75073,"date":"2017-02-16T07:23:32","date_gmt":"2017-02-16T06:23:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/discarica-chiusa-continuava-sversare-percolato-nelle-campagne-sequestrata-larea\/"},"modified":"2023-01-16T19:27:16","modified_gmt":"2023-01-16T18:27:16","slug":"137587-discarica-chiusa-continuava-sversare-percolato-nelle-campagne-sequestrata-larea","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/137587-discarica-chiusa-continuava-sversare-percolato-nelle-campagne-sequestrata-larea\/","title":{"rendered":"Discarica chiusa continuava a sversare percolato nelle campagne, sequestrata l&#8217;area"},"content":{"rendered":"<p><strong>La discarica era chiusa da tempo ma continuava a sversare pericoloso percolato nelle campagne circostanti e i carabinieri hanno sequestrato l\u2019area e avviato le relative indagini.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>MELITO PORTO SALVO (RC) &#8211; L&#8217;attivit\u00e0 di controllo e repressione dei reati ambientali nel territorio della Provincia di Reggio Calabria, ha portato i Carabinieri Forestali del neo istituito Comando Unit\u00e0 Tutela Forestale Ambientale e Agroalimentare a Melito di Porto Salvo<strong>, in localit\u00e0 Chianca<\/strong> dove \u00e8 stata sequestrata una<strong> discarica comunale<\/strong> di rifiuti solidi urbani.<\/p>\n<p>Dalla discarica, dismessa da anni, fuoriuscivano in modo incontrollato, i liquami di percolazione che, spandendosi nei terreni agricoli circostanti, confluivano poi nel <strong>torrente Arcina<\/strong>. L\u2019indagine ha subito messo in luce tutta una serie di problematiche relative alla gestione della discarica, in uso dal comune di Melito di Porto Salvo dal 1991 al 1999, relativamente alla gestione del percolato, ovvero i <strong>liquami, fortemente inquinanti,<\/strong> che si formano prevalentemente per la decomposizione della frazione organica dei rifiuti soliti urbani.<\/p>\n<p>Dagli accertamenti eseguiti \u00e8 risultato che la discarica, di recente, era stata anche interessata da un movimento franoso dei terreni sovrastanti che, oltre ad aver provocato il danneggiamento della rete di scolo e raccolta del percolato, fa sorgere non pochi interrogativi sulla idoneit\u00e0 del sito per l\u2019allocazione della discarica stessa. I sopralluoghi effettuati dai vertici della Protezione Civile della Regione Calabria e dai tecnici dell\u2019ArpaCal, congiuntamente con i tecnici del Comune interessato, hanno inoltre evidenziato la presenza <strong>di una vasca di raccolta del percolato ormai piena<\/strong> e quindi non pi\u00f9 in grado di contenere il liquame via via prodotto che, per come prescrive la vigente normativa, deve essere opportunamente raccolto, trattato e smaltito in impianti autorizzati.<\/p>\n<p>Considerata la situazione, i militari intervenuti hanno posto sotto sequestro penale l\u2019intera area, per un\u2019estensione pari a circa due ettari complessivi, lasciando la facolt\u00e0 d\u2019uso per le sole operazioni di bonifica e messa in sicurezza ed il sequestro \u00e8 stato gi\u00e0 convalidato dalla competente Autorit\u00e0 giudiziaria. Nell\u2019attesa dei risultati delle analisi su natura e pericolosit\u00e0 dei reflui, il Comune di Melito di Porto Salvo ha disposto il divieto assoluto di coltivazione, pascolo e di qualsiasi altro utilizzo agronomico dei terreni interessato dallo sversamento, nonch\u00e9 la realizzazione, in somma urgenza, delle opere necessarie per canalizzare e raccogliere il percolato. Le indagini disposte dalla Procura della Repubblica di Reggio Calabria vaglieranno, attraverso l\u2019analisi della corposa documentazione sequestrata, eventuali responsabilit\u00e0 penali ai sensi del testo unico sull\u2019ambiente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La discarica era chiusa da tempo ma continuava a sversare pericoloso percolato nelle campagne circostanti e i carabinieri hanno sequestrato l\u2019area e avviato le relative indagini.<\/p>\n","protected":false},"author":19,"featured_media":75074,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-75073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/75073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=75073"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/75073\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/75074"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=75073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=75073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=75073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}