{"id":75284,"date":"2017-02-23T04:39:13","date_gmt":"2017-02-23T03:39:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/studenti-vogliono-trasporti-gratis-qualita-piazza-prossimo-10-marzo\/"},"modified":"2023-01-16T19:27:30","modified_gmt":"2023-01-16T18:27:30","slug":"138624-studenti-vogliono-trasporti-gratis-qualita-piazza-prossimo-10-marzo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/138624-studenti-vogliono-trasporti-gratis-qualita-piazza-prossimo-10-marzo\/","title":{"rendered":"Studenti in piazza il prossimo 10 marzo contro la metro e per trasporti di qualit\u00e0"},"content":{"rendered":"<p><strong>\u201cIn questi mesi abbiamo svolto un\u2019inchiesta fra gli studenti delle scuole di Cosenza e provincia riguardo al trasporto pubblico ed \u00e8 emerso che il servizio \u00e8 pessimo e costoso\u201d.<\/strong><!--more--><\/p>\n<p>COSENZA &#8211; \u201cGli studenti lamentano poche corse giornaliere, scarsa manutenzione dei mezzi, sovraffollamento degli stessi e abbonamenti mensili che superano i 100\u20ac! Tutto questo \u00e8 inaccettabile se si considera che la Regione Calabria regala milioni di euro di finanziamenti alle ditte di trasporto pubblico ogni anno, ma nonostante ci\u00f2 il servizio non migliora e il costo \u00e8 aumentato di oltre il 60% negli ultimi anni&#8221;. A scriverlo \u00e8 <strong>Antonio Viteritti, segretario della Federazione di Cosenza del Fronte della Giovent\u00f9 Comunista,<\/strong> che prosegue: &#8220;La Regione non ha un vero piano per rilanciare il trasporto pubblico, ma preferisce favorire le stesse ditte che ormai detengono il monopolio del servizio da decenni e sostenere il progetto della metro leggera a Cosenza, che non risolver\u00e0 i problemi di mobilit\u00e0 dell\u2019area urbana e della provincia, ma far\u00e0 arricchire costruttori e speculatori, scaricandone il costo sulle spalle dei cosentini&#8221;.<\/p>\n<p>&#8220;Non possiamo pi\u00f9 accettare che si speculi sulla pelle di studenti e lavoratori &#8211; conclude la nota del Fgc &#8211; e perci\u00f2 lanceremo a breve una petizione con la quale chiediamo un trasporto pubblico e di qualit\u00e0 per studenti e lavoratori e la creazione di un\u2019unica ditta di trasporto per tutta la Regione, che sia pubblica e gestita dai lavoratori. Infine per sostenere le nostre ragioni ed opporci al progetto della metro scenderemo <strong>in piazza con gli studenti di Cosenza e provincia il 10 marzo<\/strong>\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cIn questi mesi abbiamo svolto un\u2019inchiesta fra gli studenti delle scuole di Cosenza e provincia riguardo al trasporto pubblico ed \u00e8 emerso che il servizio \u00e8 pessimo e costoso\u201d.<\/p>\n","protected":false},"author":21,"featured_media":75285,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-75284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/75284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=75284"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/75284\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/75285"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=75284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=75284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=75284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}