{"id":75316,"date":"2017-02-22T18:34:07","date_gmt":"2017-02-22T17:34:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/carnevale-castrovillari-puglia-prossimi-eventi\/"},"modified":"2023-01-16T19:27:33","modified_gmt":"2023-01-16T18:27:33","slug":"138746-carnevale-castrovillari-puglia-prossimi-eventi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/138746-carnevale-castrovillari-puglia-prossimi-eventi\/","title":{"rendered":"Festeggiare il Carnevale nel Sud Italia, confronto tra Castrovillari e la Puglia"},"content":{"rendered":"<p><span style=\"line-height: 1.5;\"><strong>La 59\u00aa edizione del Carnevale di Castrovillari ha scelto come Focus la Puglia. Tanti gli appuntamenti\u00a0nei prossimi giorni.<\/strong><\/span><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"line-height: 1.5;\">CASTROVILLARI (CS) &#8211; Il Carnevale di Castrovillari \u00e8 anche cultura. Gli eventi sono curati dalla consulta scientifica della Pro Loco cittadina sotto la lente d\u2019ingrandimento della prof.ssa <\/span><strong style=\"line-height: 1.5;\">Filomena Bloise<\/strong><span style=\"line-height: 1.5;\"> in collaborazione con l\u2019Accademia Pollineana. <\/span><strong style=\"line-height: 1.5;\">La 59\u00aa edizione ha scelto come Focus la Puglia.\u00a0<\/strong><span style=\"line-height: 1.5;\">La Regione Puglia ha dimostrato negli ultimi anni un notevole dinamismo economico e culturale, che l\u2019ha portata a raggiungere risultati inimmaginabili solo fino a qualche anno prima.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong>L\u2019area del Salento ad esempio, \u00e8 diventata una delle mete di vacanza pi\u00f9 visitate dai turisti di tutta Italia e dall\u2019estero.<\/strong> Venerd\u00ec 24 febbraio, con inizio alle ore 10 presso l\u2019Auditorium dell\u2019Istituto Tecnico Commerciale e per Geometri \u201cPitagora Calvosa\u201d di Castrovillari si terr\u00e0 un incontro sul tema: <strong>&#8220;Lo sviluppo del turismo in Puglia, diversit\u00e0 e analogie con il caso calabrese&#8221;.<\/strong> All\u2019importante appuntamento sar\u00e0 presente il Governatore della Puglia <strong>Michele Emiliano.<\/strong> L\u2019incontro mira a capire le ragioni del successo pugliese e a compararlo con la situazione calabrese per cercare di individuare un eventuale percorso di sviluppo turistico adattabile alla Calabria.<\/p>\n<p>&nbsp;<\/p>\n<p>Intanto presso la Galleria d&#8217;Arte <strong>&#8220;Il Coscile&#8221;, diretta da Mimmo Sancineto, \u00e8 in visione la mostra fotografica &#8220;Puglia, luce dei miei occhi&#8221; del fotografo pugliese Domenico Zagaria.<\/strong> La mostra, comprende quaranta scatti che documentano la passione del fotografo per le bellezze della sua regione e sar\u00e0 visitabile fino al 28 Febbraio 2017.\u00a0Ed ancora, per gli eventi culturali, ricordiamo il concorso dal titolo <strong>\u201cPitturiAmo la Puglia\u201d<\/strong>. L\u2019iniziativa \u00e8 finalizzata alla valorizzazione del patrimonio naturale, storico e culturale del territorio di Puglia. Segnaliamo, inoltre, il Concorso a Premi ispirato al <strong>celebre personaggio della tradizione castrovillarese (e calabrese) conosciuto come \u201c \u2018U monachiddu\u201d giunto alla sua V edizione<\/strong> e riservato agli alunni-singolarmente o in gruppo-della quinta Classe della Scuola Primaria e gli studenti delle Classi della Scuola secondaria di primo grado.<\/p>\n<p>&nbsp;<\/p>\n<p>I lavori originali si ispireranno preferibilmente alla leggenda <strong>\u201cStoria di Margherita, figlia di Greg\u00f9ro\u201d dell\u2019autore Antonio Dellisanti<\/strong>, libro consigliato dalla Bibliotecaria di Massafra (TA). In alternativa, saranno gli stessi docenti delle classi a scegliere un autore di libri per ragazzi, rappresentativo della Regione Puglia.\u00a0Per chi volesse sostenere l\u2019evento, lo pu\u00f2 fare attraverso la \u201cLotteria del Carnevale\u201d, sponsorizzata da \u201cPaponetti Gioielleria\u201d di Castrovillari e distribuita dalla nascente delivery agency \u201c Tic Toc\u201d. Il Carnevale \u00e8 organizzato dalla Pro Loco cittadina in collaborazione con la locale Amministrazione Comunale, la Regione Calabria, il Parco Nazionale del Pollino, la BCC Medio Crati di Rende, la Gas Pollino , patrocinata dalla Provincia di Cosenza e sostenuta da numerosi sponsor privati che da anni credono nella manifestazione ed impreziosita dai brand A.C.T. ( Ambiente, Cultura,Turismo) e da \u201c Castrovillari Citt\u00e0 Festival\u201d.<\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"text-decoration: underline;\">APPUNTAMENTI<\/span><\/h2>\n<h3>GIOVEDI\u2019 23 FEBBRAIO<\/h3>\n<p>ore 18.00 Corteo di Re Carnevale<br \/>\nPercorso: Canal Greco, Via Roma, P.zza Municipio.<br \/>\nore 19.00 Contrasto tra Re Carnevale e Quaresima a cura della compagnia teatrale \u201c J Pirrupaini\u201c &#8211; testi di Mena Filpo con Marilena La Polla e Massimo La Falce \u201c &#8211; coreografine di Ass. Cultura C.E.A. di Tilde Nocera e Sar\u00e0 Danza . P.zza Municipio .<br \/>\nOre 19.30 Incoronazione Re Carnevale e consegna delle Chiavi della Citt\u00e0 a cura del<br \/>\nCorteo Storico della Festa della Bandiera e dell\u2019Amministrazione Comunale di<br \/>\nMorano Calabro .<br \/>\nore 20.30 SIRINATA D\u2019A\u2019 SAVUZIZZA<br \/>\nXV Concorso per Serenate Tradizionali \u201cGianni FRANCOMANO\u201d<br \/>\ncon il contributo di \u201cEurospin\u201d &#8211; \u201cCampo Verde\u201d &#8211; \u201cFattorie Covelli\u201d \u2013 Sa.bra \u2013 Panificio Bruno &#8211; Passarelli Punto Legno &#8211; \u201cTic Toc\u201d \u2013 \u201cEdilgarden\u201d \u2013 Tedesco Building\u201d &#8211; PERCORSO: Via A. Alfano, Rione Pantaniddo.<br \/>\nOre 22.00 \u201cCervelliamoci in maschera \u201c Hamingue caf\u00e8.<br \/>\nOre 23.00 Ballo in Maschera con Marco Francomano &#8211; New Eleven Pub<\/p>\n<p>&nbsp;<\/p>\n<h3>VENERDI\u2019 24 FEBBRAIO<\/h3>\n<p>Ore 10.00 FOCUS PUGLIA<br \/>\nIncontro-dibattito, \u201c Lo sviluppo del turismo in Puglia, diversit\u00e0 ed analogie con il caso calabrese\u201d. Auditorium I.T.C.G. \u201cPitagora Calvosa\u201d. A cura dell\u2019Accademia Pollineana\u201d .<br \/>\nOre 20.00 Serata \u201cCALABRIA SONA\u201d con la partecipazione di:<br \/>\nANTONIO GROSSO E KILOMBO QUARTET \u2013 Musica e Jan-sesion Etnica .<br \/>\nVia A. Alfano, Rione Pantaniddo.<br \/>\nOre 20.30 \u201cCena d\u2019autore \u201c<br \/>\nc\/o La Locanda di Alia \u2013 Castrovillari<br \/>\nOre 20.30 \u201cSorriso Terapia\u201d la cura comica Calabrese \u2013 Tour Calabrese Nazione 2017, con la partecipazione di Fabrizio Nardone da \u201cZelig\u201d e Francesco Arno da \u201cMade in Sud\u201d \u2013 Ospite la ballerina Francesca del Toro da \u201cAmici\u201d a cura di AC. Carella Eventi \u2013 Teatro Sibarys &#8211; Prococonvento Francescano .<br \/>\nOre 22.00 \u201cLatino in Maschera \u201c &#8211; Mulino Pub<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La 59\u00aa edizione del Carnevale di Castrovillari ha scelto come Focus la Puglia. Tanti gli appuntamenti\u00a0nei prossimi giorni.<\/p>\n","protected":false},"author":22,"featured_media":75317,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,571,34,28],"tags":[],"class_list":["post-75316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-in-evidenza","category-magazine","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/75316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=75316"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/75316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/75317"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=75316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=75316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=75316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}