{"id":75657,"date":"2017-03-03T08:48:39","date_gmt":"2017-03-03T07:48:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/massoneria-terminate-le-operazioni-di-sequestro-degli-elenchi-per-il-goi-e-guerra-aperta\/"},"modified":"2023-01-16T19:27:56","modified_gmt":"2023-01-16T18:27:56","slug":"140276-massoneria-terminate-le-operazioni-di-sequestro-degli-elenchi-per-il-goi-e-guerra-aperta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/140276-massoneria-terminate-le-operazioni-di-sequestro-degli-elenchi-per-il-goi-e-guerra-aperta\/","title":{"rendered":"Massoneria, terminate le operazioni di sequestro degli elenchi: per il Goi \u00e8 guerra aperta"},"content":{"rendered":"<h4>Il Gran Maestro della loggia Grande Oriente d&#8217;Italia, Stefano Bisi; ha annunciato battaglia contro l&#8217;iniziativa della Commissione Antimafia, relativa al sequestro degli elenchi.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; Ieri mattina s<span class=\"Apple-style-span\">ono terminate, intorno alle 6.30 le perquisizioni dello Scico della Guardia di finanza<\/span>. Le fiamme gialle hanno infatti <strong>sequestrato gli elenchi degli iscritti, dal 1990 a oggi, alle logge di Calabria e Sicilia delle associazioni massoniche <span class=\"Apple-style-span\">Grande Oriente d&#8217;Italia; Gran Loggia Regolare d&#8217;Italia; Serenissima Gran Loggia d&#8217;Italia; Gran Loggia d&#8217;Italia degli Antichi Liberi Accettati Muratori<\/span>.<\/strong> A renderlo noto \u00e8 la stessa\u00a0Commissione antimafia che, dopo un infinito tira e molla, aveva dato mandato delle perquisizioni nelle sedi delle logge massoniche. Le operazioni sono iniziate nelle sedi nazionale alle 15.30 di ieri e si sono protratte per tutta la notte.Il materiale acquisito, sia informatico sia cartaceo \u00e8 <strong>custodito nella sede della polizia giudiziaria.<\/strong> L\u2019attivit\u00e0 d\u2019inchiesta prosegue nelle modalit\u00e0 deliberate dalla Commissione.<\/p>\n<p><span style=\"line-height: 1.5;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-140278 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/03\/Vascello-2-marzo-2017-e1488466252562-800x427-440x235.jpg\" alt=\"Vascello-2-marzo-2017-e1488466252562-800x427\" width=\"348\" height=\"185\" title=\"\">Tale sequestro non \u00e8 andato per nulla gi\u00f9 alla loggia massonica del <strong>Grande Oriente d&#8217;Italia<\/strong>, sin dall&#8217;inizio contraria a fornire gli elenchi. Ed \u00e8 proprio il Gran Maestro a tuonare e rilasciare il primo commento a caldo dopo il sequestro: \u201cCi opporremo &#8211; ha dichiarato <strong>Stefano Bisi<\/strong> &#8211; con tutte le nostre forze all\u2019atto arbitrario di cui siamo stati oggetto\u201d. Queste le sue parole<\/span><span style=\"line-height: 1.5;\">\u00a0nel corso della conferenza stampa tenuta ieri al <\/span><span class=\"Apple-style-span\" style=\"line-height: 1.5;\">Vascello (foto a sinistra).<\/span><span style=\"line-height: 1.5;\">\u00a0<strong>Bisi ha <\/strong><\/span><strong><span class=\"Apple-style-span\" style=\"line-height: 1.5;\">annunciato battaglia<\/span><span style=\"line-height: 1.5;\"> contro l\u2019iniziativa della\u00a0<\/span><span class=\"Apple-style-span\" style=\"line-height: 1.5;\">Commissione Antimafia<\/span><\/strong><span style=\"line-height: 1.5;\">, che ha dato mandato &#8211; su delibera unanime &#8211; allo Scico della Guardia di Finanza di procedere alla <\/span><span class=\"Apple-style-span\" style=\"line-height: 1.5;\">perquisizione della sede nazionale<\/span><span style=\"line-height: 1.5;\"> non solo del <\/span><span class=\"Apple-style-span\" style=\"line-height: 1.5;\">Goi<\/span><span style=\"line-height: 1.5;\"> ma anche di altre <\/span><span class=\"Apple-style-span\" style=\"line-height: 1.5;\">associazioni massoniche<\/span><span style=\"line-height: 1.5;\">, con l\u2019ordine di <\/span><span class=\"Apple-style-span\" style=\"line-height: 1.5;\">sequestrare gli elenchi di tutti i loro iscritti in Calabria e Sicilia<\/span><span style=\"line-height: 1.5;\">.Alla conferenza erano presenti il Gran Maestro Aggiunto <span class=\"Apple-style-span\">Sergio Rosso<\/span> e il Primo Gran Sorvegliante <span class=\"Apple-style-span\">Antonio Seminario<\/span>. Ha partecipato anche <span class=\"Apple-style-span\">Fabio Federico<\/span>, uno degli avvocati del pool incaricato dal Grande Oriente di valutare e promuovere le <span class=\"Apple-style-span\">iniziative necessarie<\/span> per affrontare la situazione in cui si trova l\u2019Istituzione.\u00a0<\/span><\/p>\n<header>\n<h3 class=\"entry-title\"><span style=\"text-decoration: underline;\">Bisi: \u201cTuteleremo il Grande Oriente d\u2019Italia in ogni sede\u201d<\/span><\/h3>\n<\/header>\n<div class=\"entry-content\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-140277 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/03\/Grande-Oriente-dItalia-830x510-440x271.jpg\" alt=\"Grande-Oriente-dItalia-830x510\" width=\"354\" height=\"218\" title=\"\">&#8220;Oggi \u00e8 stata commessa una palese <strong>discriminazione<\/strong> &#8211; si legge in una nota a firma del Gran Maestro Stefano Bisi &#8211; nei confronti di una<strong> Istituzione libera e secolare come la Massoneria<\/strong> e c\u2019\u00e8 stata una grave violazione della democrazia e delle leggi dello Stato. Il sequestro degli elenchi dei liberi muratori del Grande Oriente d\u2019Italia appartenenti alle logge di<strong> Calabria e Sicilia da parte della Commissione Antimafia presieduta dall\u2019onorevole Rosy Bindi, \u00e8\u00a0un atto arbitrario e intimidatorio.<\/strong> Quando il protagonismo politico, mascherato da indagine, prende il sopravvento si finisce per percorrere una strada che porta lontano dalla necessit\u00e0 di capire e che finisce per sconfinare nell\u2019illegalit\u00e0. Si fa solo del sensazionalismo che non serve ad altro che ad alimentare una ingiustificata ed intollerabile <strong>caccia all\u2019uomo e che colpisce migliaia di cittadini perbene iscritti ad una nobile Istituzione.<\/strong> Chi ha riportato indietro le lancette della storia, arrivando a prendere provvedimenti che certi regimi in passato hanno attuato, si assuma oggi le proprie responsabilit\u00e0. Sappia che noi massoni andremo sino in fondo a questa triste pagina che qualcuno ha voluto scrivere\u00a0 a tutti i costi e che abbiamo gi\u00e0 denunciato l\u2019illeicit\u00e0 dell\u2019azione esercitata dalla Commissione. <strong>Il Grande Oriente d\u2019Italia si tuteler\u00e0 in tutte le sedi italiane ed europee<\/strong> perch\u00e9 non vengano intaccati i principi fondamentali del libero pensiero e non venga oscurata una grande fiamma che alimenta la Libert\u00e0 nel nostro Paese. Uniti in catena, con grande forza, coraggio e orgoglio gridiamo ad alta voce: \u201cViva il Grande Oriente d\u2019Italia\u201d.<\/p>\n<\/div>\n<h3 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><\/h3>\n<h3 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><span style=\"text-decoration: underline;\">LEGGI ANCHE:<\/span><\/h3>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/2436\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline; color: #0000ff;\">Massoneria in Calabria, la commissione antimafia dispone sequestro elenchi iscritti<\/span><\/a><\/h2>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/2315\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline; color: #0000ff;\">Ndrangheta e massoneria, rivelati sospetti traffici d\u2019armi e \u2018favori\u2019 elettorali<\/span><\/a><\/h2>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/2307\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline; color: #0000ff;\">Massoneria e cosche, auditi in Antimafia altri tre venerabili Maestri: ancora niente elenchi<\/span><\/a><\/h2>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/2287\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline; color: #0000ff;\">Massoneria e cosche, Gran maestro audito in Antimafia: \u201cNon possiamo consegnare gli elenchi\u201d<\/span><\/a><\/h2>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/2308\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline; color: #0000ff;\">Massoneria, politica e clan: coinvolti un prete, un pentito e una giornalista (ECCO TUTTI I NOMI)<\/span><\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Il Gran Maestro della loggia Grande Oriente d&#8217;Italia, Stefano Bisi; ha annunciato battaglia contro l&#8217;iniziativa della Commissione Antimafia, relativa al sequestro degli elenchi.<\/p>\n","protected":false},"author":22,"featured_media":75658,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,16],"tags":[],"class_list":["post-75657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/75657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=75657"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/75657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/75658"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=75657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=75657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=75657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}