{"id":75712,"date":"2017-03-04T09:22:19","date_gmt":"2017-03-04T08:22:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ucciso-a-colpi-darma-da-fuoco-sparati-anche-al-volto-assassinato-un-commerciante-di-55-anni\/"},"modified":"2023-01-16T19:27:59","modified_gmt":"2023-01-16T18:27:59","slug":"140473-ucciso-a-colpi-darma-da-fuoco-sparati-anche-al-volto-assassinato-un-commerciante-di-55-anni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/140473-ucciso-a-colpi-darma-da-fuoco-sparati-anche-al-volto-assassinato-un-commerciante-di-55-anni\/","title":{"rendered":"Ucciso a colpi d&#8217;arma da fuoco sparati anche al volto, assassinato un commerciante di 55 anni"},"content":{"rendered":"<h4><b>Cruento omicidio\u00a0nel Vibonese dove \u00e8 stato ucciso un uomo di 55 anni, commerciante di pneumatici. Il delitto \u00e8 avvenuto a Gerocarne.<\/b><br \/>\n<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>GEROCARNE (VV) &#8211; Omicidio nelle Preserre vibonesi questa mattina. Con numerosi colpi d&#8217;arma da fuoco su tutto il corpo, di cui uno al volto, \u00e8\u00a0stato ucciso <strong>Domenico Stamb\u00e8, 55 anni<\/strong>, commerciante di pneumatici, gi\u00e0 noto alle forze dell&#8217;ordine.\u00a0L&#8217;omicidio \u00e8\u00a0avvenuto a<strong> Sant&#8217;Angelo di Gerocarne,<\/strong> in contrada Rombol\u00e0,\u00a0in un terreno nei pressi della sua abitazione, delimitato da una recinzione provvista di cancello. Contro il commerciante, secondo quanto \u00e9 emerso dai primi accertamenti, sono stati sparati da distanza ravvicinata alcuni colpi di fucile, uno dei quali lo ha raggiunto al volto con effetti devastanti\u00a0e la morte di Stamb\u00e9 \u00e8\u00a0stata istantanea.<\/p>\n<p>Sul posto per i rilievi e l&#8217;avvio delle indagini i carabinieri della Stazione di Soriano Calabro con il maresciallo, Barbaro Sciacca, ed i militari dell&#8217;Arma del nucleo investigativo di Vibo Valentia con il capitano Valerio Palmieri che stanno tentando di accertare se sia stato lo stesso Stamb\u00e8 ad aprire il cancello della sua propriet\u00e0 all&#8217;assassino o se sia stato quest&#8217;ultimo a forzarlo per introdursi nel terreno. Nel primo caso, infatti, il commerciante potrebbe aver aperto il cancello all&#8217;assassino senza essere colto dal minimo sospetto. Stamb\u00e8 svolgeva anche l&#8217;attivit\u00e0 di autotrasportatore, provvedendo personalmente alla consegna dei pneumatici.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cruento omicidio\u00a0nel Vibonese dove \u00e8 stato ucciso un uomo di 55 anni, commerciante di pneumatici. Il delitto \u00e8 avvenuto a Gerocarne.<\/p>\n","protected":false},"author":22,"featured_media":75713,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-75712","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/75712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=75712"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/75712\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/75713"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=75712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=75712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=75712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}