{"id":75852,"date":"2017-03-07T19:02:24","date_gmt":"2017-03-07T18:02:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/studentesse-aggredite-da-cani-randagi-vicino-al-liceo-telesio-trasportate-in-ospedale\/"},"modified":"2023-01-16T19:28:09","modified_gmt":"2023-01-16T18:28:09","slug":"141163-studentesse-aggredite-da-cani-randagi-vicino-al-liceo-telesio-trasportate-in-ospedale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/141163-studentesse-aggredite-da-cani-randagi-vicino-al-liceo-telesio-trasportate-in-ospedale\/","title":{"rendered":"Studentesse aggredite da cani randagi, vicino al Liceo &#8216;Telesio&#8217;: trasportate in Ospedale"},"content":{"rendered":"<h4 class=\"p1\">Oltre allo shock hanno riportato una serie di escoriazioni e per una delle due la frattura del perone.<\/h4>\n<p><!--more--><\/p>\n<p class=\"p1\">\n<p class=\"p1\">COSENZA &#8211; &#8220;Un grave e triste episodio si \u00e8 verificato ieri nei pressi del Liceo Classico &#8216;Telesio&#8217; di Cosenza ai danni di <strong>due studentesse, E.M. ed M.M. frequentanti la classe I A<\/strong> Cambridge della medesima scuola.&#8221; E&#8217; quanto si legge in una nota dell&#8217;ufficio stampa del Liceo classico, che denuncia l&#8217;aggressione subita dalle studentesse e chiede un intervento immediato da parte delle istituzioni. &#8220;Le due studentesse &#8211; segue la nota &#8211; uscite dall&#8217;istituto al termine delle lezioni, a bordo del loro ciclomotore, si sono viste <strong>aggredite da un branco di cani randagi che da tantissimo tempo vagano nei pressi del Liceo Telesio.\u00a0<\/strong>L&#8217;aggressione ha procurato, oltre logicamente al trauma dovuto all&#8217;enorme spavento, addirittura, anche l<strong>a frattura del perone ad M.M. pi\u00f9 una serie di escoriazioni ed escoriazioni varie ad E.M..<\/strong>\u00a0Le studentesse ferite e sotto shock sono state trasferite presso il nosocomio cittadino dove hanno ricevuto le cure del caso.<\/p>\n<p class=\"p1\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-133034 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/01\/Liceo-Classico-Telesio-Cosenza-440x280.jpg\" alt=\"Liceo Classico Telesio Cosenza\" width=\"244\" height=\"155\" title=\"\">Il Dirigente Scolastico del Liceo Classico &#8216;Telesio&#8217;, ing. <strong>Antonio Iaconianni<\/strong>, preoccupato ed indignato per quanto accaduto ha cos\u00ec commentato: Si tratta di un episodio di eccezionale gravit\u00e0. <strong>Le due povere studentesse coinvolte sono prima ancora che utenza della scuola che dirigo, cittadine della citt\u00e0 di Cosenza e, come tali, come ognuno di noi, hanno il diritto alla sicurezza ed a vivere in luoghi al riparo da simili episodi nati da incuria e superficialit\u00e0.\u00a0<\/strong>Ho personalmente segnato pi\u00f9 volte la presenza di questi pericolosi cani alle autorit\u00e0 competenti &#8211;\u00a0 ha continuato il Dirigente &#8211; ma mai ho avuto risposte concrete: anche da questo nasce la mia indignazione e quella di chi quotidianamente per lavoro o come studenti o genitori si reca presso le nostre strutture.<\/p>\n<p class=\"p1\"><strong>Dopo il gravissimo episodio di ieri<\/strong> &#8211; ha concluso Iaconianni &#8211; <strong>sento il dovere di rivolgere un appello alle istituzioni competenti tutte: che si ponga al pi\u00f9 presto rimedio a questa grave situazione di incuria a tutela dei cittadini cosentini<\/strong> e non solo che quotidianamente frequentano questa parte della citt\u00e0.\u00a0Auspico che da oggi ci siano azioni preventive e non riparatorie a danni estremamente gravi e che, nello specifico, <strong>si tolgano nell&#8217;immediato i cani dalle vicinanze del Telesio e si spostino nelle strutture preposte.\u00a0<\/strong>La cura della cosa pubblica, ognuno per la parte di sua competenza, \u00e8 il pi\u00f9 alto privilegio che la comunit\u00e0 affida ai propri concittadini: che nessuno possa mai venire meno a questo dovere ed essere tacciato di incompetenza e superficialit\u00e0!&#8221;<\/p>\n<p class=\"p1\"><em>Immagine di repertorio<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oltre allo shock hanno riportato una serie di escoriazioni e per una delle due la frattura del perone.<\/p>\n","protected":false},"author":21,"featured_media":75853,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-75852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/75852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=75852"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/75852\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/75853"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=75852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=75852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=75852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}