{"id":75858,"date":"2017-03-08T07:37:04","date_gmt":"2017-03-08T06:37:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/la-lettera-di-serena-giordanelli-aiutatemi-mio-marito-vuole-uccidermi\/"},"modified":"2023-01-16T19:28:09","modified_gmt":"2023-01-16T18:28:09","slug":"141179-la-lettera-di-serena-giordanelli-aiutatemi-mio-marito-vuole-uccidermi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/141179-la-lettera-di-serena-giordanelli-aiutatemi-mio-marito-vuole-uccidermi\/","title":{"rendered":"La lettera di Serena Giordanelli: &#8220;aiutatemi, mio marito vuole uccidermi&#8221;"},"content":{"rendered":"<h4>La drammatica lettera di Serena Giordanelli, insegnante di Cetraro e sorella di Anna Giordanelli, uccisa nel gennaio dello scorso anno a Cetraro. Serena \u00e8 stata costretta a lasciare la Calabria, perch\u00e8 teme per la sua vita e quella dei figli. La sua lettera \u00e8 apparsa sul blog di Concita de Gregorio su Repubblica.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Ad inviare la lettera \u00e8 Serena Giordanelli, insegnante di Cetraro e sorella di Anna Giordanelli, uccisa nel gennaio dello scorso anno a Cetraro. Serena \u00e8 stata costretta a lasciare la Calabria, perch\u00e8 teme per la sua vita e quella dei figli. La sua lettera \u00e8 apparsa sul blog di Concita de Gregorio su Repubblica. Per la sorella di Anna, uccisa a gennaio 2016 mentre faceva jogging nella sua citt\u00e0 dal marito di Serena, \u00e8 in carcere Paolo Di Profio e nella sua cella sarebbe stata trovata una lettera indirizzata a una persona di fiducia di Di Profio: \u201cLei va a camminare la mattina in direzione del porto, basta un colpo secco alla testa, mi raccomando scegli delle persone fidate. Se non l\u2019ammazzi almeno mandala sulla sedia a rotelle, \u00e8 l\u2019unica cosa che pu\u00f2 darmi un po\u2019 di pace\u201d.<br \/>\nSerena oggi vive in Umbria con i due figli insieme ai due figli di 11 e 8 anni, i figli di Di Profio ed ha perch\u00e8 la corte di Assise di Cosenza ha accordato al marito assassino di sua sorella il rito abbreviato: &#8220;Vorrebbero farlo passare per incapace di intendere e di volere. Se mi uccider\u00e0 chi lo spiegher\u00e0 ai miei figli?&#8221;.<\/p>\n<p>Nella lettera Serena Giordanelli racconta il suo matrimonio con Paolo Di Profio, tra l&#8217;alcol e la droga che lui assumeva inizialmente di nascosto. E la sorella di Anna, la spinge a separarsi e a lasciare quell&#8217;uomo che le fa solo del male.<\/p>\n<h3>Questa la lettera pubblicata su Repubblica.it<\/h3>\n<p>&#8220;<em>Mi chiamo Serena Giordanelli, ho due figli di 8 e 11 anni, se scrivo questa lettera \u00e8 perch\u00e9 mio marito non mi ha ancora ammazzata. Ha promesso che lo far\u00e0, ha gi\u00e0 ucciso mia sorella Annalisa il 27 gennaio del 2016: l\u2019ha strangolata e massacrata con un piede di porco perch\u00e9 la considerava colpevole della nostra separazione. Ha confessato, ora \u00e8 in carcere ma vuole uccidere anche me: mi ha scritto che me la far\u00e0 pagare, le guardie hanno trovato nella sua cella una lettera indirizzata a una persona di sua fiducia. Dice: \u201cLei va a camminare la mattina in direzione del porto, basta un colpo secco alla testa, mi raccomando scegli delle persone fidate. Se non l\u2019ammazzi almeno mandala sulla sedia a rotelle, \u00e8 l\u2019unica cosa che pu\u00f2 darmi un po\u2019 di pace\u201d.<\/em><\/p>\n<p><em>Sono laureata in lingue, insegnavo, vivevo in un paese vicino a Cosenza. Ora sono scappata in Umbria coi miei figli, vivo nascosta aiutata dai soldi di mia madre, 85 anni. Ho paura perch\u00e9 la corte di Assise di Cosenza gli ha accordato il rito abbreviato. Vorrebbero farlo passare per incapace di intendere e di volere. Se mi uccider\u00e0 chi lo spiegher\u00e0 ai miei figli?<\/em><\/p>\n<div id=\"attachment_137683\" style=\"width: 407px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-137683\" class=\"wp-image-137683\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/02\/Annalisa-Giordanelli-Paolo-di-Profio.jpg\" alt=\"Annalisa-Giordanelli-Paolo-di-Profio\" width=\"397\" height=\"225\" title=\"\"><p id=\"caption-attachment-137683\" class=\"wp-caption-text\"><em>Annalisa Giordanelli e Paolo Di Profio<\/em><\/p><\/div>\n<p><em>La mia \u00e8 una storia qualunque. Ho sposato Paolo, infermiere anestesista all\u2019Ospedale di Cetraro, nel maggio 2004. Quasi subito mi sono accorta che beveva di nascosto. Ho fatto di tutto per cercare di farlo smettere. Ho sperato che la nascita dei figli lo aiutasse, ma al contrario: ha iniziato a fare uso di sostanze anestetiche (Midazolam) sottratte in reparto. Ho combattuto da sola: per molto tempo non ho rivelato a nessuno la verit\u00e0. Familiari e amici lo conoscevano come un uomo cortese e generoso.<\/em><\/p>\n<p><em>Nel 2012 muore improvvisamente una delle mie tre sorelle e il mio equilibrio vacilla, inizio una psicoterapia. Realizzo come la mia situazione matrimoniale sia insostenibile. Ne parlo con mia sorella Annalisa che, da medico, penso possa aiutare me e magari anche lui. Quando Paolo capisce che ho rivelato il suo \u201csegreto\u201d \u00e8 l\u2019inizio della fine. Mi minaccia di morte davanti ai figli. Inizia a usare cocaina. Mi calunnia in pubblico: dice che lo tradisco e che gli rubo soldi.<\/em><\/p>\n<p><em>Naturalmente \u00e8 falso. E\u2019 lui a rubare 100mila euro in casa di mia madre. Lo denuncio. Nessuna indagine. Frantuma il parabrezza e svita i bulloni della mia auto, le videocamere lo provano. Uccide mia sorella. Dopo due settimane dall\u2019omicidio mi viene bruciata l\u2019auto. I carabinieri pensano che sia qualche esponente della cosca mafiosa del mio paese, ma io so che il mandante \u00e8 lui. Molti, primi fra tutti i suoi familiari, si schierano dalla sua parte contro di me, colpevole di averlo lasciato.<\/em><\/p>\n<p><em>Decido di trasferirmi per proteggere i figli: la pi\u00f9 grande ha capito, anche se non parla. Nell\u2019udienza preliminare, novembre 2016, confessa giustificando l\u2019omicidio come un momento di follia dettato da alcool e cocaina. Chiede il rito abbreviato per ottenere la perizia psichiatrica. La corte di Assise di Cosenza glielo accorda. Resto senza parole. Ha lavorato nella sala operatoria di un ospedale fino alle 14.30 e dopo un\u2019ora ha ucciso. Era pazzo quando lavorava? Quando commissionava per scritto dal carcere il mio omicidio? In nome di mia sorella uccisa, dei suoi due figli orfani, di tutte le donne che ogni giorno vengono ammazzate vi chiedo: aiutateci finch\u00e8 siamo ancora vive, non ci piangete solo da morte<\/em>&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La drammatica lettera di Serena Giordanelli, insegnante di Cetraro e sorella di Anna Giordanelli, uccisa nel gennaio dello scorso anno a Cetraro. Serena \u00e8 stata costretta a lasciare la Calabria, perch\u00e8 teme per la sua vita e quella dei figli. La sua lettera \u00e8 apparsa sul blog di Concita de Gregorio su Repubblica.<\/p>\n","protected":false},"author":22,"featured_media":75859,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-75858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/75858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=75858"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/75858\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/75859"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=75858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=75858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=75858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}