{"id":75882,"date":"2017-03-08T12:23:11","date_gmt":"2017-03-08T11:23:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/aeroporto-sibari-opera-utile-e-realizzabile-via-libera-della-commissione-europea\/"},"modified":"2023-01-16T19:28:11","modified_gmt":"2023-01-16T18:28:11","slug":"141236-aeroporto-sibari-opera-utile-e-realizzabile-via-libera-della-commissione-europea","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/141236-aeroporto-sibari-opera-utile-e-realizzabile-via-libera-della-commissione-europea\/","title":{"rendered":"Aeroporto Sibari: &#8220;opera utile e realizzabile&#8221;, via libera della Commissione Europea"},"content":{"rendered":"<h4><strong>Ok della Commissione Europea. <\/strong>Graziano: &#8220;Insieme alla SS106 \u00e8 opera strategica per la Calabria del Nord-Est&#8221;.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>SIBARI\u00a0(CS) \u2013\u00a0&#8220;Anche l\u2019Europa d\u00e0 l\u2019<strong>ok all\u2019aeroporto della Sibaritide<\/strong>. L\u2019opera, insieme all\u2019auspicato e non pi\u00f9 differibile <strong>ammodernamento della Strada Statale 106,<\/strong> rappresenta lo snodo strategico per lo sviluppo dell\u2019area Nord-Est della Calabria. Serve solo l\u2019impegno concreto da parte della Regione e del territorio ad individuare i fondi necessari alla realizzazione dello Scalo e farlo rientrare nelle appetenze della rete aeroportuale commerciale e turistica nazionale.<strong> Non ci sono veti. E da oggi non ci sono pi\u00f9 nemmeno alibi.<\/strong> Questo grazie al lavoro che, con responsabilit\u00e0, ho portato avanti in Consiglio regionale, facendomi portavoce delle istanze e delle esigenze palesate dall\u2019intero comprensorio della Sibaritide e sostenendo la necessit\u00e0 di inserire lo scalo aeroportuale di Sibari nel nuovo Piano dei trasporti calabrese.&#8221;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-117612 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2016\/10\/giuseppegraziano-440x234.jpg\" alt=\"giuseppe graziano\" width=\"358\" height=\"190\" title=\"\">\u00c8 quanto dichiara, con soddisfazione, il Segretario questore del Consiglio regionale, <strong>Giuseppe Graziano,<\/strong> all\u2019indomani della ratifica senza eccezioni del nuovo PRT (piano regionale dei trasporti) da parte della Commissione Europea. &#8220;L\u2019Aeroporto di Sibari \u2013 dice Graziano \u2013 <strong>\u00e8 un\u2019opera utile e realizzabile. Lo ha ribadito anche la Commissione Europea sostenendo<\/strong>, di fatto, le mie ragioni e quelle dell\u2019intero comprensorio ionico sibarita, recepite dal Governo regionale e dall\u2019Assessore alla Logistica Francesco Russo che ha guidato e coordinato l\u2019elaborazione del Piano. L\u2019Europa \u2013 aggiunge il Segretario questore \u2013 <strong>per la realizzazione del Prt ha messo sul piatto della regione ben 9 miliardi di euro.<\/strong> Una buona cifra, ma che dovr\u00e0 essere investita oculatamente e con virtuosismo se si vorranno realizzare tutte le direttive previste dal Piano. Tra queste proprio lo scalo aeroportuale di Sibari.<\/p>\n<p>Che rappresenta, in realt\u00e0, uno dei pochi elementi innovativi dello strumento di gestione dei trasporti regionale. Il quale, perlopi\u00f9, \u00e8 incentrato sulla riqualificazioni del sistema esistente. <strong>L\u2019aeroporto e l\u2019ammodernamento della Statale 106 nel tratto calabrese rappresentano, invece, l\u2019elemento di novit\u00e0 sul quale puntare.\u00a0<\/strong>\u00c8 allarmante &#8211; a proposito \u2013 la decisione del <strong>Governo di eliminare dal Cipe i fondi per la realizzazione del Megalotto 3 della strada ionica. Uno schiaffo ad un territorio gi\u00e0 privo di servizi per la mobilit\u00e0.<\/strong> Contro il quale \u2013 precisa e scandisce il Consigliere regionale &#8211; serve una reazione forte da parte della Regione Calabria che, tanto pi\u00f9 oggi dopo il via libera senza eccezioni dato dalla Commissione europea al Prt, deve fare la voce grossa sul tavolo del Primo ministro affinch\u00e9 si ristabilisca subito il progetto di ammodernamento della SS106.<\/p>\n<p>Dal canto loro, anche i Sindaci della Sibaritide, in questa vertenza che riguarda l\u2019intera collettivit\u00e0 del comprensorio, devono dimostrare capacit\u00e0 di cooperazione, promuovendo e sostenendo in modo univoco una protesta istituzionale intelligente presso il Governo. Con l\u2019auspicio che si riescano a mettere da parte, nell\u2019interesse di tutti, divergenze e personalismi che purtroppo hanno contribuito a produrre questo ennesimo colpo a <strong>danno del territorio.\u00a0<\/strong>Intanto \u2013 conclude Graziano \u2013 ho gi\u00e0 <strong>presentato un\u2019interrogazione al Presidente Oliverio<\/strong> per sapere quali iniziative intender\u00e0 assumere, nel breve tempo, la Regione Calabria per individuare i fondi e finanziare i lavori di realizzazione dell\u2019aeroporto di Sibari e quali saranno, invece, le iniziative atte ad evitare il blocco dei fondi Cipe destinati alle opere del Megalotto 3 della Statale 106&#8243;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ok della Commissione Europea. Graziano: &#8220;Insieme alla SS106 \u00e8 opera strategica per la Calabria del Nord-Est&#8221;.<\/p>\n","protected":false},"author":22,"featured_media":75883,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-75882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/75882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=75882"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/75882\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/75883"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=75882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=75882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=75882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}