{"id":7594,"date":"2012-11-12T15:11:18","date_gmt":"2012-11-12T14:11:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=7594"},"modified":"2023-01-17T13:40:50","modified_gmt":"2023-01-17T12:40:50","slug":"3171-nel-weekend-hotel-transylvania-fa-il-pieno-al-cinema","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/3171-nel-weekend-hotel-transylvania-fa-il-pieno-al-cinema\/","title":{"rendered":"Nel weekend &#8220;Hotel Transylvania&#8221; fa il pieno al cinema"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>ROMA<\/strong> &#8211; Dracula, Mavis e Jonathan conquistano il box office degli incassi del weekend (da gioved\u00ec 8 a domenica 11 novembre): \u201cHotel Transylvania\u201d ha<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">incassato 2 milioni 416 milioni di euro. Scivola dal primo al secondo posto \u201c007 Skyfall\u201d, di Sam Mendes, con Daniel Craig e Javier Bardem, registrando 2 milioni 327 mila euro. Al terzo posto si piazza \u201cVenuto al mondo\u201d di e con Sergio Castellitto e con Penelope Cruz, che ha ottenuto un milione 434 mila euro. Al quinti posto entra \u201cArgo\u201d, di e con Ben Affleck, realizzando 815 mila euro. Scende al quinto posto \u201cViva l\u2019Italia\u201d, di Massimiliano Bruno, con 661 mila euro. Al sesto posto si trova \u201cRed Lights\u201d, di Rodrigo Cort\u00e9s, con 546 mila euro. Al settimo posto c\u2019\u00e8 \u201cVicini del terzo tipo\u201d, di Akiva Schaffer, con 236 mila euro. All\u2019ottavo posto si trova \u201cGladiatori di Roma\u201d, di Iginio Straffi, con 209 mila euro. Al nono c\u2019\u00e8 \u201cL\u2019era glaciale 4: Continenti alla deriva\u201d, di Steve Martino e Mike Thurmeier, con 188 mila euro. Chiude la top ten \u201cLe belve\u201d, di Oliver Stone, con 178 mila euro. In totale, il botteghino ha incassato 10 milioni 244 milioni di euro, in calo del 31 per cento rispetto al precedente fine settimana. &nbsp; (ilVelino\/AGV)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; Dracula, Mavis e Jonathan conquistano il box office degli incassi del weekend (da gioved\u00ec 8 a domenica 11 novembre): \u201cHotel Transylvania\u201d ha<\/p>\n","protected":false},"author":22,"featured_media":7595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,40,34,5],"tags":[],"class_list":["post-7594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-cultura-spettacolo","category-magazine","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=7594"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7594\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/7595"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=7594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=7594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=7594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}