{"id":76161,"date":"2017-03-15T10:46:34","date_gmt":"2017-03-15T09:46:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/presunto-caso-di-malasanita-52enne-muore-per-un-intervento-di-ernia-del-disco\/"},"modified":"2023-01-16T19:28:30","modified_gmt":"2023-01-16T18:28:30","slug":"142467-presunto-caso-di-malasanita-52enne-muore-per-un-intervento-di-ernia-del-disco","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/142467-presunto-caso-di-malasanita-52enne-muore-per-un-intervento-di-ernia-del-disco\/","title":{"rendered":"Presunto caso di malasanit\u00e0: 52enne muore per un intervento di ernia del disco"},"content":{"rendered":"<h4>I familiari hanno sporto denuncia. A breve sar\u00e0 effettuato l&#8217;esame autoptico sulla salma dell&#8217;uomo.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CROTONE\u00a0&#8211; Un semplice intervento che, invece, ha causato il decesso di un uomo. Ancora un presunto caso di malasanit\u00e0 in Calabria. A perdere la vita <strong>S.T. 52enne di Lamezia Terme,<\/strong> mentre si stava sottoponendo ad <strong>un intervento di ernia del disco nella struttura privata del Marrelli Hospital.<\/strong> Un decesso alquanto strano che ha insospettito i familiari spingendoli a denunciare l&#8217;accaduto ai Carabinieri del Comando di Crotone, che stanno effettuando le indagini del caso.<\/p>\n<p>Nella giornata dello scorso luned\u00ec, il paziente si era recato presso la clinica crotonese per essere sottoposto ad <span class=\"Apple-style-span\">un\u00a0<\/span><span class=\"Apple-style-span\">in<\/span><span class=\"Apple-style-span\">tervento all&#8217;ernia del disco,<\/span> ma qualcosa pare sia andata storta ed <span class=\"Apple-style-span\">\u00e8 morto<\/span><span style=\"line-height: 1.5;\">. <strong>Il magistrato della Procura di Crotone, Alfredo Manca, ha subito disposto il <\/strong><\/span><strong><span class=\"Apple-style-span\" style=\"line-height: 1.5;\">sequestro della cartella<\/span><span style=\"line-height: 1.5;\">. Sul corpo del 52enne sar\u00e0 effettuato a breve <\/span><span class=\"Apple-style-span\" style=\"line-height: 1.5;\">l\u2019esame autoptico<\/span><\/strong><span style=\"line-height: 1.5;\"> che aiuter\u00e0 a far chiarezza sul caso.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I familiari hanno sporto denuncia. A breve sar\u00e0 effettuato l&#8217;esame autoptico sulla salma dell&#8217;uomo.<\/p>\n","protected":false},"author":22,"featured_media":76162,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-76161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/76161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=76161"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/76161\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/76162"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=76161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=76161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=76161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}