{"id":7643,"date":"2012-11-13T10:49:39","date_gmt":"2012-11-13T09:49:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=7643"},"modified":"2023-01-17T13:40:52","modified_gmt":"2023-01-17T12:40:52","slug":"3194-manifestazione-della-cgil-al-liceo-classico-il-14-novembre","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/3194-manifestazione-della-cgil-al-liceo-classico-il-14-novembre\/","title":{"rendered":"Manifestazione della Cgil al Liceo Classico il 14 novembre"},"content":{"rendered":"<p><strong>COSENZA<\/strong> &#8211; Verr\u00e0 messa in scena il 14 novembre 2012 una manifestazione della CGIL a Cosenza, sulla scia di una iniziativa della&nbsp;<span style=\"font-size: 12px; line-height: 18.649999618530273px; background-color: #ffffff;\">Confederazione Europea dei Sindacati, per il lavoro e la solidariet\u00e0 e \u201ccontro l\u2019austerit\u00e0 che nel nostro Paese.<\/span><\/p>\n<p>Tutto partir\u00e0 alle ore 9.30 presso il Liceo Classico &#8220;Bernardino Telesio&#8221;, nell&#8217;Auditorium &#8220;Guarasci&#8221;.<\/p>\n<p>La mattinata si articoler\u00e0 su una serie di interventi di lavoratori e lavoratrici, dopo l&#8217;introduzione del Segretario Generale Giovanni Donato ed il saluto del Presidente di Cosenza Mario Oliviero.<\/p>\n<p>La conclusione della manifestazione sar\u00e0 affidata a Vincenzo Scudieri, Segretario Nazionale della CGIL.<br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; background-color: #ffffff;\" \/><br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; background-color: #ffffff;\"><br \/><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Verr\u00e0 messa in scena il 14 novembre 2012 una manifestazione della CGIL a Cosenza, sulla scia di una iniziativa della&nbsp;Confederazione Europea dei Sindacati, per il lavoro e la solidariet\u00e0 e \u201ccontro l\u2019austerit\u00e0 che nel nostro Paese. Tutto partir\u00e0 alle ore 9.30 presso il Liceo Classico &#8220;Bernardino Telesio&#8221;, nell&#8217;Auditorium &#8220;Guarasci&#8221;. La mattinata si articoler\u00e0 [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":7644,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42,5],"tags":[],"class_list":["post-7643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=7643"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7643\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/7644"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=7643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=7643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=7643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}