{"id":76779,"date":"2017-03-30T04:57:20","date_gmt":"2017-03-30T02:57:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/abusi-sessuali-sulle-figlie-minorenni-arrestato-un-51enne\/"},"modified":"2023-01-16T19:29:10","modified_gmt":"2023-01-16T18:29:10","slug":"145108-abusi-sessuali-sulle-figlie-minorenni-arrestato-un-51enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/145108-abusi-sessuali-sulle-figlie-minorenni-arrestato-un-51enne\/","title":{"rendered":"Stupra le figlie per dieci anni senza che la moglie possa intervenire"},"content":{"rendered":"<h4>Violenze e abusi sessuali tra le mura domestiche sin da quando erano bambine, arrestato cinquantunenne.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>SOVERATO (CZ) &#8211; Vivere con l&#8217;orco in casa. Termina l&#8217;incubo per due ragazze calabresi. Il loro pap\u00e0, un uomo di 51 anni \u00e8 stato arrestato dai carabinieri della Compagnia di Soverato con l&#8217;accusa di violenza sessuale nei confronti di entrambe le figlie. L&#8217;arresto \u00e8 stato disposto dal giudice per le indagini preliminari di Catanzaro, su richiesta della Procura, nei confronti di un netturbino, residente nel comprensorio soveratese. Le indagini sono state avviate dopo una segnalazione al numero di pronto intervento 112, scattata da una telefonata di un conoscente che riferiva di un comportamento anomalo con le piccole. Secondo quanto poi accertato<strong> nel corso delle indagini l&#8217;uomo avrebbe attuato ripetute violenze sessuali, per oltre dieci anni, tra le mura domestiche, nei confronti delle figlie sin da quando erano ancora bambine.<\/strong> La moglie dell&#8217;uomo nonostante le violenze avvenissero sempre in casa, non avrebbe mai potuto far nulla per evitarlo.\u00a0L&#8217;arrestato \u00e9 stato rinchiuso nel carcere di Catanzaro, sottoposto a particolari controlli e tutele per evitare il &#8216;linciaggio&#8217; da parte degli altri detenuti.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Violenze e abusi sessuali tra le mura domestiche sin da quando erano bambine, arrestato cinquantunenne.<\/p>\n","protected":false},"author":22,"featured_media":76780,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-76779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/76779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=76779"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/76779\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/76780"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=76779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=76779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=76779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}