{"id":76859,"date":"2017-03-31T18:42:29","date_gmt":"2017-03-31T16:42:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/soldi-ai-clan-per-le-regionali-2005-8-indagati\/"},"modified":"2023-01-16T19:29:15","modified_gmt":"2023-01-16T18:29:15","slug":"145595-soldi-ai-clan-per-le-regionali-2005-8-indagati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/145595-soldi-ai-clan-per-le-regionali-2005-8-indagati\/","title":{"rendered":"Soldi alle cosche per comprare i voti delle regionali 2005, otto indagati"},"content":{"rendered":"<h4>Voti e accordi con le\u00a0&#8216;ndrine per ottenere una &#8216;poltrona&#8217; nel\u00a0Consiglio regionale della Calabria.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; Patti indicibili siglati a suon di mazzette.\u00a0Soldi ad esponenti delle cosche di &#8216;ndrangheta di Cutro e Lamezia Terme in cambio di sostegno alle elezioni regionale del 3 e 4 aprile 2005. E&#8217; questa l&#8217;accusa emersa dalle indagini condotte dalla Sezione criminalita&#8217; organizzata della Squadra Mobile di Catanzaro che ha provveduto, su disposizione della Procura della Repubblica di Catanzaro, alla notifica del provvedimento di avviso della conclusione delle indagini preliminari.\u00a0Nell&#8217;inchiesta sono finiti Angela De Feo, 56 anni, candidata alle elezioni con il Nuovo Psi; Romolo Villirillo, 39 anni; Vincenzo Bonaddio, 58; Aldo Notarianni, 52; <strong>i collaboratori di giustizia Rosario Cappello, Pasquale Giampa&#8217;, Angelo Torcasio e Saverio Cappello, tutti accusati di scambio elettorale politico mafioso. <\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Secondo le indagini della polizia, grazie anche alle dichiarazioni dei collaboratori di giustizia Gennaro Pulice e Giuseppe Giampa&#8217;, De Feo avrebbe utilizzato <strong>50mila euro per ottenere sostegno elettorale dagli esponenti delle due cosche della provincia di Catanzaro e Crotone.<\/strong>\u00a0I soldi sarebbero stati consegnati nelle mani di Pasquale Giampa&#8217; e sarebbero stati utilizzati grazie anche all&#8217;intermediazione di Romolo Villirillo, componente della cosca Grande Aracri di Cutro. Sarebbe stato lo stesso Giampa&#8217; a ripartire il denaro con gli altri rappresentanti delle cosche. I Cappello, invece, si sarebbero preoccupati di distribuire il materiale elettorale, ricevendo la somma di 5mila euro direttamente da Angela De Feo. Soldi che sarebbero stati poi distribuiti, in tranche da cento euro, ad altri esponenti delle cosche sul territorio.\u00a0Davanti al risultato elettorale negativo, la stessa De Feo si sarebbe rivolta a Villirillo per riottenere indietro il denaro, con quest&#8217;ultimo che avrebbe comunicato la richiesta ad esponenti di spicco della &#8216;ndrangheta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voti e accordi con le\u00a0&#8216;ndrine per ottenere una &#8216;poltrona&#8217; nel\u00a0Consiglio regionale della Calabria.<\/p>\n","protected":false},"author":22,"featured_media":76860,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-76859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/76859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=76859"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/76859\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/76860"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=76859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=76859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=76859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}