{"id":76898,"date":"2017-04-01T19:36:23","date_gmt":"2017-04-01T17:36:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/incidente-tra-due-auto-due-feriti-lievi-trasportati-allannunziata\/"},"modified":"2023-01-16T19:29:18","modified_gmt":"2023-01-16T18:29:18","slug":"145788-incidente-tra-due-auto-due-feriti-lievi-trasportati-allannunziata","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/145788-incidente-tra-due-auto-due-feriti-lievi-trasportati-allannunziata\/","title":{"rendered":"Incidente tra due auto: due feriti lievi, trasportati all&#8217;Annunziata"},"content":{"rendered":"<h4>Lo scontro \u00e8 avvenuto, intorno alle 21:00, su viale Magna Grecia, nei pressi di Castrolibero.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Due auto, una Ford e una Citroen, sono rimaste coinvolte in uno scontro, le cui cause sono ancora in corso di accertamento, avvenuto su viale Magna Grecia, nei pressi di Castrolibero; intorno alle 21:00. Nell&#8217;impatto\u00a0due persone sarebbero rimaste lievemente ferite. Sul posto, immediatamente, il personale del 118, che ha trasportato i feriti per accertamenti all&#8217;ospedale di Cosenza e le forze dell&#8217;ordine, che stanno ricostruendo la dinamica precisa dell&#8217;incidente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo scontro \u00e8 avvenuto, intorno alle 21:00, su viale Magna Grecia, nei pressi di Castrolibero.<\/p>\n","protected":false},"author":22,"featured_media":76899,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,564,42,571],"tags":[],"class_list":["post-76898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-castrolibero","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/76898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=76898"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/76898\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/76899"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=76898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=76898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=76898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}