{"id":77084,"date":"2017-04-06T15:33:47","date_gmt":"2017-04-06T13:33:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-comune-di-castrolibero-dimentica-che-esistono-anche-i-cittadini\/"},"modified":"2023-01-16T19:29:31","modified_gmt":"2023-01-16T18:29:31","slug":"146573-il-comune-di-castrolibero-dimentica-che-esistono-anche-i-cittadini","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/146573-il-comune-di-castrolibero-dimentica-che-esistono-anche-i-cittadini\/","title":{"rendered":"Il Comune di Castrolibero &#8216;dimentica&#8217; che esistono anche i cittadini"},"content":{"rendered":"<h4>Ignorato il problema della disoccupazione mentre l&#8217;amministrazione continua ad indebitarsi sulle spalle dei castroliberesi.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CASTROLIBERO (CS) &#8211; La democrazia \u00e8 sinonimo di libert\u00e0, l\u2019informazione \u00e8 l\u2019affluente necessario affinch\u00e9 una societ\u00e0 democratica viva e prosperi nel rispetto degli altri, in primis i cittadini altrimenti si cade nel totalitarismo e nella bulimia politica. &#8220;<strong>La cittadinanza di Castrolibero, ci domandiamo, &#8211; scrive in una nota l&#8217;Associazione Spazio 18 &#8211; \u00a0sa cosa \u00e8 avvenuto in Consiglio Comunale giorno 31 Marzo 2017?<\/strong> Sa che in quella data \u00e8 stato approvato il bilancio 2017? Conosce i risvolti economici, tributari e politici che possono avvenire dall\u2019approvazione del bilancio comunale 2017? Riteniamo di No. Per questo che scriviamo alla cittadinanza tutta per rimarcare ancora una volta l\u2019assenza di ogni forma democratica nella gestione comunale di Castrolibero e le prospettive nefaste dell\u2019approvazione di tale bilancio preventivo 2017.\u00a0 Ancora una volta, ci\u00f2 lo denunciavamo in precedenza, vi \u00e8 disinteresse pi\u00f9 totale a far conoscere queste cose, dettato anche da un\u2019assenza di informazione sull\u2019attivit\u00e0 alquanto scarsa dell\u2019attuale amministrazione comunale.<\/p>\n<p>&nbsp;<\/p>\n<p>E\u2019 giusto, pertanto, informare come nel corso dell\u2019assise comunale pi\u00f9 che conoscere i numeri del bilancio abbiamo assistito a lezioni filosofico dialettiche, pi\u00f9 che parlare di pressione tributaria abbiamo sentito dire che era, da parte del vero primo cittadino, un bilancio elettorale. In pratica una lezione di filosofia che girava intorno ai problemi inveendo verso lo Stato che elargisce ancora oggi, nonostante le lamentele, al Comune un buon 30% di entrate.\u00a0E\u2019giusto evidenziare come il bilancio gi\u00e0 gravato dall\u2019anno scorso di un mutuo acceso dal Comune di euro 7.200.217 \u00a0frutto di debiti comunali che gravano sulle tasche dei cittadini per ben 230mila euro l\u2019anno. Con l\u2019attuale bilancio, \u00e8 stato previsto un mutuo ulteriore di 550mila euro per bitumazione strade. Ebbene tale mutuo produrr\u00e0 un irrigidimento della spesa ed un ulteriore sforzo da parte dei cittadini. <strong>Tradotto il cittadino dovr\u00e0 pagare anche questo mutuo e l\u2019indebitamento salir\u00e0 quasi ad 8.000.000 di euro. Le tasse pertanto saliranno altro che restano invariate<\/strong>. In un periodo in cui le famiglie stentano, in cui i giovani disoccupati di Castrolibero piangono l\u2019assenza di lavoro, e lamentano promesse mai mantenute questo ulteriore aggravio in un bilancio gi\u00e0 pieno di tasse e tributi \u00e8 l\u2019ennesima botta sui bilanci in rosso dei cittadini.<\/p>\n<p>&nbsp;<\/p>\n<p>E\u2019 stato detto che \u00e8 un bilancio elettorale da parte del vero primo cittadino eppure i cittadini verranno vessati e provati ancora nonostante la carenza dei servizi e il gi\u00e0 violento carico tributario. Ripetiamo servizi non adeguati ai costi. Ebbene questi dati fanno prospettare<strong> un adeguamento verso l\u2019alto della tassazione tributaria oppure prospettano un taglio di servizi in corso dell\u2019anno;<\/strong> sicuramente il bilancio comunale gi\u00e0 irrigidito dalla gestione Greco finir\u00e0 per creare ipotesi di dissesto ed anni bui per il Comune nonostante dicano che viviamo nell\u2019eldorado dopando la realt\u00e0 dei fatti. I fatti sono un indebitamento comunale pari all\u201985% che significa manovre future fatte di lacrime e sangue, altro che bilancio elettorale; facevate bene a fare un bilancio equo e solidale altro che elettorale. Il bilancio cos\u00ec si riverser\u00e0 sui cittadini ignari di subire un ulteriore aggravio grazie al nuovo mutuo e a possibili assunzioni, con il chiaro intento di utilizzare il predetto strumento di programmazione di spesa, non per creare sviluppo, bens\u00ec per fini elettoralistici. Bisognava garantire i servizi efficienti rispettando per\u00f2 la cittadinanza ed assumendosi la responsabilit\u00e0 delle tante crepe amministrative oggi alquanto evidenti in citt\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>La democrazia \u00e8 fatta di confronto sereno e costruttivo. <strong>L\u2019amministrazione si \u00e8 chiusa ed ha chiuso le porte alla cittadinanza salvo aprirle vicino alle elezioni. Non funziona cos\u00ec<\/strong>. La prospettiva oggi \u00e8 il dissesto comunale, tassazioni sempre pi\u00f9 alte e disservizi diffusi il tutto conditi dall\u2019assenza di informazione sulla reale situazione contabile ed economica della Citt\u00e0; nel rispetto dei cittadini siate trasparenti e maggiormente efficienti cos\u00ec come impone la vera filosofia democratica fatta di confronti non di scontri, di libert\u00e0 e di parola. Noi, come Associazione Spazio 18, vista la penuria di informazione e di confronto con i cittadini, ci sentiamo in dovere di vigilare sulla nostra citt\u00e0 e sull\u2019operato di questa amministrazione Comunale che appare impalpabile e assente di fronte ai bisogni della gente. Riteniamo che la misura della sopportazione ormai \u00e8 colma. Se da un lato si registra la depressione del Sindaco ingabbiato da troppa filosofia, dall\u2019altro si registra l\u2019isterismo di una giunta che si prepara alla prossima campagna elettorale pronta a promettere che porter\u00e0 il mare a Castrolibero. Riflettiamo e consideriamo che in gioco c\u2019\u00e8 il futuro della nostra comunit\u00e0&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ignorato il problema della disoccupazione mentre l&#8217;amministrazione continua ad indebitarsi sulle spalle dei castroliberesi.<\/p>\n","protected":false},"author":21,"featured_media":77085,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,565],"tags":[],"class_list":["post-77084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-castrolibero-montalto"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/77084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=77084"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/77084\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/77085"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=77084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=77084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=77084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}