{"id":77189,"date":"2017-04-09T15:34:44","date_gmt":"2017-04-09T13:34:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/anziano-aggredito-in-casa-da-due-donne-e-derubato-e-ricoverato-allannunziata\/"},"modified":"2023-01-16T19:29:37","modified_gmt":"2023-01-16T18:29:37","slug":"146994-anziano-aggredito-in-casa-da-due-donne-e-derubato-e-ricoverato-allannunziata","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/146994-anziano-aggredito-in-casa-da-due-donne-e-derubato-e-ricoverato-allannunziata\/","title":{"rendered":"Anziano aggredito in casa da due donne e derubato, \u00e8 ricoverato all&#8217;Annunziata"},"content":{"rendered":"<h4>Un uomo di 81 anni, pensionato, aggredito e rapinato ieri sera in casa in un stabile in piazza Spirito Santo.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Ad allertare la Polizia sono stati i vicini di casa, dopo aver sentito rumori e lamenti provenire dall&#8217;appartamento del pensionato, che vive da solo. Sul posto si sono precipitati gli agenti della squadra Volante che, entrati nell&#8217;abitazione hanno trovato l&#8217;uomo riverso a terra con diverse ecchimosi e contusioni.<\/p>\n<p>Il povero malcapitato \u00e8 stato soccorso e portato in ospedale. L&#8217;anziano avrebbe poi raccontato di essere stato aggredito e picchiato da due donne, pare di etnia rom. Le due, avrebbero bussato alla sua porta, e una volta aperta avrebbero picchiato e derubato il povero anziano della somma di circa 4 mila euro che aveva in casa. Intanto l&#8217;uomo versa in condizioni critiche in ospedale. La polizia \u00e8 poi tornata nell&#8217;abitazione dell&#8217;81enne per ricostruire meglio la dinamica dei fatti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un uomo di 81 anni, pensionato, aggredito e rapinato ieri sera in casa in un stabile in piazza Spirito Santo.<\/p>\n","protected":false},"author":22,"featured_media":77190,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-77189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/77189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=77189"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/77189\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/77190"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=77189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=77189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=77189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}