{"id":7729,"date":"2012-11-14T09:53:53","date_gmt":"2012-11-14T08:53:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=7729"},"modified":"2023-01-17T13:40:57","modified_gmt":"2023-01-17T12:40:57","slug":"3241-terremoto-ancora-due-scosse-nellarea-del-pollino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/3241-terremoto-ancora-due-scosse-nellarea-del-pollino\/","title":{"rendered":"Terremoto: ancora due scosse nell&#8217;area del Pollino"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>CATANZARO<\/strong> &#8211; Non si attenua lo sciame sismico che sta interessando l&#8217;area del Pollino, tra Calabria e Basilicata, colpita nei giorni scorsi da un terremoto di<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">magnitudo 5. La scorsa notte sono state due le scosse registrate nella zona, alle quali se ne aggiunge una terza nel vicino distretto del Monte Alpi Sirino. Nello specifico, i terremoti si sono verificati alle 3 con magnitudo 2.1 e alle 8,59 (magnitudo 2.2), mentre il Monte Sirino e&#8217; stato interessato da un movimento tellurico alle 10,03 con magnitudo 2. Nessun danno per cose o persone. Una quarta scossa si era verificata ieri sera, alle 23:22, in provincia di Vibo Valentia con una magnitudo di 2.6, senza danni . (Fonte AGI)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Non si attenua lo sciame sismico che sta interessando l&#8217;area del Pollino, tra Calabria e Basilicata, colpita nei giorni scorsi da un terremoto di<\/p>\n","protected":false},"author":22,"featured_media":7730,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17,5],"tags":[],"class_list":["post-7729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=7729"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/7730"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=7729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=7729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=7729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}