{"id":77306,"date":"2017-04-12T13:27:10","date_gmt":"2017-04-12T11:27:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/fotonotizia-zona-industriale-di-rende-una-distesa-di-discariche-abusive\/"},"modified":"2023-01-16T19:29:45","modified_gmt":"2023-01-16T18:29:45","slug":"147524-fotonotizia-zona-industriale-di-rende-una-distesa-di-discariche-abusive","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/147524-fotonotizia-zona-industriale-di-rende-una-distesa-di-discariche-abusive\/","title":{"rendered":"FOTONOTIZIA &#8211; Zona industriale di Rende, una distesa di discariche abusive"},"content":{"rendered":"<h4>Responsabile delle bonifiche \u00e8 Calabra Maceri che ha sede nella stessa area e tra venti giorni avvier\u00e0, nel silenzio assoluto, la raccolta porta a porta.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; Una distesa di discariche abusive accoglie lavoratori e residenti a contrada Lecco. Nell&#8217;area industriale di Rende \u00e8 possibile notare come, in diverse zone, siano presenti rifiuti di ogni genere accatastati al lato della carreggiata. Uno spettacolo poco invitante per un industriale che volesse investire nel rendese e soprattutto per gli abitanti costretti a vivere nel costante disagio, tra i miasmi dei laghi chimici, quelli della Calabra Maceri e la spazzatura abbandonata in ogni dove. <strong>Ad occuparsi del servizio di bonifica dovrebbe <img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-142968 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/03\/Cassonetti1-440x215.jpg\" alt=\"Cassonetti1\" width=\"440\" height=\"215\" title=\"\">essere proprio la Calabra Maceri che, ironia della sorte, ha sede nella zona industriale, per\u00f2 probabilmente fatica a notare ci\u00f2 che succede al di l\u00e0 dei propri cancelli<\/strong>. Su segnalazione di Polizia Municipale o della Rende Servizi l&#8217;azienda che gestisce la raccolta e lo smaltimento dei rifiuti rendesi dovrebbe rimuovere le discariche abusive oltre a ripulire il perimetro che dista 2,50 metri da ogni cassonetto.<\/p>\n<p>&nbsp;<\/p>\n<p>Ma anche in\u00a0questo servizio si registrano numerose inadempienze, soprattutto nelle zone centrali della citt\u00e0 come il Metropolis.<strong> Ormai sembra una tradizione consolidata quello che avviene <img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-147533 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/04\/zona-industriale-rende-8-440x264.jpg\" alt=\"zona-industriale-rende (8)\" width=\"440\" height=\"264\" title=\"\">in via Pertini, tra il centro commerciale e il liceo scientifico Pitagora: ogni sabato i cassonetti vengono dati alle fiamme.<\/strong> Il problema probabilmente tra qualche settimana sar\u00e0 risolto. Dal 2 Maggio infatti la Calabria Maceri avvier\u00e0 la raccolta differenziata porta a porta rimuovendo tutti i cassonetti sul territorio. Un&#8217;operazione di cui a circa venti giorni dal suo lancio non \u00e8 stata data alcuna informazione. I rendesi non sanno nulla e in casa solo i pochi &#8216;privilegiati&#8217; delle periferie hanno ricevuto i mastelli da esporre fuori dalle abitazioni. Per il resto regna il completo silenzio. Fino ad oggi Rende \u00e8 stata utilizzata dai cittadini dei Comuni come Cosenza e Castrolibero, per depositare nei cassonetti di tutto, senza rispettare il vincolo dei giorni della differenziata attiva nei territori in cui risiedono. Da Maggio ci\u00f2 non sar\u00e0 pi\u00f9 possibile. Preoccupa molto la disinformazione della comunit\u00e0 che potrebbe verosimilmente portare ad un aumento esponenziale delle discariche abusive nella citt\u00e0 di Rende.<\/p>\n<p>&nbsp;<\/p>\n<p>[huge_it_gallery id=&#8221;243&#8243;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Responsabile delle bonifiche \u00e8 Calabra Maceri che ha sede nella stessa area e tra venti giorni avvier\u00e0, nel silenzio assoluto, la raccolta porta a porta.<\/p>\n","protected":false},"author":22,"featured_media":77307,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,44],"tags":[],"class_list":["post-77306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/77306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=77306"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/77306\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/77307"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=77306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=77306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=77306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}