{"id":77431,"date":"2017-04-15T11:47:49","date_gmt":"2017-04-15T09:47:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tela-di-ragno-in-manette-37enne-omicida-condannato-allergastolo\/"},"modified":"2023-01-16T19:29:54","modified_gmt":"2023-01-16T18:29:54","slug":"148049-tela-di-ragno-in-manette-37enne-omicida-condannato-allergastolo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/148049-tela-di-ragno-in-manette-37enne-omicida-condannato-allergastolo\/","title":{"rendered":"&#8220;Tela di Ragno&#8221;, in manette 37enne omicida: condannato all&#8217;ergastolo"},"content":{"rendered":"<h4><span style=\"line-height: 1.5;\">Misura applicata nei confronti di Valerio Salvatore Crivello\u00a0condannato all&#8217;ergastolo nel processo sui clan del Cosentino. \u00c8 accusato dell&#8217;omicidio di Pietro Serpa.<\/span><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p><span style=\"line-height: 1.5;\">COSENZA &#8211; I carabinieri del Nucleo investigativo del comando provinciale di Cosenza e Treviso, hanno eseguito l&#8217;applicazione di una misura cautelare in carcere per il <strong>37enne Valerio Salvatore Crivello, condannato in primo grado nel processo &#8220;Tela del ragno&#8221;.<\/strong> Il provvedimento \u00e8 stato emesso dalla Corte di Assise di Cosenza (presidente Giovanni Garofalo a latere la collega Francesca De Vuono), su richiesta della Dda di Catanzaro dopo la condanna all&#8217;ergastolo inflitta lo scorso 29 settembre.<\/span><\/p>\n<p><span style=\"line-height: 1.5;\"><strong>Crivello, infatti, a settembre dell&#8217;anno scorso, con sentenza emessa dalla prima sezione della Corte d&#8217;Assise Bruzia a carico di 14 persone<\/strong> (tutte inserite nelle organizzazioni criminali operanti sul territorio del tirreno cosentino e responsabili a vario titolo di tentati e consumati omicidi, estorsioni, usura, detenzione e porto abusivo di armi, munizioni ed esplosivo), <strong>era stato condannato alla pena dell&#8217;ergastolo poich\u00e8 ritenuto colpevole del reato di omicidio pluriaggravato in danno di Serpa Pietro<\/strong> e del connesso reato di detenzione e porto in luogo pubblico delle armi utilizzate per commettere il delitto.\u00a0<\/span>Crivello \u00e8 stato individuato dai Carabinieri nella provincia di Treviso, dove risultava domiciliare a seguito della scarcerazione, per altri reati, avvenuta nello scorso mese di marzo.<\/p>\n<p><em>Immagine di repertorio<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Misura applicata nei confronti di Valerio Salvatore Crivello\u00a0condannato all&#8217;ergastolo nel processo sui clan del Cosentino. \u00c8 accusato dell&#8217;omicidio di Pietro Serpa.<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-77431","post","type-post","status-publish","format-standard","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/77431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=77431"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/77431\/revisions"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=77431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=77431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=77431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}