{"id":77626,"date":"2017-04-23T19:00:03","date_gmt":"2017-04-23T17:00:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/una-gioiello-di-cavallaro-stende-lakragas-il-cosenza-torna-a-ruggire-al-marulla\/"},"modified":"2023-01-16T19:30:06","modified_gmt":"2023-01-16T18:30:06","slug":"148995-una-gioiello-di-cavallaro-stende-lakragas-il-cosenza-torna-a-ruggire-al-marulla","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/148995-una-gioiello-di-cavallaro-stende-lakragas-il-cosenza-torna-a-ruggire-al-marulla\/","title":{"rendered":"Una punizione gioiello di Cavallaro stende l&#8217;Akragas, Il Cosenza torna a ruggire al Marulla"},"content":{"rendered":"<h4><strong>Partita intensa con occasioni da una parte e dell&#8217;altra e\u00a0<\/strong><strong>decisa a poco pi\u00f9 di 10&#8242; minuti dal termine da una punizione capolavoro di Cavallaro che regala ai rossoblu tre punti fondamentali che significano play-off matematici a due giornate dal termine<\/strong><\/h4>\n<h4><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p><strong>COSENZA<\/strong> &#8211;\u00a0Il Cosenza batte l&#8217;Akragas,<strong> sfata il tab\u00f9 Marulla<\/strong>, conquista\u00a0la <strong>matematica certezza di disputare<\/strong> i<strong>\u00a0play-off<\/strong>\u00a0promozione e risponde ai\u00a0successi di Siracusa e Juve Stabia nella giornata che ha sancito il <strong>ritorno in serie B del Foggia<\/strong>. Vittoria sudata (come prevedibile) e meritata quella dei rossoblu, arrivata al termine di una partita bella e combattuta, con occasioni da entrambe le parti e decisa ad una decina di minuti dalla fine, forse proprio nel peggior momento del Cosenza, da una <strong>punizione capolavoro di Cavallaro<\/strong>, subentrato nel secondo tempo a Statella, che con un <strong>destro morbido e preciso insacca il pallone nel sette dalla destra<\/strong> di un impietrito Pane. Per i siciliani una\u00a0sconfitta amara e pesante, visto che i &#8220;Giganti&#8221; vengono risucchiati\u00a0nuovamente in zona play-out e superati di due punti dal Monopoli che si \u00e8 sbarazzato del Catania con un netto 3 a 0.<\/p>\n<div id=\"attachment_149093\" style=\"width: 637px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-149093\" class=\" wp-image-149093\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/04\/Esultanza-Cosenza.jpg\" alt=\"Foto Marco Belmonte\" width=\"627\" height=\"418\" title=\"\"><p id=\"caption-attachment-149093\" class=\"wp-caption-text\"><em><strong>Foto Marco Belmonte<\/strong><\/em><\/p><\/div>\n<p>Dicevamo di una partite avvincente e giocata su buoni ritmi soprattutto nel primo tempo dove le migliori occasioni sono arrivate per i siciliani sui piedi di Salvemini ma sopratutto di Klaric\u00a0che da ottima posizione spara alle stelle. Ma l&#8217;occasionissima del primi 45&#8242;\u00a0capita al Cosenza e pi\u00f9 precisamente sui piedi di <strong>Letizia<\/strong> che imbeccato da una <strong>perfetta verticalizzazione di D&#8217;Anna<\/strong>\u00a0si presenta tutto solo davanti a Pane ma <strong>il suo destro finisce incredibilmente alto sulla traversa<\/strong>. I rossoblu sfruttano molto la corsia di destra con D&#8217;anna e Corsi, meno quella di Statella, mettendo in area diversi palloni che Baclet e Letizia non concretizzano o sprecano.<\/p>\n<div id=\"attachment_149095\" style=\"width: 612px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-149095\" class=\"wp-image-149095\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/04\/cosenzalecce701.jpg\" alt=\"cosenzalecce701\" width=\"602\" height=\"401\" title=\"\"><p id=\"caption-attachment-149095\" class=\"wp-caption-text\"><em><strong>Foto Marco Belmonte<\/strong><\/em><\/p><\/div>\n<p>Nel <strong>secondo tempo<\/strong> i rossoblu rischiano in avvio di prendere goal, provano a colpire senza successo con due conclusioni di D&#8217;Orazio, ma dopo il 15&#8242; i ritmi calano e nemmeno i cambi di De Angelis (Cavallaro e Mendicino) riescono da dare nuova verve alla sqaudra che gioca si nella met\u00e0 campo avversaria ma sembra sbattere contro il muro dei siciliani che si difendono bene. Di contro, \u00e8 proprio l&#8217;Akragas a\u00a0sfruttare le azioni di contropiede sfiorando\u00a0in almeno un paio di circostanze la rete del\u00a0vantaggio. La partita sembra scemare verso il pareggio e l&#8217;impressione \u00e8 che solo una prodezza possa sbloccare\u00a0il risultato. Prodezza che arriva\u00a0al 78&#8242; con la<strong> punizione di Cavallaro<\/strong> che regala i tre punti al Cosenza che rimane in scia di Siracusa e Juve Stabia quando mancano oramai solo due giornate alla fine del campionato.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/507\" rel=\"attachment wp-att-49952\"><br \/>\n<\/a>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48820 alignnone\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/05\/Logo-Cosenza-Calcio.png\" width=\"132\" height=\"171\" alt=\"\" title=\"\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-49948 alignnone\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/09\/Akragas-Logo.png\" width=\"119\" height=\"171\" alt=\"\" title=\"\"><\/p>\n<p style=\"text-decoration: blink;\"><span style=\"font-family: 'arial black', 'avant garde'; font-size: 18pt;\"><strong style=\"font-size: 18px; line-height: 1;\"><span style=\"font-size: 18pt;\"><span style=\"color: #000000; text-decoration: blink;\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Cosenza \u00a0 &#8211; \u00a0\u00a0<\/span><span style=\"color: #ff0000; text-decoration: blink;\"><span style=\"color: #000000; text-decoration: blink;\">\u00a0Akragas\u00a0<\/span><\/span><\/span><\/strong><\/span><span style=\"color: #ff0000; font-size: 20pt;\"><a target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff0000;\">1\u00a0&#8211;\u00a00<\/span><\/a><\/span><\/p>\n<p style=\"text-decoration: blink;\"><span style=\"font-family: 'arial black', 'avant garde'; font-size: 14pt;\"><strong style=\"font-size: 18px; line-height: 1;\"><span style=\"font-size: 18pt;\"><span style=\"color: #ff0000; text-decoration: blink;\"><span style=\"color: #000000; text-decoration: blink;\"><script type=\"text\/javascript\">\/\/ \nfunction blink_one() { document.getElementById('blink').style.visibility='visible'; setTimeout('blink_two()',1000); } function blink_two() { document.getElementById('blink').style.visibility='hidden'; setTimeout('blink_one()',1000); } blink_one();\n\/\/ <\/script><\/span><\/span><\/span><\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Marcatori<\/strong>: 78&#8242; Cavallaro<\/span><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong><span style=\"color: #0000ff;\">SECONDO\u00a0TEMPO<br \/>\n<\/span><\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>93&#8242; &#8211; FINALE DI GARA.<\/strong> Il Cosenza torna a vincere al Marulla, conquista la matematica certezza dei play-off e risponde ai successi di Siracusa e Juve Stabia\u00a0<strong><br \/>\n90&#8242; &#8211; <\/strong>Ci saranno 3&#8242; minuti di recupero<strong><br \/>\n89&#8242; &#8211; <\/strong>Contropiede del Cosenza. Fa tutto Calamai che arriva la limite ma la sua conclusione \u00e8 debole e finsice fuori<strong><br \/>\n87&#8242;\u00a0&#8211; <\/strong>Cosenza adesso costretto sulla difensiva dal forcing disperato dell&#8217;Akragas<strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354 alignnone\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/Sostituzione.gif\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\">85&#8242;\u00a0&#8211;\u00a0<\/strong>Ultimo cambio nei siciliani. Fuori Caz\u00e8 da Silva, in campo Laveque<strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354 alignnone\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/Sostituzione.gif\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\">82&#8242;\u00a0&#8211;\u00a0<\/strong>L&#8217;Akragas sostituisce Coppola con Cocuzza<strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354 alignnone\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/Sostituzione.gif\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\">81&#8242;\u00a0&#8211;\u00a0<\/strong>Ultimo cambio nel Cosenza. Fuori Letizia e dentro Criaco<strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38926 alignnone\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/03\/Ammonizione.png\" alt=\"Ammonizione\" width=\"18\" height=\"24\" title=\"\">\u00a079&#8242;\u00a0&#8211;<\/strong> Cavallaro si toglie la maglia e si becca il giallo<strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-49956 alignnone\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/09\/Goal2.gif\" alt=\"Goal2\" width=\"150\" height=\"75\" title=\"\">78&#8242;\u00a0&#8211; <span style=\"color: #ff0000;\">GOAL COSENZA con Cavallaro. <span style=\"color: #000000;\">Punizione al limite dell&#8217;area per i rossoblu. Cavallaro di destro pennella un pallone che va a morire nel sette alla destra di Pane che pu\u00f2 solo guardare la rete gonfiarsi<\/span><\/span><br \/>\n69&#8242;\u00a0&#8211; <\/strong>Mendicino di testa, pallone solo spizzicato che Pane blocca con facilit\u00e0<strong><br \/>\n67&#8242;\u00a0&#8211; \u00a0<\/strong>Ancora un&#8217;occasione per gli ospiti. Klaric supera D&#8217;Orazio in velocit\u00e0 e si porta a spasso tutta la difesa del Cosenza, pallone scaricato fuori per Palmiero che prova il destro a giro. Pallone alto di poco<strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354 alignnone\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/Sostituzione.gif\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\">65&#8242;\u00a0&#8211; <\/strong>Secondo cambio per il Cosenza. Mendicino in campo al posto di Baclet<strong><br \/>\n64&#8242;\u00a0&#8211; \u00a0<\/strong>Sventola di Salvemini che fa la barba al palo con il pallone che sibila di pochissimo fuori alla destra di Perina<strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354 alignnone\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/Sostituzione.gif\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\">60&#8242;\u00a0&#8211;\u00a0<\/strong>Primo cambio anche per l&#8217;Akragas. Fuori Rotulo, in campo Russo<strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354 alignnone\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/Sostituzione.gif\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\">60&#8242;\u00a0&#8211;<\/strong> Cambio nel Cosenza. Fuori Statella e dentro Cavallaro<strong><br \/>\n53&#8242;\u00a0&#8211; \u00a0<\/strong>Uno\/due di D&#8217;Orazio che scambia con Statella e va alla conclusione da dentro l&#8217;area, Pane respinge in angolo\u00a0<strong><br \/>\n50&#8242;\u00a0&#8211; <\/strong>\u00a0Replica del Cosenza con una punizione di D&#8217;Orazio dai 20 metri, Pane blocca a terra<strong><br \/>\n47&#8242;\u00a0&#8211; \u00a0<\/strong>Occasionissima per l&#8217;Akragas. Salvemini dalla destra crossa rasoterra, il pallone supera Saracco ma ne Klaric ne Longo riescono ad impattare il pallone in scivolata che attraversa l&#8217;area e si spegne sul fondo<strong><br \/>\n45&#8242;\u00a0&#8211; \u00a0<\/strong>Riprende la gara al Marulla tra Cosenza e Akragas. Nessun cambio nell&#8217;intervallo<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong><span style=\"color: #0000ff;\">PRIMO TEMPO<\/span><\/strong><br \/>\n<\/span><span style=\"color: #000000;\"><strong><br \/>\n47&#8242; &#8211; FINALE DI PRIMO TEMPO. <\/strong>Non c&#8217;\u00e8 recupero, formazioni negli spogliatoi sul nulla di fatto<strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38926 alignnone\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/03\/Ammonizione.png\" alt=\"Ammonizione\" width=\"18\" height=\"24\" title=\"\">\u00a047&#8242;\u00a0&#8211; <\/strong>Ammonito Corsi per aver trattenuto per la maglia Salvemini<strong><br \/>\n45&#8242;\u00a0&#8211; <\/strong>\u00a0Due i minuti di recupero concessi<strong><br \/>\n38&#8242;\u00a0&#8211; \u00a0<\/strong>Punizione dal limite dell&#8217;area per i rossoblu decentrata sulla destra. Batte Letizia a giro, pallone fuori di poco<strong><br \/>\n35&#8242;\u00a0&#8211; \u00a0<\/strong>Angolo battuto dalla destra da Letizia, Baclet si tuffa ma non arriva sul pallone che viene colpito invece da D&#8217;Anna, pallone per\u00f2 debole bloccato da Pane<strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38926 alignnone\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2015\/03\/Ammonizione.png\" alt=\"Ammonizione\" width=\"18\" height=\"24\" title=\"\">\u00a034&#8242;\u00a0&#8211; \u00a0<\/strong>Klaric per fermare D&#8217;Anna lo afferra per la maglia. Cartellino giallo per l&#8217;attaccante siciliano<strong><br \/>\n30&#8242;\u00a0&#8211; \u00a0<\/strong>Calamai per Baclet che di tacco serve Corsi. Botta del terzino rossoblu pallone in curva sud<strong><br \/>\n29&#8242;\u00a0&#8211; <\/strong>\u00a0Cross rasoterra di Corsi per Baclet che in scivolata non arriva sulla sfera, mandata in angolo dalla difesa siciliana<strong><br \/>\n24&#8242;\u00a0&#8211; \u00a0<\/strong>Ranieri verticalizza per Letizia che si presenta tutto solo davanti a Pane, ma l&#8217;attaccante si divora il vantaggio tirando alto. Che occasione per i rossoblu!<strong><br \/>\n20&#8242;\u00a0&#8211; \u00a0<\/strong>Ranieri si fa soffiare ingenuamente la sfera da Salvemini che arriva al limite dell&#8217;area rossoblu e calcia ad incrociare. Il suo rasoterra finisce fuori<strong><br \/>\n18&#8242;\u00a0&#8211; \u00a0<\/strong>Akragas vicinissimo al vantaggio. Salvemini riceve palla al limite e serve in area Klaric che appoggia per l&#8217;accorrente Longo che da due passi tutto solo spara incredibilmente alto<strong><br \/>\n14&#8242;\u00a0&#8211; \u00a0<\/strong>Capovolgimento di fronte. Baclet serve D&#8217;Anna sulla destra che arriva sul fondo e crossa verso\u00a0secondo palo per Letizia che non arriva a colpire di testa per pochissimo<strong><br \/>\n13&#8242;\u00a0&#8211; \u00a0<\/strong>Contropiede dei siciliani. Caz\u00e8 verticalizza per Salvemenini che supera Tedeschi in velocit\u00e0 e viene anticipato da un&#8217;uscita a valanga di Saracco<strong><br \/>\n8&#8242;\u00a0&#8211; \u00a0<\/strong>Akragas in avanti. Cross dalla sinistra di Longo che pesca in area Klaric che prova un&#8217;acrobazia volante, pallone altissimo sulla traversa<strong><br \/>\n3&#8242;\u00a0&#8211;\u00a0\u00a0<\/strong>Cosenza subito al tiro con Calamai che riceve palla, avanza e lascia partire un tiro dai 25 metri, Pane blocca la sfera con un volo plastico alla sua destra<strong><br \/>\n1&#8242; &#8211;<\/strong>\u00a0Si parte, il Cosenza batte il calcio di avvio e da il via alla contesa tra Cosenza e Akragas<\/span><\/p>\n<p><span style=\"color: #000000;\">Le due squadre osservano un minuto di raccoglimento in memoria del ciclista italiano dell&#8217;Astana Michele Scarponi, morto ieri dopo essere stato travolto da un camion mentre si allenava. applausi commossi del Marulla per la scomparsa del ciclista<\/span><\/p>\n<p><span style=\"color: #000000;\">Ecco le due formazioni fare il loro ingresso sul terreno di gioco. Cosenza in campo con la classica maglia \u00a0rossoblu e pantaloncini bianchi. Akragas con maglia a strisce verticali bianche e blu e pantaloncini blu<\/span><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><strong>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>COSENZA CALCIO\u00a0(4-4-2):<\/strong>\u00a0Saracco, Corsi, Tedeschi, Pinna, Ranieri, Calamai, D\u2019Anna, Letizia (81&#8242; Criaco), Statella (60&#8242; Cavallaro), Baclet (65&#8242; Mendicino),\u00a0 D\u2019Orazio<strong><br \/>\nPanchina: <\/strong>Abbatemarco, Blondett, Capece, Criaco, Cavallaro, Meroni, Madrigali, Calamai, Mendicino<strong><br \/>\nAllenatore:\u00a0<\/strong>Stefano De Angelis<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>SS AKRAGAS (3-5-2):<\/strong>\u00a0Pane, Mileto, Riggio,\u00a0Caz\u00e8 Da Silva (87&#8242; Laveque), Palmiero, Coppola (85&#8242; Cocuzza), Rotulo (60&#8242; Russo), Sepe, Longo, Salvemini, Klaric<\/span><br \/>\n<span style=\"color: #000000;\"><strong>Panchina: <\/strong>Addario, Leveque, Russo, Tardo, Cocuzza, Sicurella, Privitera, Petrucci, Minacori<strong><br \/>\nAllenatore:\u00a0<\/strong>Raffaele Di Napoli<strong><br \/>\n<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Arbitro<\/strong>:\u00a0Signor Luigi Carella di Bari<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Assistenti: <\/strong>Signor\u00a0Giuseppe Antonacci di Barletta e signor Sante Selicato di Siena<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Ammoniti<\/strong>:\u00a0Klaric (A)<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Espulsi<\/strong>:<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Angoli<\/strong>: 6-3<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Note<\/strong>:\u00a0Pomeriggio sereno ma ventoso con temperatura fresca. Terreno del Marulla in buone\u00a0condizioni. Presenti 2.017 spettatori di cui 972 paganti + 539 abbonati e 12\u00a0tifosi ospiti, per un incasso di 7.982 \u20ac. In Tribuna B anche 464\u00a0volontari\u00a0rappresentanti di associazioni che si occupano di donazione.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-149104\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/04\/Formazione-Cosenza-1.jpeg\" alt=\"Formazione Cosenza\" width=\"603\" height=\"347\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-149097\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/04\/cosenzalecce301.jpg\" alt=\"cosenzalecce301\" width=\"602\" height=\"401\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-149098\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/04\/cosenzalecce501.jpg\" alt=\"cosenzalecce501\" width=\"605\" height=\"403\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-149118\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/04\/cosenzalecce401.jpg\" alt=\"cosenzalecce401\" width=\"603\" height=\"402\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-149119\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/04\/cosenzalecce601.jpg\" alt=\"cosenzalecce601\" width=\"603\" height=\"402\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-149120\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/04\/cosenzalecce901-1.jpg\" alt=\"cosenzalecce901\" width=\"605\" height=\"403\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-149100\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/04\/cosenzalecce801.jpg\" alt=\"cosenzalecce801\" width=\"614\" height=\"409\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-149102\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/04\/cosenzalecce1001.jpg\" alt=\"cosenzalecce1001\" width=\"611\" height=\"407\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Partita intensa con occasioni da una parte e dell&#8217;altra e\u00a0decisa a poco pi\u00f9 di 10&#8242; minuti dal termine da una punizione capolavoro di Cavallaro che regala ai rossoblu tre punti fondamentali che significano play-off matematici a due giornate dal termine<\/p>\n","protected":false},"author":23,"featured_media":77627,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,20],"tags":[],"class_list":["post-77626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/77626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=77626"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/77626\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/77627"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=77626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=77626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=77626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}