{"id":77667,"date":"2017-04-24T12:54:16","date_gmt":"2017-04-24T10:54:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cetraro-consigliere-quercia-pd-commenta-la-riuscita-dellevento-un-mare-idee\/"},"modified":"2023-01-16T19:30:09","modified_gmt":"2023-01-16T18:30:09","slug":"149198-cetraro-consigliere-quercia-pd-commenta-la-riuscita-dellevento-un-mare-idee","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/149198-cetraro-consigliere-quercia-pd-commenta-la-riuscita-dellevento-un-mare-idee\/","title":{"rendered":"Cetraro, il consigliere Quercia (PD) commenta la riuscita dell\u2019evento \u201cUn mare di idee\u201d"},"content":{"rendered":"<p><strong>Erano presenti, tra gli altri, il Presidente della Regione Mario Oliverio, l\u2019Assessore regionale Federica Roccisano e il Consigliere Regionale Giuseppe Aieta<\/strong><\/p>\n<p><!--more--><\/p>\n<p>Il Consigliere Comunale del Comune di Cetraro<strong> Carmine Quercia<\/strong><strong> (PD)<\/strong>, commenta sull\u2019evento politico <strong>Un mare di idee<\/strong>, tenutisi nei giorni 21, 22 e 23 a Cetraro.<\/p>\n<p>\u201cPer la terza volta \u2013 scrive Quercia \u2013 <strong>Cetraro<\/strong> ha ospitato un evento politico e culturale di portata nazionale, particolarmente coinvolgente e di grande valenza formativa. Sono state splendide giornate che hanno visto lo straordinario protagonismo dei <strong>Giovani Democratici<\/strong>, vera risorsa del nostro partito\u201d.<\/p>\n<p>\u201cUna comunit\u00e0, quella dei <strong>Giovani Democratici<\/strong> che vuole contribuire attivamente ad elaborare proposte, a <strong>produrre idee<\/strong> e vuole entrare in sinergia con le istituzioni con la finalit\u00e0 di agevolare il cambiamento e l\u2019innovazione\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-149200 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/04\/Un-mare-di-idee-2-1-374x280.jpg\" alt=\"Un mare di idee (2)\" width=\"374\" height=\"280\" title=\"\"><\/p>\n<p>Giunta oramai alla terza edizione, l\u2019iniziativa, promossa e organizzata dai <strong>Giovani Democratici<\/strong>, <strong>\u00e8 stata<\/strong> incentrata quest\u2019anno sulle <strong>nuove prospettive di sviluppo<\/strong> volte a ridare slancio alla <strong>Calabria<\/strong><strong>. Vi hanno preso parte <\/strong>diverse personalit\u00e0 politiche di ambito nazionale e locale<strong>, tra cui, <\/strong>il Presidente della Regione <strong>Mario Oliverio<\/strong><strong>, l\u2019Assessore regionale Federica Roccisano<\/strong><strong> e il Consigliere Regionale Giuseppe Aieta<\/strong><strong>.<\/strong><\/p>\n<p>\u00abSono orgoglioso \u2013 continua \u2013 di far parte di questa straordinaria realt\u00e0, che dimostra dinamismo, entusiasmo e voglia di mettersi <strong>#incammino<\/strong> verso traguardi significativi che vanno nella direzione di un profondo rinnovamento e cambiamento\u00bb.<\/p>\n<p>\u00abRingrazio il <strong>Segretario Nazionale Mattia Zunino<\/strong>, che ha contribuito con il suo poderoso e convincente intervento ad impreziosire il dibattito, che ha assunto una notevole qualit\u00e0 culturale. Ringrazio tutti i <strong>Giovani Democratici<\/strong>, in particolare <strong>Anna<\/strong> <strong>Pittelli<\/strong>, <strong>Pasquale<\/strong> <strong>Villella<\/strong>, <strong>Mario<\/strong> <strong>Valente<\/strong> e <strong>Michele Rizzuti<\/strong>&#8230; che hanno sottolineato con la loro presenza e con qualit\u00e0 dei loro interventi la grande valenza politico culturale della nostra tre giorni. Ringrazio il <strong>Partito Democratico<\/strong> che crede nel rinnovamento, che d\u00e0 spazio alle novit\u00e0 ed ai giovani, che contribuisce attivamente alla valorizzazione di iniziative politiche e di formazione, che mette a disposizione dirigenti ed esponenti delle istituzioni a tutti i livelli con la finalit\u00e0 di agevolare il circuito delle idee, la reciprocit\u00e0, la costruzione di una comunit\u00e0 di soggetti pensanti accumunati da valori e ideali\u00bb.<\/p>\n<p>\u00abI <strong>Giovani Democratici <\/strong>\u2013 conclude \u2013 ancora una volta dimostrano attenzione verso la formazione, bussola irrinunciabile per un partito che vuole crescere lungo il solco della buona politica, della qualit\u00e0 e dei valori senza scivolare sul piano inclinato di mediocri contrapposizioni, che non giovano a nessuno, che abbassano il livello del confronto e che creano solo sterili polemiche, fumoso chiacchiericcio, sterili percorsi, fastidiose contrapposizioni individualistiche. <strong>Unmarediidee<\/strong> si \u00e8 mossa nella direzione giusta, senza condizionamenti, senza individualismi e con l\u2019ottica della comunit\u00e0 che vuole crescere insieme\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erano presenti, tra gli altri, il Presidente della Regione Mario Oliverio, l\u2019Assessore regionale Federica Roccisano e il Consigliere Regionale Giuseppe Aieta<\/p>\n","protected":false},"author":33,"featured_media":77668,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-77667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/77667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=77667"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/77667\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/77668"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=77667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=77667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=77667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}