{"id":77905,"date":"2017-05-02T14:09:26","date_gmt":"2017-05-02T12:09:26","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/bottiglie-incendiarie-recapitare-a-due-noti-imprenditori-edili-cosentini\/"},"modified":"2023-01-16T19:30:25","modified_gmt":"2023-01-16T18:30:25","slug":"152153-bottiglie-incendiarie-recapitare-a-due-noti-imprenditori-edili-cosentini","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/152153-bottiglie-incendiarie-recapitare-a-due-noti-imprenditori-edili-cosentini\/","title":{"rendered":"Bottiglie incendiarie e proiettili per due noti imprenditori edili cosentini"},"content":{"rendered":"<h4>Chiaro messaggio intimidatorio in un cantiere a Zumpano con proiettili inesplosi e liquido infiammabile.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; In tutta la Calabria recrudescenza delle intimidazioni subite dagli imprenditori. Sono delle ultime ore i chiari messaggi intimidatori ricevuti da due attivit\u00e0 imprenditoriali del settore edile operanti in provincia di Cosenza di cui sono titolari Pasquale Cundari e Andrea Lo Gullo, dirigenti di Ance (Associazione Nazionale Costruttori Edili) Cosenza. Uno dei due episodi \u00e8 stato registrato ad un cantiere edile di Zumpano alle porte di Cosenza in cui lavora una ditta con sede legale a Rende. I titolari stamattina al loro arrivo <strong>hanno trovato una bottiglia con del liquido incendiario nei pressi dell&#8217;ingresso. Alcuni proiettili vi erano stati attaccati con del nastro adesivo<\/strong>, sul caso indagano i carabinieri. Non \u00e8 la prima volta che l&#8217;azienda si ritrova oggetto di minacce ed atti intimidatori. L&#8217;altro caso si \u00e8 invece verificato in un cantiere del centro storico di Cosenza la scorsa settimana. Anche in questo caso sono stati ritrovati proiettili inesplosi e una bottiglia con liquido infiammabile.<\/p>\n<p>&nbsp;<\/p>\n<p>Solidariet\u00e0 ai colleghi imprenditori, ai dipendenti delle aziende ed ai familiari viene espressa dal mondo associativo da parte del presidente degli industriali calabresi Natale Mazzuca e del numero uno di Ance Cosenza, Giovan Battista Perciaccante. &#8220;Stiamo combattendo una battaglia estenuante. Quasi tutti i giorni &#8211; commenta Natale Mazzuca &#8211; siamo sottoposti a tensioni di varia natura. Il clima di insicurezza che respiriamo ci mortifica come cittadini e come imprenditori e ci sottopone a dure prove. <strong>Questi atti inqualificabili ci sviliscono. Tentano di indebolirci ma non arretreremo.\u00a0<\/strong>Anche noi imprenditori abbiamo bisogno del sostegno della pubblica opinione ed in particolare dello Stato perch\u00e9 faccia sentire la sua presenza, presidiando il territorio e garantendo certezza del diritto.<\/p>\n<p>&nbsp;<\/p>\n<p>E&#8217; un problema che ci riguarda tutti &#8211; sottolinea il presidente di Ance Cosenza Giovan Battista Perciaccante &#8211; perch\u00e9 non riusciremo a crescere e svilupparci se intorno al collo avremo il cappio stretto della cultura criminosa che distrugge quello che di buono si cerca di costruire, con fatica, impegno, sforzi personali e collettivi. Quello che bisogna fare nella direzione della legalit\u00e0 non e&#8217; mai abbastanza e non dobbiamo abbassare la guardia. Occorre denunciare, impegnarsi quotidianamente al fianco delle istituzioni e delle forze dell&#8217;ordine, realizzare iniziative anche nelle scuole dove si iniziano a formare le coscienze&#8221;. <strong>Intanto a Vibo Valentia in queste ore sette colpi di pistola sono stati esplosi all&#8217;indirizzo di un camion di un piccolo imprenditore edile a Vibo Valentia.<\/strong> Il mezzo si trovava parcheggiata sotto casa dell&#8217;impreditore nei pressi del cimitero cittadino. Sul posto per i rilievi e l&#8217;avvio delle indagini si sono portati i carabinieri della locale stazione. Nei giorni scorsi a poca distanza dalla zona era stato incendiato un supermercato.<\/p>\n<p style=\"text-align: right;\">Immagine di repertorio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chiaro messaggio intimidatorio in un cantiere a Zumpano con proiettili inesplosi e liquido infiammabile.<\/p>\n","protected":false},"author":22,"featured_media":77906,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-77905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/77905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=77905"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/77905\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/77906"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=77905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=77905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=77905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}