{"id":77948,"date":"2017-05-03T11:11:09","date_gmt":"2017-05-03T09:11:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/calvizie-secondo-alcuni-studi-la-colpa-e-dei-geni-materni-come-combatterla\/"},"modified":"2023-01-16T19:30:28","modified_gmt":"2023-01-16T18:30:28","slug":"152285-calvizie-secondo-alcuni-studi-la-colpa-e-dei-geni-materni-come-combatterla","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/152285-calvizie-secondo-alcuni-studi-la-colpa-e-dei-geni-materni-come-combatterla\/","title":{"rendered":"Calvizie, secondo alcuni studi la colpa \u00e8 dei geni materni: come combatterla"},"content":{"rendered":"<h4><strong style=\"line-height: 1.5;\"><span style=\"line-height: 1.5;\">Secondo la ricerca condotta dall\u2019Universit\u00e0 di Edimburgo, la calvizie sarebbe causata dai marcatori genetici contenuti <\/span><\/strong><span style=\"color: #000000;\"><span style=\"line-height: 1.5;\">all\u2019interno del cromosoma X<\/span><span style=\"line-height: 1.5;\">,<\/span><\/span><strong style=\"line-height: 1.5;\"><span style=\"line-height: 1.5;\"> dunque da parte di madre.<\/span><\/strong><\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p><strong style=\"line-height: 1.5;\"><span style=\"line-height: 1.5;\">La calvizie deriva dai geni materni: come combatterla<\/span><\/strong><\/p>\n<p><span style=\"line-height: 1.5;\">Quando si parla di problemi che possono minare gravemente la nostra autostima, sia al maschile che al femminile, ecco che la calvizie rappresenta uno dei pi\u00f9 problematici. La caduta prematura dei capelli, infatti, pu\u00f2 causare una condizione psicologica tale da impedirci di vivere con giustezza la nostra socialit\u00e0, proprio perch\u00e9 il look \u2013 da sempre considerato molto importante sia nel lavoro che nella vita di tutti i giorni \u2013 ne risente in modo pesante e ci spinge a dubitare di noi stessi. Viste le implicazioni in ballo, dunque, potrebbe essere molto interessante capire come combatterla e avere pi\u00f9 informazioni a riguardo dei fattori scatenanti della calvizie.<\/span><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Calvizie: secondo alcuni studi la colpa \u00e8 dei geni materni<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-152286 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/05\/Cromosomi.png\" alt=\"Cromosomi\" width=\"202\" height=\"162\" title=\"\">Secondo la ricerca condotta dall\u2019Universit\u00e0 di Edimburgo, la calvizie sarebbe causata dai marcatori genetici contenuti <span style=\"text-decoration: underline; color: #0000ff;\"><strong><a style=\"color: #0000ff; text-decoration: underline;\" href=\"https:\/\/quicosenza.it\/news\/2718\" target=\"_blank\" rel=\"noopener\">all\u2019interno del cromosoma X<\/a><\/strong><\/span>, dunque da parte di madre. Si tratta di uno studio che \u2013 nel caso venisse confermato \u2013 riuscirebbe finalmente a fare un po\u2019 di luce sui fattori genetici che provocano la caduta dei capelli, e che oggi rappresentano ancora un mistero. Ma sulla base di quali dati l\u2019universit\u00e0 scozzese \u00e8 giunta alle suddette conclusioni? Lo studio \u00e8 riuscito ad individuare circa 120 geni nel cromosoma X condivisi dai tantissimi pazienti sofferenti di calvizie presentatisi ai test.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Come prevenire e combattere la calvizie?<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-152287 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/05\/Giuliani-440x269.png\" alt=\"Giuliani\" width=\"263\" height=\"160\" title=\"\">Premesso che solo il tempo ci dir\u00e0 della bont\u00e0 delle sperimentazioni sul cromosoma X, esistono attualmente diversi modi per prevenire e curare la calvizie. Ad esempio, i rimedi naturali rappresentano un\u2019ottima strategia per contrastare la caduta dei capelli: rimedi biologici come gli impasti a base di polpa e succo di avocado, insieme agli oli naturali come quelli a base di aloe vera, si dimostrano utilissimi per combattere la calvizie. Cos\u00ec come una dieta a base di zenzero: un alimento che aiuta i bulbi piliferi chiusi a riaprirsi e a rimettersi in attivit\u00e0. Ma il modo migliore per contrastare la caduta dei capelli<span style=\"text-decoration: underline; color: #0000ff;\"><strong> <a style=\"color: #0000ff; text-decoration: underline;\" href=\"https:\/\/quicosenza.it\/news\/2719\" target=\"_blank\" rel=\"noopener\">sono i prodotti tricologici di Giuliani Pharma<\/a><\/strong>,<\/span> pi\u00f9 veloci e mirati alla risoluzione diretta del problema.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Come capire se si soffre di calvizie?<\/strong><\/p>\n<p>Innanzitutto la caduta dei capelli non \u00e8 di per s\u00e9 indicatore di calvizie: quando invece porta alla graduale recessione della chioma, mostrando sempre pi\u00f9 sezioni prive di capelli, allora in quel caso \u00e8 molto probabile che la calvizie abbia cominciato a manifestarsi. Inoltre, si parla di questa patologia anche quando la perdita dei capelli coincide con lo stress, dato che la calvizie trova nelle condizioni psicologiche una delle sue cause principali. Infine, spesso e volentieri la calvizie \u00e8 una condizione che colpisce l\u2019organismo a causa degli sbalzi ormonali: ci\u00f2 accade sia alle donne, in periodi quali la gravidanza, sia agli uomini.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Secondo la ricerca condotta dall\u2019Universit\u00e0 di Edimburgo, la calvizie sarebbe causata dai marcatori genetici contenuti all\u2019interno del cromosoma X, dunque da parte di madre.<\/p>\n","protected":false},"author":22,"featured_media":77949,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,34,52],"tags":[],"class_list":["post-77948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-magazine","category-salute-bellezza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/77948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=77948"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/77948\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/77949"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=77948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=77948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=77948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}