{"id":77960,"date":"2017-05-04T06:18:39","date_gmt":"2017-05-04T04:18:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/spacciatrice-fermata-al-droga-party-di-via-popilia-trovata-con-un-chilo-di-marijuana\/"},"modified":"2023-01-16T19:30:30","modified_gmt":"2023-01-16T18:30:30","slug":"152324-spacciatrice-fermata-al-droga-party-di-via-popilia-trovata-con-un-chilo-di-marijuana","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/152324-spacciatrice-fermata-al-droga-party-di-via-popilia-trovata-con-un-chilo-di-marijuana\/","title":{"rendered":"Spacciatrice fermata al &#8216;droga party&#8217; di via Popilia, trovata con un chilo di marijuana"},"content":{"rendered":"<h4>Era tra le persone scoperte in un appartamento del secondo lotto di via Popilia, dove era in corso un vero e proprio droga party. I carabinieri di Cosenza l&#8217;hanno arrestata<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; Una giovane cosentina di<strong> 26 anni, Luisa Barbieri,<\/strong> fermata mercoled\u00ec scorso nell&#8217;appartamento di via Popilia dove era in corso una sorta di droga Party, \u00e8 stata nuovamente arrestata dai carabinieri di Cosenza, per aver violato la misura cautelare dell&#8217;obbligo di dimora, che le era stato imposto, spostandosi nel territorio di Rende. La giovane infatti, \u00e8 stata seguita fino ad un&#8217;abitazione di Rende dove \u00e8 stata sorpresa insieme ad un&#8217;altra ragazza ma soprattutto in possesso di un chilogrammo di marijuana. Per l&#8217;altra giovane non sono stati presi, al momento, provvedimenti in mancanza di elementi indiziari. Proseguono invece le indagini sulla giovane per capire da dove provenga tutta quella marijuana.<\/p>\n<p>&nbsp;<\/p>\n<h3>LEGGI ANCHE <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/2720\" target=\"_blank\" rel=\"noopener\">Appartamento dello sballo scoperto a Cosenza: due arresti e sequestrati chili di droga<\/a><\/span><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Era tra le persone scoperte in un appartamento del secondo lotto di via Popilia, dove era in corso un vero e proprio droga party. I carabinieri di Cosenza l&#8217;hanno arrestata<\/p>\n","protected":false},"author":22,"featured_media":77961,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-77960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/77960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=77960"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/77960\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/77961"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=77960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=77960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=77960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}