{"id":78005,"date":"2017-05-04T17:52:40","date_gmt":"2017-05-04T15:52:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/metro-cosenza\/"},"modified":"2023-01-16T19:30:32","modified_gmt":"2023-01-16T18:30:32","slug":"152484-metro-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/152484-metro-cosenza\/","title":{"rendered":"La Metrotramvia Cosenza &#8211; Unical, un progetto tecnologicamente arretrato"},"content":{"rendered":"<h4>Fantasiosa l&#8217;ipotesi che a viaggiare sulla metro da 160 milioni di euro saranno 48mila passeggeri, paganti, al giorno.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; &#8220;Che la citt\u00e0 di Cosenza e l\u2019intera Area urbana abbiano bisogno di un sistema di trasporto collettivo adeguato alle necessit\u00e0 dei cittadini e che sia sostenibile dal punto di vista ambientale ed economico \u00e8 un\u2019esigenza avvertita da tutti i residenti e non solo dagli amministratori della cosa pubblica. La querelle che oggi vede contrapposti alcune associazioni di liberi cittadini come, appunto, il Comitato No Metro, che si oppongono alla realizzazione della Metrotranvia Cosenza\/Unical, contrariet\u00e0 condivisa anche dall\u2019USB, trova fondamento sulla vetust\u00e0 del progetto. Solo in Calabria &#8211; scrive il sindacato USB di Cosenza &#8211; si poteva progettare una Metropolitana che<strong> ha i binari delle due direzioni che non scorrono parallelamente, che ha un tratto a binario unico e quindi incroci, che \u00e8 superato per le tecnologie che esso propon<\/strong>e, che produce la deturpazione dell\u2019assetto urbanistico e viario nei comuni dove dovr\u00e0 sorgere, in particolare in territorio di Rende a differenza di quanto avviene in altri contesti europei, e che a priori tutti i favorevoli alla sua realizzazione sono consapevoli della sua insostenibilit\u00e0 economica. Un\u2019assurdit\u00e0 che solo una classe politica come quella calabrese pu\u00f2 valutare come un\u2019opera strategica.<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\nCi troviamo quindi, davanti ad un\u2019opera inutile poich\u00e9 il progetto, invariato rispetto a quello originale per quanto riguarda il business plan che l\u2019ha accompagnato e che ha convinto la UE ad approvare il progetto, prevede, a r\u00e9gime,<strong> un\u2019utenza giornaliera di 48.000 persone che rappresenta il numero ideale di utenti per garantire la sostenibilit\u00e0 economica.<\/strong> In sostanza, il 50% dei residenti nell\u2019Area urbana dovr\u00e0 utilizzare ogni giorno la Metro. Citt\u00e0 che hanno realizzato infrastrutture simili la media residenti\/utenti non supera il 6%. Come \u00e8 facile capire si tratta di numeri irrealizzabili se consideriamo che la popolazione residente nell\u2019Area urbana continua a diminuire anche in ragione delle inadeguate politiche del lavoro e di sviluppo del territorio e nonostante ci\u00f2 Oliverio non trova di meglio che imporre alla citt\u00e0 un\u2019opera che sar\u00e0 devastante accettando il gioco al rialzo del sindaco. Una mega opera, inutile i cui costi ricadranno sulle generazioni future non solo per la sua insostenibilit\u00e0 che ne determiner\u00e0 la chiusura, ma, soprattutto, perch\u00e9 si sperperano, allegramente, oltre 160 milioni di euro di fondi comunitari che potrebbero veramente segnare una svolta decisiva per la crescita economica e sociale dei territori se impiegati nella realizzazione di un sistema di mobilit\u00e0 moderno ed ecosostenibile.<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\nNoi siamo per un progetto serio e per un sistema di mobilit\u00e0 che dia le risposte ai residenti, che allo stesso tempo s\u2019integri con un piano di sviluppo e valorizzazione del territorio. Abbiamo proposto una valida alternativa chiamando alla sua progettazione qualificati e riconosciuti professionisti di livello mondiale del settore che oltre ad avere un costo iniziale di molto inferiore, \u00e8 sostenibile economicamente per un bacino d\u2019utenza come quello dell\u2019Area urbana, e completamente elettrico e alimentato con energie rinnovabili e molto pi\u00f9 flessibile rispetto ad una infrastruttura ferroviaria come, appunto, la Metrotranvia. <strong>Dispiace che il sindaco Occhiuto, che sbaglia a cedere per avere risorse compensative per realizzare una serie di interventi per la riqualificazione urbana tra le quali salviamo il solo parco urbano<\/strong>, si accinga a sottoscrivere l\u2019Accordo di programma quadro nonostante sia consapevole che la Metrotranvia non solo non risolve i problemi della mobilit\u00e0 ma porta con se diversi limiti di compatibilit\u00e0 ambientale ed economica.<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\nIn questo disastro annunciato gioca un ruolo importante un presidente della Regione Calabria Oliverio, fuori dal tempo e assolutamente non preparato tanto da postulare che la Metrotranvia diventer\u00e0 la dorsale del trasporto collettivo nell\u2019Area urbana e che risolver\u00e0 il problema della mobilit\u00e0 cittadina nonostante lo stesso progetto faccia emergere che non ne ha le caratteristiche con <strong>una capacit\u00e0 di solo 1500 utenti l\u2019ora massima trasportabile e velocit\u00e0 commerciale\/tempi di percorrenza di oltre quaranta minuti- tempi che aumenteranno con le modifiche richieste dal sindaco Occhiuto.<\/strong> Ci sono insomma 160 mln di ragioni per dire no e crediamo che alla fine sia giusto che a decidere siano i cittadini anche in ragione dei palesi errori di programmazione e governo del territorio che gli amministratori ci hanno regalato in questi ultimi decenni. I cittadini, ne siamo convinti, spesso hanno dimostrato di essere molto pi\u00f9 lungimiranti rispetto a coloro che a cui hanno conferito mandato per amministrarli. Ne sa qualcosa il governo Renzi&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fantasiosa l&#8217;ipotesi che a viaggiare sulla metro da 160 milioni di euro saranno 48mila passeggeri, paganti, al giorno.<\/p>\n","protected":false},"author":21,"featured_media":78006,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-78005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/78005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=78005"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/78005\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/78006"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=78005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=78005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=78005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}