{"id":7815,"date":"2012-11-15T11:36:37","date_gmt":"2012-11-15T10:36:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=7815"},"modified":"2023-01-17T13:41:02","modified_gmt":"2023-01-17T12:41:02","slug":"3287-gli-studenti-dell-unical-incontrano-il-vescovo-di-locri","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/3287-gli-studenti-dell-unical-incontrano-il-vescovo-di-locri\/","title":{"rendered":"Gli studenti dell&#8217; Unical incontrano il Vescovo di Locri"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>RENDE<\/strong> &#8211; Marted\u00ec 27 novembre, alle 17 e 30, il Vescovo di Locri incontrer\u00e0 gli studenti dell&#8217;Universit\u00e0 della Calabria, nella Cappella Universitaria (cubo 23 B). L&#8217;evento rappresenta<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">una sorta di cammino spirituale vuoluto da un gruppo di studenti della Locride.&nbsp;<\/p>\n<p style=\"text-align: justify;\">Questo evento vedr\u00e0, quindi, la partecipazione di Sua Eccellenza Mons.Fiorini Morosini, vescovo di Locri-Gerace.\u00abLa nostra speranza &#8211; informano gli organizzatori &#8211;&nbsp; \u00e8 quella di costituire un gruppo di Studenti Cattolici &#8211; Ma ci\u00f2 non vorr\u00e0 dire chiusura a quanti hanno fatto o vogliono fare altre scelte di vita. Il dialogo \u00e8 sempre un fattore che ci fa crescere e non ci fa correre il rischio di chiuderci nelle&nbsp; nostre vedute\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Marted\u00ec 27 novembre, alle 17 e 30, il Vescovo di Locri incontrer\u00e0 gli studenti dell&#8217;Universit\u00e0 della Calabria, nella Cappella Universitaria (cubo 23 B). L&#8217;evento rappresenta<\/p>\n","protected":false},"author":22,"featured_media":7816,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,5,44],"tags":[],"class_list":["post-7815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-old","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=7815"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7815\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/7816"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=7815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=7815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=7815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}