{"id":78435,"date":"2017-05-15T09:42:23","date_gmt":"2017-05-15T07:42:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ndrangheta-operazione-jonny-richieste-le-dimissioni-di-alfano\/"},"modified":"2023-01-16T19:31:00","modified_gmt":"2023-01-16T18:31:00","slug":"154422-ndrangheta-operazione-jonny-richieste-le-dimissioni-di-alfano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/154422-ndrangheta-operazione-jonny-richieste-le-dimissioni-di-alfano\/","title":{"rendered":"&#8216;Ndrangheta, Operazione &#8220;Jonny&#8221;: richieste le dimissioni di Alfano"},"content":{"rendered":"<h4>Ministro Alfano incontr\u00f2 Sacco nel 2011,<strong>\u00a0imprenditore che gestiva oltre al centro pi\u00f9 grande d&#8217;Europa a Isola Capo Rizzuto anche quello di Lampedusa.<\/strong><\/h4>\n<h4><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA\u00a0&#8211; &#8220;Dopo i 68 arresti per &#8216;ndrangheta legati al business migranti nel centro di accoglienza di Isola Capo Rizzuto, ad Alfano non rimane che una sola cosa, rassegnare le dimissioni da ministro&#8221;. Lo dichiarano i capigruppo M5S di Camera e Senato <strong>Roberto Fico e Carlo Martelli<\/strong> insieme al senatore M5S della commissione antimafia <strong>Mario Michele Giarrusso.<\/strong> &#8220;Le stesse dimissioni &#8211; sottolineano &#8211; che chiedemmo lo scorso 13 febbraio, quando usc\u00ec un articolo del giornalista <span style=\"text-decoration: underline; color: #0000ff;\"><a style=\"color: #0000ff; text-decoration: underline;\" href=\"https:\/\/quicosenza.it\/news\/2767\" target=\"_blank\" rel=\"noopener\">Tizian su L&#8217;Espresso<\/a><\/span> che ricostru\u00ec come il ministro degli interni<strong> Alfano nulla si accorse sull&#8217;imprenditore Leonardo Sacco (arrestato nell&#8217;operazione odierna dei ROS)<\/strong>, che gi\u00e0 dal 2007 era sospettato dagli investigatori del ROS di <strong>essere vicino al clan della &#8216;ndrangheta degli Arena di Capo Rizzuto<\/strong>. Nonostante questi rapporti del ROS, il ministro Alfano incontr\u00f2 Sacco nel 2011, parliamo di <strong>un imprenditore che gestiva oltre al centro pi\u00f9 grande d&#8217;Europa a Isola Capo Rizzuto anche quello di Lampedusa<\/strong>&#8221; concludono gli esponenti M5S.<\/p>\n<h3><\/h3>\n<h3><b style=\"line-height: 1.5;\">Meloni, Alfano riferisca su rapporti con &#8216;Misericordia&#8217;\u00a0<\/b><\/h3>\n<p>&#8220;Basta con questo schifo! <strong>Mandiamo a casa questo Governo complice degli scafisti e di chi lucra sui disperati.<\/strong> Chiediamo al ministro Alfano di riferire immediatamente sui suoi rapporti con uno degli arrestati, vicepresidente della &#8216;Misericordia&#8217;, che gestiva milioni di euro destinati all&#8217;accoglienza, presente al congresso del suo partito quando lui era ministro dell&#8217;Interno&#8221;. Lo scrive su Facebook il presidente di Fratelli d&#8217;Italia, <strong>Giorgia Meloni<\/strong> commentando la notizia sulla cosca della &#8216;ndrangheta smantellata nell&#8217;operazione di stamane che &#8220;faceva <strong>affari sull&#8217;accoglienza dei profughi<\/strong>&#8220;. Meloni sottolinea infatti, come &#8220;Insieme ai mafiosi\u00a0\u00e8\u00a0stato arrestato un <strong>manager della &#8216;Misericordia&#8217;, struttura vicina ai partiti di Governo.<\/strong> C&#8217;\u00e8 altro da dire? Gli sbarchi servono solo ai mafiosi, ai ladri, ai truffatori per rubare con il benestare dei partiti della maggioranza&#8221;.<\/p>\n<h3><\/h3>\n<h3><b>Scotto (Mdp), mafie fanno affari su migranti non le ong <\/b><\/h3>\n<p>&#8220;L&#8217;inchiesta di Catanzaro conferma che sono <strong>le mafie a fare affari con i migranti e non le ong che salvano le vite<\/strong>. Qualcuno chieda scusa&#8221;: cos\u00ec su twitter il deputato di Movimento democratico e progressista <strong>Arturo Scotto.<\/strong><\/p>\n<h3><\/h3>\n<h3><span style=\"line-height: 1.5;\">Commissariata Misericordia Isola Capo Rizzuto e della Federazione Regionale Calabrese<\/span><\/h3>\n<p><span style=\"line-height: 1.5;\">&#8220;Abbiamo appreso con forte preoccupazione del fermo di Don Edoardo Scordio e di Leonardo Sacco, rispettivamente Correttore e Governatore della Misericordia di Isola Capo Rizzuto. Otto secoli di storia non vengono cancellati da fatti, seppure presunti, cos\u00ec gravi e pesanti. Continueremo a dare le risposte ai cittadini ed alla popolazione pi\u00f9 debole, dando continuit\u00e0 ai servizi svolti dalla Misericordia non facendo mancare la risposta ai bisogni di assistenza e di carita&#8217;&#8221;. Cos\u00ec, in una nota, la <strong>Confederazione Nazionale delle Misericordie d&#8217;Italia<\/strong> &#8211; che ha la sua sede a Firenze &#8211; interviene sull&#8217;inchiesta giudiziaria che coinvolge la Confraternita di Isola Capo Rizzuto per collusioni con la &#8216;ndrangheta negli appalti del Centro di accoglienza dei richiedenti asilo. &#8220;Confermiamo la nostra totale fiducia nell&#8217;operato dell&#8217;Autorit<\/span><span style=\"line-height: 1.5;\">\u00e0\u00a0<\/span><span style=\"line-height: 1.5;\">Giudiziaria &#8211; aggiunge la nota &#8211; auspicando una rapida conclusione delle indagini. <strong>Annunciamo gi<\/strong><\/span><strong><span style=\"line-height: 1.5;\">\u00e0<\/span><\/strong><span style=\"line-height: 1.5;\"><strong> da adesso il commissariamento della Misericordia di Isola Capo Rizzuto e della Federazione Regionale Calabrese.<\/strong> Peraltro la gestione del centro di Isola Capo Rizzuto \u00e8\u00a0da tempo affidata al consorzio &#8220;Opere di Misericordia&#8221;, con sede a Firenze, che continuer\u00e0 i propri compiti nell&#8217;interesse degli ospiti secondo i principi che ci contraddistinguono&#8221;. Dal pomeriggio di oggi il consigliere nazionale della Confederazione, <strong>Alberto Corsinovi<\/strong>, sar\u00e0 ad Isola Capo Rizzuto per seguire personalmente gli sviluppi della vicenda.<\/span><\/p>\n<h3 class=\"p1\"><\/h3>\n<h3 class=\"p1\">Ferrara (M5S),\u00a0accoglienza a Crotone mai stata trasparente<\/h3>\n<p class=\"p1\">&#8220;Dalla mia visita ispettiva del 2014 subito dopo l\u2019insediamento al Parlamento europeo, emersero tutte le criticit\u00e0 e le anomalie rispetto al modus operandi dell\u2019ente gestore, le Misericordie del Governatore Leonardo Sacco. <strong>Nessun tipo di trasparenza sui contratti e le convenzioni, difficili da reperire anche dopo espresse richieste alla Prefettura<\/strong>&#8220;. Cos\u00ec l&#8217;europarlamentare 5stelle <strong>Laura Ferrara,<\/strong> che gi\u00e0 tre anni fa ispezion\u00f2 il Cara di Isola Capo Rizzuto oggi al centro della cronaca per gli arresti di stamattina. &#8220;Questa situazione &#8211; prosegue Ferrara &#8211; e le condizioni miserabili in cui vivevano gli oltre 1500 ospiti, mi spinsero a presentare un<strong> esposto alla Procura di Catanzaro<\/strong> oltre ad essere oggetto di diverse inchieste giornalistiche. Nonostante tutto c\u2019era chi diceva che andava tutto bene, fra questi <strong>Matteo Salvini che dopo la sua visita al Sant\u2019Anna si compliment\u00f2 proprio con Sacco<\/strong>, con tanto di foto ricordo, per il buon lavoro svolto. L\u2019inchiesta Johnny \u00e8 il frutto di questo &#8216;buon lavoro&#8217;. <strong>I clan si erano impossessati del centro, per anni migliaia di richiedenti asilo hanno vissuto in condizioni disumane e nello stesso tempo i portafogli dei soliti si sono ampiamente ingrossati.<\/strong> Nel frattempo i nostri politici hanno continuato a fare orecchie da mercante e relegare la questione accoglienza a sterili e ipocriti dibattiti nei comodi salotti televisivi&#8221;.<\/p>\n<h3>Bindi, contro clan Arena importante operazione<\/h3>\n<p>&#8220;L&#8217;imponente operazione contro il clan Arena, coordinata dalla DDA di Catanzaro, \u00e8\u00a0un importante risultato nella lotta contro la &#8216;ndrangheta e le infiltrazioni mafiose nella gestione dei migranti&#8221;. Lo ha dichiarato l&#8217;on. <strong>Rosy Bindi<\/strong>, Presidente Commissione Antimafia.\u00a0&#8220;<strong>Il Cara di Isola Capo Rizzuto, era diventato una miniera di denaro per la cosca, che grazie alla complicit\u00e0 del responsabile dell&#8217;ente che gestiva il centro<\/strong>, gi\u00e0\u00a0vicepresidente delle Misericordie, controllava &#8211; continua la Bindi -appalti e forniture dirottando nelle casse della famiglia i fondi comunitari destinati ai profughi. <strong>Sull&#8217;opacit\u00e0\u00a0della gestione del Cara in provincia di Crotone, aveva aperto un&#8217;inchiesta anche la nostra Commissione<\/strong>. Questa vicenda conferma la capacit\u00e0\u00a0delle mafie di sfruttare le debolezze e le fragilit\u00e0 del nostro tempo con un approccio predatorio e parassitario. La tragedia dei migranti \u00e8\u00a0anche un vergognoso volano di corruzione, come gi\u00e0 rivelato da Mafia Capitale, che va perseguita e stroncata con estremo determinazione. Gli arresti di oggi sono &#8211; ha concluso &#8211; il coronamento di un&#8217;accurata indagine dei Ros, che ha permesso di ricostruire i molteplici affari della famiglia e il ruolo di cerniera con la pubblica amministrazione svolto dal responsabile del centro. Ringrazio il Procuratore Nicola Gratteri e gli uomini dei Carabinieri della Polizia e della Guardia di Finanza di Catanzaro e Crotone che condotto l&#8217;operazione e sequestrato beni e societ\u00e0 riconducibili agi Arena&#8221;.<\/p>\n<p><em>Fonte foto L&#8217;Espresso<\/em><\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><span style=\"text-decoration: underline;\">LEGGI QUI:<\/span><\/h3>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/2768\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline; color: #0000ff;\">\u2018Ndrangheta: le mani del clan Arena anche sull\u2019accoglienza dei migranti, tra i fermati don Edoardo Scordio (NOMI E VIDEO)<\/span><\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Ministro Alfano incontr\u00f2 Sacco nel 2011,\u00a0imprenditore che gestiva oltre al centro pi\u00f9 grande d&#8217;Europa a Isola Capo Rizzuto anche quello di Lampedusa.<\/p>\n","protected":false},"author":22,"featured_media":78436,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-78435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/78435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=78435"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/78435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/78436"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=78435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=78435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=78435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}