{"id":78558,"date":"2017-05-18T06:43:45","date_gmt":"2017-05-18T04:43:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ordigno-esplode-sotto-unauto-in-un-quartiere-rom-lauto-e-di-un-ragazzo\/"},"modified":"2023-01-16T19:31:09","modified_gmt":"2023-01-16T18:31:09","slug":"154916-ordigno-esplode-sotto-unauto-in-un-quartiere-rom-lauto-e-di-un-ragazzo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/154916-ordigno-esplode-sotto-unauto-in-un-quartiere-rom-lauto-e-di-un-ragazzo\/","title":{"rendered":"Ordigno esplode sotto un&#8217;auto in un quartiere rom, distrutti i vetri di alcune abitazioni"},"content":{"rendered":"<h4>Un\u2019esplosione si \u00e8 verificata ieri sera poco dopo le 21.00. Distrutti i vetri di alcune abitazioni ma, per fortuna, nessun ferito<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>LAMEZIA TERME &#8211; L&#8217;esplosione \u00e8 avvenuta nel quartiere Savutano. Un ordigno a basso potenziale sarebbe stato posizionato sotto l&#8217;automobile di un ragazzo, una Toyota Yarsi, che si trovava parcheggiata sotto la sua abitazione nei pressi di alcuni palazzi popolari, dove abitano in prevalenza nuclei familiari di etnia rom. L&#8217;esplosione avvenuta ieri sera non ha provocato feriti ma danni, perch\u00e8 i vetri di alcune abitazioni sono andati distrutti e ovviamente la Yaris ha subito ingenti danni. Sul posto sono intervenuti gli agenti del Commissariato di Lamezia Terme per i rilievi del caso insieme ai vigili del fuoco. Il giovane proprietario dell&#8217;auto risulta avere piccoli precedenti ed abita nel quartiere Savutano.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\"><em>Foto: calabrianews<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un\u2019esplosione si \u00e8 verificata ieri sera poco dopo le 21.00. Distrutti i vetri di alcune abitazioni ma, per fortuna, nessun ferito<\/p>\n","protected":false},"author":22,"featured_media":78559,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-78558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/78558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=78558"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/78558\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/78559"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=78558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=78558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=78558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}