{"id":78807,"date":"2017-05-25T06:00:59","date_gmt":"2017-05-25T04:00:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-un-seminario-dieta-salute-restrizione-calorica\/"},"modified":"2023-01-16T19:31:25","modified_gmt":"2023-01-16T18:31:25","slug":"155997-cosenza-un-seminario-dieta-salute-restrizione-calorica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/155997-cosenza-un-seminario-dieta-salute-restrizione-calorica\/","title":{"rendered":"A Cosenza un seminario su dieta, salute e restrizione calorica"},"content":{"rendered":"<h4>Il seminario, promosso dall&#8217;Universit\u00e0 di Tor Vergata con la partecipazione dell&#8217;Unical, mira a fare luce sui diversi aspetti della restrizione calorica per il suo utilizzo nella nutrizione clinica.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Il Seminario &#8220;Dieta, salute e longevit\u00e0: restrizione calorica, quale opzione terapeutica?&#8221; si svolger\u00e0 domani, alle 14,00, presso la Sala Convegni di Palazzo Lucchetta (sede Ordine dei Medici &#8211; Cosenza). La restrizione calorica serve non solo a ridurre il peso corporeo (che rappresenta il primo obiettivo per cui \u00e8 stata proposta) ma sembra anche rallentare l&#8217;<strong>invecchiamento cellulare<\/strong> in quanto agisce su una serie di processi o di molecole ad esso associati. Diversi trial clinici hanno dimostrato che la restrizione calorica \u00e8 in grado di <strong>allungare\u00a0la vita<\/strong> fino al 30%. Ma la quasi totalit\u00e0 degli esperimenti che prevedono un taglio delle calorie quotidiane di almeno un terzo rispetto al normale \u00e8 stata condotta negli ultimi decenni sugli animali da laboratorio. Trovare un regime alimentare altrettanto efficace che vada bene anche per gli uomini \u00e8 l&#8217;ultima sfida per i biologi dell&#8217;invecchiamento.<\/p>\n<p>&nbsp;<\/p>\n<p>Il Prof. Antonino De Lorenzo, Ordinario di Scienza dell&#8217;Alimentazione Universit\u00e0 degli Studi di Roma Tor Vergata spiegher\u00e0 come sia possibile adattare ai nostri gusti e alla nostra societ\u00e0 una dieta nata nei laboratori e studiata per agire sui gruppi di geni che accelerano o decelerano i processi di invecchiamento. Il Biologo Ennio Avolio, Patologo Clinico e ricercatore presso il Dipartimento DiBEST dell&#8217;Unical sottolineer\u00e0 con quali meccanismi si innesta la spirale che collega <strong>obesit\u00e0 e cervello<\/strong>. &#8220;Il grasso libera delle sostanze e molte di queste arrivano al cervello. Fino a qualche anno fa, si riteneva che quello adiposo fosse solo un tessuto di riserva su cui contare in condizione di riduzione calorica. In concreto, alcune sostanze come la leptina danno segnali di saziet\u00e0, altre come le citochine provocano una <strong>neuroinfiammazione<\/strong> che, a sua volta, pu\u00f2 generare disturbi cognitivi e del comportamento&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il seminario, promosso dall&#8217;Universit\u00e0 di Tor Vergata con la partecipazione dell&#8217;Unical, mira a fare luce sui diversi aspetti della restrizione calorica per il suo utilizzo nella nutrizione clinica.<\/p>\n","protected":false},"author":22,"featured_media":78808,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[34,52],"tags":[],"class_list":["post-78807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","category-salute-bellezza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/78807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=78807"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/78807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/78808"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=78807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=78807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=78807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}