{"id":78868,"date":"2017-05-26T04:30:59","date_gmt":"2017-05-26T02:30:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/oltre-duecento-coristi-spezzano-albanese-flos-carmeli\/"},"modified":"2023-01-16T19:31:30","modified_gmt":"2023-01-16T18:31:30","slug":"156202-oltre-duecento-coristi-spezzano-albanese-flos-carmeli","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/156202-oltre-duecento-coristi-spezzano-albanese-flos-carmeli\/","title":{"rendered":"Oltre duecento coristi a Spezzano Albanese per il &#8221;Flos Carmeli&#8221;"},"content":{"rendered":"<h4>Tutto pronto per la rassegna corale &#8220;Flos Carmeli&#8221; che si terr\u00e0 domani, presso la chiesa del Carmine di Spezzano Albanese, a partire dalle 21,00.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SPEZZANO ALBANESE (CS) &#8211; La cittadina arb\u00ebreshe sar\u00e0 letteralmente invasa da oltre <strong>200 coristi<\/strong> che si ritroveranno per una vera e propria <strong>maratona<\/strong> <strong>di musica corale.<\/strong> Sono tredici, infatti, le formazioni canore che si confronteranno sulle note di repertori che spaziano dal gospel al classico, passando per un mix di sonorit\u00e0 provenienti da tutte le parti del mondo, con particolare attenzione anche per la<strong> musica arb\u00ebreshe e bizantina.<\/strong> Particolarmente soddisfatti il parroco don Fiorenzo De Simone e il suo vice don Emanuele Tagliaferro per la massiccia partecipazione, affermano: &#8220;La manifestazione ha il chiaro intento di celebrare la figura della <strong>Madonna del Carmine<\/strong>, creando occasioni di confronto, scambio e arricchimento culturale fra le diverse comunit\u00e0. Per tali ragioni l&#8217;evento rappresenta un pretesto importante per far conoscere alcuni aspetti peculiari del mondo Arb\u00ebresh, con lo scopo di mantenere viva e valorizzare una cultura e una tradizione plurisecolare&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Fondamentale \u00e8 stata ancora una volta la collaborazione dell&#8217;associazione spezzanese<strong> &#8220;Voci di Pace&#8221;<\/strong> il cui coro, diretto da<strong> Emanuele Armentano<\/strong>, sar\u00e0 fra i protagonisti della serata assieme a:<strong> &#8220;Cantus Vitae&#8221; di Cosenza<\/strong> diretto dal M\u00b0 Giuseppina Conti, Corale &#8220;Ss. Pietro e Paolo&#8221; di Spezzano diretta da Emiliana Oriolo, &#8220;Nova Vox Aurea&#8221; di Castrovillari diretto dal M\u00b0 Agnese Bellini, &#8220;Fughe Armoniche&#8221; di Corigliano Calabro diretto dal M\u00b0 Alfonso Ponte, Corale Madonna delle Grazie di Spezzano diretta da Savina Montone, &#8220;Black&amp;White Gospel Choir&#8221; di Cassano Jonio diretto dal M\u00b0 Maria Risol\u00e8, &#8220;Sofioti Cantores&#8221; di Santa Sofia d&#8217;Epiro diretto dal M\u00b0 Daniela Bifano, &#8220;Corale citt\u00e0 di Rossano&#8221; e &#8220;Santa Cecilia di Mirto diretti dal M\u00b0 Nino Sicilia, Corale &#8220;Anastasis&#8221; di Spezzano diretta da Antonio Gattabria, &#8220;Fenice Ensemble&#8221; di Cassano Jonio diretto dal M\u00b0 Mauro Aluigi, e Corale &#8220;S. Maria del Carmine&#8221; di Spezzano diretta da Mirko Valente. Per l&#8217;occasione \u00e8 stato indetto anche un <strong>concorso fotografico<\/strong> che premier\u00e0 la foto del coro pi\u00f9 simpatica e pi\u00f9 apprezzata dal web sulla pagina facebook ufficiale del Flos Carmeli.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tutto pronto per la rassegna corale &#8220;Flos Carmeli&#8221; che si terr\u00e0 domani, presso la chiesa del Carmine di Spezzano Albanese, a partire dalle 21,00.<\/p>\n","protected":false},"author":22,"featured_media":78869,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,34],"tags":[],"class_list":["post-78868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/78868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=78868"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/78868\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/78869"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=78868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=78868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=78868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}