{"id":79014,"date":"2017-05-28T11:10:09","date_gmt":"2017-05-28T09:10:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/videointervista-quicosenza-re-della-risata-italiana-neri-parenti\/"},"modified":"2023-01-16T19:31:41","modified_gmt":"2023-01-16T18:31:41","slug":"156952-videointervista-quicosenza-re-della-risata-italiana-neri-parenti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/156952-videointervista-quicosenza-re-della-risata-italiana-neri-parenti\/","title":{"rendered":"VIDEOINTERVISTA &#8211; Quattro chiacchiere con il &#8220;Re della risata italiana&#8221; Neri Parenti"},"content":{"rendered":"<h4>Nuovo appuntamento con i grandi nomi del cinema italiano ieri in Calabria. Ad Acri dopo Andrea Roncato, Loredana Cannata e Carlo Verdone, \u00e8 stato il turno di Neri Parenti.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ACRI (CS) &#8211; Parenti, regista e sceneggiatore italiano tra i pi\u00f9 apprezzati all&#8217;interno della cinematografia italiana, \u00e8 il &#8220;fondatore&#8221; della commedia pi\u00f9 viscerale, fantozziana e natalizia, tra i &#8220;padri&#8221; del <strong>cinepanettone<\/strong>, direttore di pellicole che per molti anni sono stati ai vertici delle classifiche per &#8220;visualizzazioni&#8221;, sempre primi ai botteghini del nostro bel Paese.<\/p>\n<p>Laureato in Scienze politiche, ha poi deciso di dedicarsi al cinema e molti registi, a partire da Pasquale Festa Campanile, lo prendono come loro allievo e aiuto. Ha collaborato con Steno (pap\u00e0 di Carlo ed Enrico Vanzina), con gli stessi Vanzina, Giorgio Capitani e molti altri. Il deus ex machine della commedia nostrana \u00e8 stato ospite del quarto appuntamento del <strong>CineIncontriamoci<\/strong>, il format ideato dal giovane artista-producer Mattia Scaramuzzo, che sta accogliendo diverse star del cinema italiano sul territorio acrese, mirando a far di Acri una vera e propria location cinematografica.<\/p>\n<p><strong>Neri Parenti<\/strong> ieri ha incontrato gli studenti delle scuole superiori, mentre la sera ricever\u00e0 un premio per la sua lunga e proficua carriera. <strong>Luca Le Piane\u00a0ha fatto quattro chiacchiere con il regista\u00a0<\/strong>in esclusiva per <strong>Quicosenza.it<\/strong><\/p>\n<h3><span style=\"color: #ff0000;\">GUARDA L&#8217;INTERVISTA ESCLUSIVA<\/span><\/h3>\n<p><iframe loading=\"lazy\" title=\"Luca Le Piane intervista Neri Parenti\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/NVrky2Y2WDc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuovo appuntamento con i grandi nomi del cinema italiano ieri in Calabria. Ad Acri dopo Andrea Roncato, Loredana Cannata e Carlo Verdone, \u00e8 stato il turno di Neri Parenti.<\/p>\n","protected":false},"author":22,"featured_media":79015,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-79014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/79014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=79014"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/79014\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/79015"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=79014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=79014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=79014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}