{"id":79026,"date":"2017-05-29T04:18:38","date_gmt":"2017-05-29T02:18:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/francesco-primo-papa-social-oggi-la-presentazione-del-volume\/"},"modified":"2023-01-16T19:31:41","modified_gmt":"2023-01-16T18:31:41","slug":"156989-francesco-primo-papa-social-oggi-la-presentazione-del-volume","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/156989-francesco-primo-papa-social-oggi-la-presentazione-del-volume\/","title":{"rendered":"\u201cBuonasera. Francesco, il primo papa social\u201d, oggi la presentazione del volume"},"content":{"rendered":"<h4>Sar\u00e0 presentato oggi alle 18,30 nei locali del Centro socio-educativo &#8220;L\u2019Arcobaleno&#8221; di San Marco Argentano il nuovo libro curato da Antonio Modaffari, \u201cBuonasera. Francesco, il primo papa social\u201d, edito dalla casa editrice cosentina Progetto 2000.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SAN MARCO ARGENTANO (CS) &#8211; &#8220;L&#8217;idea del libro nasce dopo il tour di appuntamenti del mio primo libro su Giovanni Paolo II. Ho avuto l\u2019onore &#8211; ha dichiarato lo stesso autore, Modafferi &#8211; di fare molte presentazioni, di incontrare tanta gente. Migliaia di persone innamorate di Wojtyla, ma allo stesso tempo, curiose di sapere le differenze tra il papa polacco e quello argentino\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-156990 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/05\/libro-papa.jpg\" alt=\"libro-papa\" width=\"309\" height=\"458\" title=\"\">\u201cPartendo da questa domanda \u2013 ha aggiunto &#8211; ho sviluppato il mio lavoro che si \u00e8 arricchito riga dopo riga di spunti interessanti; ne \u00e8 venuto fuori un quadro a dir poco incredibile sul pontificato di papa Francesco, sulle sue azioni e sul suo linguaggio che, forse ancora non abbiamo capito, ma gi\u00e0 influisce, tanto, nel nostro quotidiano. Bergoglio, come Wojtyla, ha iniziato a rivoluzionare il mondo gi\u00e0 pochi secondi dopo essere stato eletto e lo ha fatto con un semplice &#8220;buonasera&#8221; pronunciato dal loggione di piazza San Pietro\u201d.<\/p>\n<p>\u201cHo voluto fortemente che la prima presentazione si svolgesse presso il Centro &#8220;L\u2019Arcobaleno&#8221; di San Marco Argentano \u2013 conclude Modaffari \u2013 perch\u00e9 il mio intento \u00e8 quello di trasformare la presentazione del libro in una festa per i ragazzi dell\u2019Associazione Fa.Di.A e per gli operatori che svolgono un lavoro prezioso. Ringraziare per la collaborazione il sindaco del mio paese, Virginia Mariotti e la Presidente dell\u2019Associazione Fa.Di.A. Silvana Chiappetta&#8221;.<\/p>\n<p>L\u2019editore Demetrio Guzzardi ha voluto questo testo che va ad arricchire le sue pubblicazioni di argomento religioso: &#8220;Sono grato a Modaffari per questo suo nuovo lavoro, che contribuisce a far conoscere una figura come quella di Bergoglio, che \u00e8 avvertita da tutti come un papa riformatore. Abbiamo bisogno di figure valoriali e papa Francesco rappresenta una grande speranza per chi ha cuore il destino dell\u2019umanit\u00e0&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sar\u00e0 presentato oggi alle 18,30 nei locali del Centro socio-educativo &#8220;L\u2019Arcobaleno&#8221; di San Marco Argentano il nuovo libro curato da Antonio Modaffari, \u201cBuonasera. Francesco, il primo papa social\u201d, edito dalla casa editrice cosentina Progetto 2000.<\/p>\n","protected":false},"author":22,"featured_media":79027,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[25],"tags":[],"class_list":["post-79026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-libri"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/79026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=79026"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/79026\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/79027"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=79026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=79026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=79026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}