{"id":7925,"date":"2012-11-16T16:25:08","date_gmt":"2012-11-16T15:25:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=7925"},"modified":"2023-01-17T13:41:10","modified_gmt":"2023-01-17T12:41:10","slug":"3347-si-schianta-al-suolo-38enne-reggino-in-nuova-zelanda","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/3347-si-schianta-al-suolo-38enne-reggino-in-nuova-zelanda\/","title":{"rendered":"Si schianta al suolo 38enne reggino in Nuova Zelanda"},"content":{"rendered":"<div style=\"text-align: left;\"><strong>WANAKA (NUOVA ZELANDA)<\/strong> &#8211; Un ex dipendente dell&#8217;Azienda ospedaliera universitaria pisana e&#8217; morto precipitando con il suo paracadute a Wanaka, in Nuova<\/div>\n<p>  <!--more-->  <\/p>\n<div style=\"text-align: left;\">Zelanda, ieri durante una sessione di lanci di paracadutismo sportivo. Antonino Arilotta, 38 anni, originario di Reggio&nbsp;Calabria&nbsp;ma a lungo vissuto a Pisa, si e&#8217; schiantato al suolo durante la pratica di questo sport. La notizia viene riportata dal quotidiano The New Zealand Herald. La vittima, un informatico, per 14 anni ha lavorato nell&#8217;Unita&#8217; operativa di Reti e tecnologie (ora passata sotto l&#8217;Estav Nord-ovest) dell&#8217;azienda ospedaliera universitaria di Pisa, impiego che aveva lasciato un mese fa per dedicarsi interamente alla sua passione per il volo e farne la sua professione definitiva. Dalle prime ipotesi sulla tragedia &#8211; sull&#8217;incidente e&#8217; stata aperta un&#8217;inchiesta dalla polizia e dall&#8217;aviazione civile locale &#8211; pare che abbia avuto difficolta&#8217; nell&#8217;apertura di entrambi i paracadute, principale e di emergenza, durante le riprese di un tandem (volo in coppia) nel sorvolo di un&#8217;area limitrofa all&#8217;aeroporto di Wanaka, dove poi e&#8217; avvenuta la caduta su un campo da golf vicino all&#8217;autostrada. Le borse dei due paracadute sono state trovate infatti chiuse a pochi metri di distanza dal corpo. Arilotta era stato anche paracadutista della Folgore con all&#8217;attivo due missioni in Bosnia e aveva girato il mondo inseguendo la sua passione per il volo: aveva partecipato a raduni in Australia, California, Isole Fiji, Florida e Nuova Zelanda. Da tre anni aveva scelto il lavoro part-time all&#8217;Aoup proprio per poter dedicare l&#8217;altra meta&#8217; dell&#8217;anno alla sua passione e farne il suo lavoro. Un mese fa la decisione definitiva di licenziarsi per intraprendere la carriera sportiva.<\/div>\n<div style=\"text-align: left;\">&nbsp;<\/div>\n<div style=\"text-align: left;\">Fonte: ANSA<\/div>\n","protected":false},"excerpt":{"rendered":"<p>WANAKA (NUOVA ZELANDA) &#8211; Un ex dipendente dell&#8217;Azienda ospedaliera universitaria pisana e&#8217; morto precipitando con il suo paracadute a Wanaka, in Nuova<\/p>\n","protected":false},"author":22,"featured_media":7926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17,5],"tags":[],"class_list":["post-7925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=7925"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7925\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/7926"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=7925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=7925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=7925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}