{"id":79281,"date":"2017-06-04T09:26:58","date_gmt":"2017-06-04T07:26:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/castrovillari-comitato-di-quartiere-esprime-perplessita-sullaccoglienza-migranti\/"},"modified":"2023-01-16T19:31:58","modified_gmt":"2023-01-16T18:31:58","slug":"157926-castrovillari-comitato-di-quartiere-esprime-perplessita-sullaccoglienza-migranti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/157926-castrovillari-comitato-di-quartiere-esprime-perplessita-sullaccoglienza-migranti\/","title":{"rendered":"Castrovillari, comitato di quartiere esprime perplessit\u00e0 sull&#8217;accoglienza migranti"},"content":{"rendered":"<h4>Il Comitato di Quartiere n. 7, i cittadini ed i residenti nell\u2019area di via E. Moneta, a Castrovillari, esprimono forti perplessit\u00e0 in merito ai risultati della Manifestazione d\u2019Interesse della Prefettura di Cosenza.<!--more--><\/h4>\n<p>CASTROVILLARI (CS) &#8211; La Prefettura starebbe selezionando per individuare operatori economici ed organizzazioni a cui affidare la prima accoglienza di cittadini stranieri richiedenti protezione internazionale e la gestione dei servizi connessi. &#8220;Al pubblico avviso ha partecipato &#8211; scrive in una nota il <strong>Comitato di Quartiere n. 7,<\/strong> i cittadini ed i residenti di via Moneta &#8211; come si evince dagli elenchi della Prefettura un&#8217;organizzazione di <strong>Montalto Uffugo<\/strong> che ha candidato la proposta di una struttura di ospitalit\u00e0 per migranti a Castrovillari&#8221;.<\/p>\n<p>&#8220;Gi\u00e0 dai giorni prima della scadenza dell\u2019Avviso, il 22 maggio, i cittadini del Quartiere avevano sollecitato un intervento e dei chiarimenti da parte dell\u2019Amministrazione Comunale e negli incontri che si sono tenuti alla presenza del Sindaco, dell\u2019Assessore Giuseppe Russo e di diversi Consiglieri Comunali, il Sindaco ha pi\u00f9 volte ribadito la contrariet\u00e0 ad azioni di privati o di organizzazioni che non siano in linea con quanto gi\u00e0 avviato in termini di accoglienza e integrazione dei migranti (progetto SPRAR), comunicando allo stesso Prefetto tali valutazioni&#8221;.<\/p>\n<p><strong>Gli abitanti del quartiere e dell\u2019area dove presumibilmente sar\u00e0 allocato il centro di accoglienza ribadiscono con forza ed a gran voce che:<\/strong><\/p>\n<p>1) i cittadini, pur avendo l\u2019Amministrazione Comunale attivato diversi strumenti di partecipazione e consultazione civica non sono stati ascoltati in via preventiva, se non su interessamento degli stessi negli ultimi 15 giorni;<br \/>\n2) il quartiere non \u00e8 idoneo per tale tipo di strutture di accoglienza ed in particolare l\u2019area nord (via E. Moneta e dintorni), un quartiere periferico dove sussistono diversi interventi pubblici non completati e dove gi\u00e0 in altre occasioni il Comitato di Quartiere ha sollecitato maggiore attenzione in termini di sicurezza e prevenzione del degrado;<br \/>\n3) non si condivide la modalit\u00e0 di gestione della manifestazione di interesse da parte della Prefettura, non si pu\u00f2 ridurre l\u2019accoglienza dei migranti ad una mera questione matematica di ripartizione numerica dei migranti nei diversi Comuni della Provincia, n\u00e9 si possono penalizzare territori che hanno avviato buone pratiche di \u201caccoglienza ed integrazione\u201d come per il caso di Castrovillari;<br \/>\n4) come ribadito dal Sindaco e dall\u2019Assessore ai Servizi Sociali, si chiede l\u2019applicazione della \u201cclausola di salvaguardia\u201d prevista dal Piano Nazionale per la ripartizione dei migranti, sostenuta e concordata con l\u2019ANCI, come specificato nella direttiva trasmessa dal Ministero degli Interni ai Prefetti (del 11 ottobre 2016). Ovvero: i comuni aderenti alla rete SPRAR, come lo \u00e8 Castrovillari, sono esenti dall\u2019attivazione di ulteriori forme di accoglienza.<\/p>\n<p>&#8220;In pi\u00f9 occasioni il Quartiere ed i cittadini hanno mostrato partecipazione attiva, attenzione e dialogo &#8211; prosegue la nota &#8211; ma sono seriamente preoccupati perch\u00e9 situazioni critiche, interessi economici, strumentalizzazioni politiche e gestioni distanti dalle reali esigenze dei territori e dei bisogni locali, possano portare a forzature che provocherebbero azioni decise anche da parte di chi vive e chi opera in questi luoghi.<br \/>\nAl momento \u00e8 stata avviata una raccolta di firme per sollecitare maggiore attenzione da parte dell\u2019Amministrazione Comunale e della Prefettura; sar\u00e0 convocata a breve una nuova assemblea\/manifestazione pubblica alla presenza della stampa e delle forze politiche locali, per sostenere la voce del Quartiere e dei suoi abitanti, nonch\u00e9 \u00e8 stato chiesto al Prefetto un incontro sulla problematica specifica dell\u2019accoglienza migranti nella nostra citt\u00e0&#8221;.<\/p>\n<p>Intanto il comitato e i residenti<strong> domani protocolleranno l\u2019istanza<\/strong> e le firme raccolte (circa 500 al momento) e promuoveranno una manifestazione pubblica, sempre per la stessa giornata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Comitato di Quartiere n. 7, i cittadini ed i residenti nell\u2019area di via E. Moneta, a Castrovillari, esprimono forti perplessit\u00e0 in merito ai risultati della Manifestazione d\u2019Interesse della Prefettura di Cosenza.<\/p>\n","protected":false},"author":21,"featured_media":79282,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-79281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/79281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=79281"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/79281\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/79282"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=79281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=79281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=79281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}