{"id":79508,"date":"2017-06-09T08:09:00","date_gmt":"2017-06-09T06:09:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/presunte-infiltrazioni-mafiose-commissione-daccesso-al-comune-lamezia\/"},"modified":"2023-01-16T19:32:14","modified_gmt":"2023-01-16T18:32:14","slug":"158783-presunte-infiltrazioni-mafiose-commissione-daccesso-al-comune-lamezia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/158783-presunte-infiltrazioni-mafiose-commissione-daccesso-al-comune-lamezia\/","title":{"rendered":"Presunte infiltrazioni mafiose, commissione d&#8217;accesso al Comune di Lamezia"},"content":{"rendered":"<h4>Il prefetto di Catanzaro, Luisa Latella, ha disposto l&#8217;accesso antimafia al Comune di Lamezia Terme<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>LAMEZIA TERME &#8211; I motivi sono legati alla &#8220;necessita&#8217; di svolgere approfonditi accertamenti al fine di verificare la sussistenza di collegamenti, diretti o indiretti, con la criminalita&#8217; organizzata degli amministratori&#8221;. Lo rende noto la stessa prefettura con un comunicato. Gli ispettori s&#8217;insedieranno in giornata. Il Comune di Lamezia Terme, quarta citta&#8217; della Calabria per rilevanza e numero di abitanti, e&#8217; gia&#8217; stato commissariato due volte per infiltrazioni della &#8216;ndrangheta.<\/p>\n<p>I precedenti commissariamenti risalgono al 1991 ed al 2002. La nomina della commissione d&#8217;accesso arriva dopo l&#8217;operazione &#8220;Crisalide&#8221; contro la cosca di &#8216;ndrangheta Cerra-Torcasio-Gualtieri che vede indagati il vicepresidente del Consiglio comunale Giuseppe Paladino, dimessosi proprio a causa della vicenda giudiziaria che lo riguarda, e il consigliere Pasqualino Ruberto, gia&#8217; sospeso dalla carica per il coinvolgimento nell&#8217;operazione &#8220;Robin Hood&#8221;. I risvolti dell&#8217;operazione &#8220;Crisalide avevano portato anche alle dimissioni di un&#8217;altra consigliera comunale, Marialucia Raso, il cui fidanzato e&#8217; fra gli arrestati dell&#8217;operazione &#8220;Crisalide&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il prefetto di Catanzaro, Luisa Latella, ha disposto l&#8217;accesso antimafia al Comune di Lamezia Terme<\/p>\n","protected":false},"author":22,"featured_media":79509,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-79508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/79508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=79508"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/79508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/79509"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=79508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=79508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=79508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}