{"id":79564,"date":"2017-06-10T08:39:20","date_gmt":"2017-06-10T06:39:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ndrangheta-arrestato-brasile-boss-latitante-vincenzo-macri\/"},"modified":"2023-01-16T19:32:18","modified_gmt":"2023-01-16T18:32:18","slug":"158940-ndrangheta-arrestato-brasile-boss-latitante-vincenzo-macri","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/158940-ndrangheta-arrestato-brasile-boss-latitante-vincenzo-macri\/","title":{"rendered":"&#8216;Ndrangheta: catturato in Brasile il latitante Vincenzo Macri&#8217;, figlio del &#8220;boss dei due mondi&#8221;"},"content":{"rendered":"<h4>Il boss latitante della &#8216;ndrangheta, Vincenzo Macr\u00ec, figlio del cosiddetto &#8216;Boss dei due mondi&#8217; Antonio, e&#8217; stato arrestato a San Paolo del Brasile.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA &#8211; L&#8217;arresto e&#8217; giunto al termine di un&#8217;indagine coordinata dalla Procura Distrettuale Antimafia di Reggio Calabria e condotta dal Servizio Centrale Operativo della Polizia di Stato e dalla Squadra Mobile di Reggio Calabria con l&#8217;attivita&#8217; di raccordo svolta del Servizio per la Cooperazione Internazionale di Polizia e dalla rete dell&#8217;Interpol.<strong> Vincenzo Macr\u00ec, 52 anni,<\/strong> esponente apicale della potente cosca della &#8216;ndrangheta <strong>Commisso<\/strong> operante a Siderno e gia&#8217; proposto per l&#8217;inserimento nell&#8217;elenco dei latitanti pericolosi stilato dal Ministero dell&#8217;Interno, \u00e8 stato localizzato e catturato da agenti della polizia brasiliana.<\/p>\n<p>L&#8217;uomo \u00e8 il figlio di Antonio Macri&#8217;, classe 1904, leader carismatico, soprannominato per la sua caratura criminale &#8220;Boss dei due mondi&#8221;, particolarmente influente anche oltreoceano (Canada e Stati Uniti), ucciso in un agguato a Siderno nel 1975, nell&#8217;ambito della prima guerra di &#8216;ndrangheta. Vincenzo Macri&#8217;, che negli ultimi anni si era stabilito ad Aalsmeer (in Olanda) dove gestiva gli interessi illeciti del sodalizio mafioso di riferimento, e&#8217; stato rintracciato all&#8217;aeroporto di San Paolo del Brasile diretto nella capitale del Venezuela Caracas, dove viveva da qualche tempo utilizzando una falsa identita&#8217; individuata proprio dagli investigatori della Squadra Mobile reggina e dello SCO.<\/p>\n<h4>L&#8217;arresto di Macr\u00ec e l&#8217;inchiesta Acero Krupy Connection<\/h4>\n<p>Un proficuo scambio di informazioni tra il Servizio Centrale Operativo, il Federal Bureau of Investigation e l&#8217;Homeland Security ha consentito di catturare il latitante. In particolare, la collaborazione tra SCO e FBI e&#8217; avvenuta nell&#8217;ambito del progetto &#8220;Pantheon&#8221;, siglato nel 2005, che ha dato nuovo impulso agli storici rapporti che legano i due uffici investigativi. Inoltre si e&#8217; rivelato decisivo ai fini della cattura anche lo scambio di informazioni, attivato tramite il Servizio Cooperazione Internazionale di Polizia, tra le Polizie del Venezuela e Brasile, in un&#8217;ampia cornice di collaborazione tra l&#8217;Italia ed i Paesi del Sud-America interessati.<\/p>\n<p>Secondo gli investigatori l&#8217;inserimento di Vincenzo Macri&#8217; nella cosca Commisso di Siderno e&#8217; ampiamente comprovata dalle risultanze dell&#8217;operazione Acero-Krupy Connection della Procura Distrettuale Antimafia di Reggio Calabria, condotta congiuntamente dalla Polizia di Stato e dall&#8217;Arma dei Carabinieri il 28 settembre del 2015 per associazione mafiosa e di traffico internazionale di sostanze stupefacenti con l&#8217;aggravante della transnazionalita&#8217;. Macri&#8217; e&#8217; stato, infatti, ritenuto, appartenere al vertice della famiglia di &#8216;ndrangheta Commisso di Siderno, attiva oltre che nelle zone limitrofe anche oltre i confini nazionali, in particolar modo a Toronto in Canada ed in Olanda. Sarebbero stati provati i rapporti con altri esponenti di vertice della stessa organizzazione tra cui Antonio Commisso, di 61 anni di Siderno, detto &#8220;u&#8217; Bucatu&#8221;, Giuseppe Coluccio, di 51, di Roccella Jonica, entrambi gia&#8217; detenuti,ed Angelo e Cosimo Figliomeni, di 55 anni e 53 anni originari di Siderno ma residenti in Ontario in Canada, entrambi detti &#8220;Brigante&#8221; e attualmente latitanti.<\/p>\n<p>Inoltre, stando sempre all&#8217;inchiesta Acero Krupy Connection, Vincenzo Macri&#8217; avrebbe collaborato nell&#8217;entroterra pontino e in Olanda con Vincenzo Crupi nella gestione di importanti stabilimenti floro-vivaistici. In questo contesto sono anche state registrate alcune conversazioni ambientali all&#8217;interno di una societa&#8217; olandese tra Macri&#8217; e Crupi che hanno fornito anche un importante spaccato dei rapporti tra diverse fazioni della &#8216;ndrangheta reggina, insediatesi in Canada. In particolare, Crupi, di ritorno da un viaggio a Toronto (Canada), riferisce a Macri&#8217; alcune importanti circostanze, apprese in Canada, riguardanti frizioni in atto tra membri di clan di &#8216;ndrangheta presenti nell&#8217;Ontario, specie a seguito della morte del boss Carmine Verduci, assassinato a Woodbrige, il 25 aprile 2014. In merito al traffico di stupefacenti, Macri&#8217;, insieme a Giuseppe Coluccio, Antonio Stefano, Salvatore Coluccio, Nicola Tassone, Antonio Coluccio, e Alfonso Condino, e&#8217; ritenuto tra i promotori e gli organizzatori del sodalizio decidendo presso quali canali di approvvigionamento procurarsi la droga e le localita&#8217; in cui consegnare lo stupefacente, nonche&#8217; le modalita&#8217; di ripartizione degli utili. Macri&#8217; il 28 settembre 2015 si era sottratto all&#8217;esecuzione del fermo di indiziato di delitto, trovandosi in Olanda. Inoltre e&#8217; da sottolineare che ha gia&#8217; scontato negli Stati Uniti d&#8217;America &#8211; dopo l&#8217;arresto avvenuto a Wilmington, (Delaware) dal Federal Boureau of Investigation per traffico internazionale di stupefacenti &#8211; una condanna dal 18 luglio 1989 fino al 27 settembre 2002. Al termine delle procedure di estradizione dal Brasile l&#8217;arrestato verra&#8217; condotto in Italia per essere sottoposto al regime di custodia cautelare in carcere.<\/p>\n<h4>Minniti si \u00e8 congratulato con il capo della Polizia Gabrielli<\/h4>\n<p>Il ministro dell&#8217;interno, Marco Minniti, ha telefonato al capo della Polizia, Franco Gabrielli, per complimentarsi dell&#8217;operazione, coordinata dalla Procura Antimafia di Reggio Calabria ed eseguita dal Servizio Centrale Operativo della Polizia di Stato, dalla Squadra Mobile di Reggio Calabria e dalla Polizia brasiliana con il raccordo del Servizio per la Cooperazione Internazionale di Polizia e dall&#8217;Interpol, che ha portato all&#8217;arresto, in Brasile, di Vincenzo Macri&#8217;, esponente di spicco della cosca della &#8216;ndrangheta Commisso, operante a Siderno, e inserito nell&#8217;elenco dei latitanti piu&#8217; pericolosi. &#8220;L&#8217;arresto di Vincenzo Macri&#8217;- ha commentato il ministro Minniti &#8211; e&#8217; un&#8217;altra importantissima operazione contro la &#8216;ndrangheta che si aggiunge agli arresti di altri pericolosi latitanti operati di recente dal lavoro straordinario delle Forze di Polizia&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il boss latitante della &#8216;ndrangheta, Vincenzo Macr\u00ec, figlio del cosiddetto &#8216;Boss dei due mondi&#8217; Antonio, e&#8217; stato arrestato a San Paolo del Brasile.<\/p>\n","protected":false},"author":22,"featured_media":79565,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-79564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/79564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=79564"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/79564\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/79565"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=79564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=79564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=79564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}