{"id":79624,"date":"2017-06-12T10:41:03","date_gmt":"2017-06-12T08:41:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-capo-della-polizia-gabrielli-allunical-per-parlare-di-ludopatia\/"},"modified":"2023-01-16T19:32:22","modified_gmt":"2023-01-16T18:32:22","slug":"159155-il-capo-della-polizia-gabrielli-allunical-per-parlare-di-ludopatia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/159155-il-capo-della-polizia-gabrielli-allunical-per-parlare-di-ludopatia\/","title":{"rendered":"Gabrielli all&#8217;Unical, Ludopatia: &#8220;90 miliardi solo nel 2016, lo spaccio di droga in Europa 26 miliardi&#8221; (AUDIO e FOTO)"},"content":{"rendered":"<h4>All&#8217;incontro organizzato dalla Questura di Cosenza nell\u2019aula magna \u201cB. Andreatta\u201d dell\u2019Unical, anche il Procuratore della Repubblica di Cosenza Mario Spagnuolo oltre al Capo della Polizia Franco Gabrielli<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; <strong>&#8220;Ludopatia: Prevenzione e Sicurezza Sociale&#8221;<\/strong> \u00e8\u00a0il tema affrontato stamattina all&#8217;Universit\u00e0 della Calabria alla presenza del Capo della Polizia, prefetto Franco Gabrielli al quale sono state affidate le conclusioni. I relatori sono stati Marco Luna della Direzione Centrale di Sanit\u00e0 del Dipartimento della Polizia di Stato, Giap Parini, docente dell\u2019Universit\u00e0 della Calabria, ed il Procuratore della Repubblica Mario Spagnuolo. <strong>Gabrielli<\/strong> in merito a questa forma di dipendenza dilagante e distruttiva, ha voluto sottolineare pi\u00f9 aspetti partendo innanzitutto dall&#8217;istituzione, &#8220;<em>nel 2002, di una struttura centrale e delle strutture a livello di Corte di appello,<\/em><strong> della Polizia dei giochi e delle scommesse<\/strong><em> a significare che non siamo solo in presenza di problematiche patologiche, psicologiche e di altra natura, ma la preoccupazione e&#8217; che questo sia l&#8217;ennesimo territorio in cui le organizzazioni criminali possano far valere il loro peso e raccogliere illecitamente profitti&#8221;.<\/em><br \/>\nIl Capo della Polizia ha poi citato due dati &#8220;<em>nel 2016 solo in Italia la <\/em><strong>filiera<\/strong><em> dei <\/em><strong>giochi<\/strong><em> ha fruttato un fatturato di oltre <\/em><strong>90 miliardi di euro;<\/strong><em> nello stesso periodo e quindi il 2016 una ricerca di Europol ha valutato che il fatturato legato allo spaccio di <\/em><strong>droga<\/strong><em> in tutta <\/em><strong>Europa<\/strong><em> \u00e8 di<\/em><strong> 26 miliardi<\/strong><em>. L&#8217;appeal di questo fenomeno \u00e8 questo e ha ricadute economiche, sociali e personali. I soggetti che sono portatori di questa patologia infatti vivono sconquassi pazzeschi nella loro vita, personale e familiare, ma io credo che sia anche e soprattutto un fenomeno da monitorare e da seguire perch\u00e8 diventa sempre pi\u00f9 l&#8217;eldorado delle organizzazioni criminali<\/em>&#8220;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-159162 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/06\/gabrielli-unical-02.jpg\" alt=\"gabrielli unical 02\" width=\"735\" height=\"413\" title=\"\"><\/p>\n<p>Gabrielli ha poi parlato della <strong>criminalit\u00e0<\/strong> organizzata in <strong>Calabria<\/strong>: <em>&#8220;La &#8216;ndrangheta oggi \u00e8 tra le organizzazioni a livello internazionale tra le pi\u00f9 potenti e capaci di inserirsi anche nei circuiti leciti avendo grande disponibilit\u00e0 di denaro e riuscendo molto spesso a stravolgere le regole del mercato. Chi accede a flussi finanziari leciti ha tutta una serie di giusti e corretti paletti; chi invece \u00e8 incontrollato e incontrollabile ha una potenzialit\u00e0 enorme che per\u00f2 rischia di minare la stessa architettura dell&#8217;economia ma anche degli assetti democratici del nostro e dell&#8217;intero continente<\/em>&#8220;.<\/p>\n<h4><span style=\"color: #ff0000;\">ASCOLTA LE DICHIARAZIONI DI GABRIELLI<\/span><\/h4>\n<p>[audio_mp3 url=&#8221;https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/06\/Gabrielli-su-ludopatia.mp3&#8243;]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-159160 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/06\/gabrielli-unical-01.jpg\" alt=\"gabrielli unical 01\" width=\"735\" height=\"424\" title=\"\"><\/p>\n<h3>La ludopatia non \u00e8 un&#8230; gioco!<\/h3>\n<p><strong>Il gioco d\u2019azzardo in Italia \u00e8 una vera e propria emergenza sociale<\/strong> che richiede interventi responsabili e immediati. La ludopatia \u00e8 infatti una malattia riconosciuta a livello mondiale ed i numeri del fenomeno sono impressionanti: l&#8217;Italia \u00e8 il Paese europeo dove si gioca di pi\u00f9, dove si arriva a bruciare in scommesse il 3% del PIL; ogni cittadino spende in media circa 1.300 euro l\u2019anno e il dato \u00e8 in costante crescita. Il gioco d\u2019azzardo on line (e non) porta con s\u00e9 un rischio che, in persone vulnerabili, pu\u00f2 sfociare in una vera e propria dipendenza comportamentale. La situazione \u00e8 assai pi\u00f9 grave al sud dove, paradossalmente, ci sono meno prospettive di lavoro e di conseguenza di avere un&#8217;entrata, ma i giocatori sono maggiori proprio perch\u00e8 spinti dalla &#8216;possibilit\u00e0&#8217; di vincere per &#8216;cambiare&#8217; vita. La crisi economica dunque, acuisce il problema: meno risorse si hanno e pi\u00f9 si vuole rischiare ed inoltre, giocano di pi\u00f9 le persone meno istruite e con minore reddito. Il marcatore dell\u2019ingresso nella patologia \u00e8 costituito dalla rincorsa delle perdite. Il passaggio a un livello grave \u00e8 il superamento del confine della legalit\u00e0. Poi si arriva a trascurare le normali occupazioni e si ha bisogno di giocare sempre di pi\u00f9 per ottenere lo stesso piacere.<\/p>\n<p>La <strong>ludopatia<\/strong> \u00e8 considerata un \u201cequivalente depressivo\u201d, cio\u00e8 un comportamento che sta al posto di una depressione negata (che solitamente compare quando il giocatore smette di giocare). Un giocatore dipendente ha un impulso per il gioco irrefrenabile e incontrollabile, al quale si accompagna una forte tensione emotiva e l\u2019incapacit\u00e0 di ricorrere a un pensiero riflessivo e logico. L\u2019autoinganno serve al controllo del senso di colpa e alimenta un circolo autodistruttivo: se il giocatore perde, giustifica il suo giocare col tentativo di rifarsi, se vince si giustifica affermando che deve approfittare del giorno fortunato. La diffusione della ludopatia \u00e8 amplificata dall\u2019accessibilit\u00e0 al gioco che fanno i mass media ed \u00e8 tanto pi\u00f9 diffusa quanto pi\u00f9 \u00e8 legalizzata. Oltre a decine e decine di siti web legali, cio\u00e8 regolarizzati dai Monopoli di Stato, proliferano sale gioco on-line, fuori dal controllo dello Stato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>All&#8217;incontro organizzato dalla Questura di Cosenza nell\u2019aula magna \u201cB. Andreatta\u201d dell\u2019Unical, anche il Procuratore della Repubblica di Cosenza Mario Spagnuolo oltre al Capo della Polizia Franco Gabrielli<\/p>\n","protected":false},"author":19,"featured_media":79625,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,571,44],"tags":[],"class_list":["post-79624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-in-evidenza","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/79624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=79624"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/79624\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/79625"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=79624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=79624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=79624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}